{"id":325287,"date":"2024-06-01T13:47:05","date_gmt":"2024-06-01T12:47:05","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=44823"},"modified":"2025-03-07T18:28:20","modified_gmt":"2025-03-07T17:28:20","slug":"concluye-el-ii-consejo-general-ampliado-de-la-fraternidad","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/","title":{"rendered":"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD."},"content":{"rendered":"<p>Despu\u00e9s de tres d\u00edas de gozoso encuentro bajo el lema \u201cLa Fraternidad, nuestro Lugar para los nuevos Trast\u00e9veres\u201d e inspirados por la cita del profeta Isa\u00edas, \u201cEnsancha el espacio de tu tienda, alarga tus cuerdas, refuerza tus estacas. Is. 54. 2\u201d, el II Consejo General Ampliado de la Fraternidad ha terminado hoy con la celebraci\u00f3n de la Eucarist\u00eda presidida por el P. General.<\/p>\n<p>En estos d\u00edas, hemos tenido oportunidad de evaluar el trabajo realizado en estos \u00faltimos tres a\u00f1os por parte del Consejo General y conocer con detalle la realidad de cada Fraternidad demarcacional.<\/p>\n<p>Algunas Fraternidades, como las de Eslovaquia y Hungr\u00eda, se hac\u00edan presentes por primera vez en estos encuentros, con lo que ello ha conllevado de alegr\u00eda por tener noticias de nuevas hermanas y hermanos. Con el mismo gozo hemos conocido los primeros pasos de las fraternidades escolapias de \u00c1frica del Oeste y Estados Unidos y Puerto Rico.<\/p>\n<p>Especialmente significativa fueron las palabras del P. General que, en nombre de la Congregaci\u00f3n General nos record\u00f3 la riqueza que supone la Fraternidad para la Orden y la responsabilidad de quienes nos toca el servicio de acompa\u00f1arla para que crezca en identidad escolapia y sinton\u00eda con la Orden.<\/p>\n<p>En el d\u00eda de ayer pudimos sentir tambi\u00e9n el aliento de tantas hermanas y hermanos que se conectaron online para recordarnos que es en este momento, a nuestra vuelta a nuestras comunidades de origen cuando comienza nuestra tarea de comunicar y transmitir lo que hemos vivido aqu\u00ed.<\/p>\n<p>Hoy por la ma\u00f1ana ha sido el momento de priorizar las propuestas que elaboramos los equipos en el d\u00eda de ayer, habiendo quedado claro el \u00e9nfasis que tenemos que hacer por avanzar en una formaci\u00f3n de religiosos y laicos que incluyan las claves de la participaci\u00f3n, por conectar la Fraternidad con el Movimiento Calasanz y por clarificar el lugar de la Fraternidad en la Orden y en cada Demarcaci\u00f3n, aprovechando el modelo de presencia escolapia en los diferentes niveles.<\/p>\n<p>En la sesi\u00f3n final, los testimonios de Elena de Betania y el P. Javier de Brasil-Bolivia, han abierto un momento donde cada quien hemos podido expresar lo que nos llev\u00e1bamos del encuentro.<\/p>\n<p>En resumen, este II Consejo General Ampliado ha sido una experiencia de comuni\u00f3n en la Casa de Calasanz, s\u00f3lo posible gracias a la acogida y el esfuerzo de quienes viven y trabajan en ella, y hacen que cada vez que venimos nos sintamos en nuestra propia casa.<\/p>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de tres d\u00edas de gozoso encuentro bajo el lema \u201cLa Fraternidad, nuestro Lugar para los nuevos Trast\u00e9veres\u201d e inspirados por la cita del profeta Isa\u00edas, \u201cEnsancha el espacio de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":325865,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-325287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD.<\/title>\n<meta name=\"description\" content=\"Despu\u00e9s de tres d\u00edas de gozoso encuentro bajo el lema \u201cLa Fraternidad, nuestro Lugar para los nuevos Trast\u00e9veres\u201d e inspirados por la cita del profeta Isa\u00edas, \u201cEnsancha el espacio de tu tienda, alarga tus cuerdas, refuerza tus estacas. Is. 54. 2\u201d, el II Consejo General Ampliado de la Fraternidad ha terminado hoy con la celebraci\u00f3n&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Despu\u00e9s%20de%20tres%20d\u00edas%20de%20gozoso%20encuentro%20bajo%20el%20lema%20\u201cLa%20Fraternidad,%20nuestro%20Lugar%20para%20los%20nuevos%20Trast\u00e9veres\u201d%20e%20inspirados%20por%20la%20cita%20del%20profeta%20Isa\u00edas,%20\u201cEnsancha%20el%20espacio%20de%20tu%20tienda,%20alarga%20tus%20cuerdas,%20refuerza%20tus%20estacas.%20Is.%2054.%202\u201d,%20el%20II%20Consejo%20General%20Ampliado%20de%20la%20Fraternidad%20ha%20terminado%20hoy%20con%20la%20celebraci\u00f3n&hellip;\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD.\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de tres d\u00edas de gozoso encuentro bajo el lema \u201cLa Fraternidad, nuestro Lugar para los nuevos Trast\u00e9veres\u201d e inspirados por la cita del profeta Isa\u00edas, \u201cEnsancha el espacio de tu tienda, alarga tus cuerdas, refuerza tus estacas. Is. 54. 2\u201d, el II Consejo General Ampliado de la Fraternidad ha terminado hoy con la celebraci\u00f3n&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-01T12:47:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1145\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/\"},\"author\":{\"name\":\"administrador\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/aaa10333558991c1d6ad358b7721fe71\"},\"headline\":\"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD.\",\"datePublished\":\"2024-06-01T12:47:05+00:00\",\"dateModified\":\"2025-03-07T17:28:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/\"},\"wordCount\":440,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/\",\"name\":\"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD. - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg\",\"datePublished\":\"2024-06-01T12:47:05+00:00\",\"dateModified\":\"2025-03-07T17:28:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg\",\"width\":2000,\"height\":1145},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2024\\\/06\\\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/aaa10333558991c1d6ad358b7721fe71\",\"name\":\"administrador\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/administrador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD.","description":"Despu\u00e9s de tres d\u00edas de gozoso encuentro bajo el lema \u201cLa Fraternidad, nuestro Lugar para los nuevos Trast\u00e9veres\u201d e inspirados por la cita del profeta Isa\u00edas, \u201cEnsancha el espacio de tu tienda, alarga tus cuerdas, refuerza tus estacas. Is. 54. 2\u201d, el II Consejo General Ampliado de la Fraternidad ha terminado hoy con la celebraci\u00f3n&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Despu\u00e9s de tres d\u00edas de gozoso encuentro bajo el lema \u201cLa Fraternidad, nuestro Lugar para los nuevos Trast\u00e9veres\u201d e inspirados por la cita del profeta Isa\u00edas, \u201cEnsancha el espacio de tu tienda, alarga tus cuerdas, refuerza tus estacas. Is. 54. 2\u201d, el II Consejo General Ampliado de la Fraternidad ha terminado hoy con la celebraci\u00f3n&hellip;","og_locale":"en_US","og_type":"article","og_title":"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD.","og_description":"Despu\u00e9s de tres d\u00edas de gozoso encuentro bajo el lema \u201cLa Fraternidad, nuestro Lugar para los nuevos Trast\u00e9veres\u201d e inspirados por la cita del profeta Isa\u00edas, \u201cEnsancha el espacio de tu tienda, alarga tus cuerdas, refuerza tus estacas. Is. 54. 2\u201d, el II Consejo General Ampliado de la Fraternidad ha terminado hoy con la celebraci\u00f3n&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/","og_site_name":"Itaka-Escolapios","article_published_time":"2024-06-01T12:47:05+00:00","article_modified_time":"2025-03-07T17:28:20+00:00","og_image":[{"width":2000,"height":1145,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg","type":"image\/jpeg"}],"author":"administrador","twitter_card":"summary_large_image","twitter_misc":{"Written by":"administrador","Est. reading time":"2 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/"},"author":{"name":"administrador","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/aaa10333558991c1d6ad358b7721fe71"},"headline":"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD.","datePublished":"2024-06-01T12:47:05+00:00","dateModified":"2025-03-07T17:28:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/"},"wordCount":440,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/","name":"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD. - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg","datePublished":"2024-06-01T12:47:05+00:00","dateModified":"2025-03-07T17:28:20+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/Foto-grupo-II-CONSEJO-FRATERNIDAD-ROMA-2024-scaled-1.jpg","width":2000,"height":1145},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2024\/06\/concluye-el-ii-consejo-general-ampliado-de-la-fraternidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"CONCLUYE EL II CONSEJO GENERAL AMPLIADO DE LA FRATERNIDAD."}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/aaa10333558991c1d6ad358b7721fe71","name":"administrador","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/administrador\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/325287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=325287"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/325287\/revisions"}],"predecessor-version":[{"id":326248,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/325287\/revisions\/326248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/325865"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=325287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=325287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=325287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}