{"id":37023,"date":"2022-06-14T16:49:58","date_gmt":"2022-06-14T15:49:58","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=37023"},"modified":"2023-11-28T12:35:44","modified_gmt":"2023-11-28T11:35:44","slug":"le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/","title":{"rendered":"LE PERSONNEL DE L'AMBASSADE D'ESPAGNE A L'ECOLE MATERNELLE\/PRIMAIRE ST SACREMENT"},"content":{"rendered":"<p>Le vendredi 10 juin 2022, l&#8217;\u00c9cole Maternelle et Primaire saint Sacrement de Kinshasa a re\u00e7u la visite de Mme Magdalena, personnel de l&#8217;ambassade d&#8217;Espagne en RDC. Ce fut un moment ponctu\u00e9 par une projection de film, des po\u00e8mes, des chants et une visite des locaux abritant ladite \u00e9cole. Notre h\u00f4te a \u00e9t\u00e9, tout comme les enfants et les enseignants, tr\u00e8s \u00e9mue par la visite; et a fait promesse de revenir nous voir avec l&#8217;Ambassadeur lui-m\u00eame. Esp\u00e9rons donc que les fruits tiendront la promesse des fleurs!<a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.10.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-37024\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.10.jpeg\" alt=\"\" width=\"1600\" height=\"960\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.10.jpeg 1600w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.10-300x180.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.10-1024x614.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.10-768x461.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.10-1536x922.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.10-250x150.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.10-1080x648.jpeg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-37025\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09.jpeg 1600w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09-1536x1152.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.09-1080x810.jpeg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-37026\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08.jpeg 1600w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08-1536x1152.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.08-1080x810.jpeg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-37027\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06.jpeg 1600w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06-1536x1152.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.06-1080x810.jpeg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-37028\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04.jpeg 1600w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04-1536x1152.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.04-1080x810.jpeg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-37029\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02.jpeg 1600w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02-1536x1152.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.02-1080x810.jpeg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-37030\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00.jpeg 1600w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00-1536x1152.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.39.00-1080x810.jpeg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-37031\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59.jpeg 1600w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59-1536x1152.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.59-1080x810.jpeg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a> <a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-37032\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg 1600w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57-1536x1152.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57-510x382.jpeg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57-1080x810.jpeg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vendredi 10 juin 2022, l&#8217;\u00c9cole Maternelle et Primaire saint Sacrement de Kinshasa a re\u00e7u la visite de Mme Magdalena, personnel de l&#8217;ambassade d&#8217;Espagne en RDC. Ce fut un moment [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":37032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[551,562],"class_list":["post-37023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo","tag-campagne-de-solidarite","tag-education"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LE PERSONNEL DE L&#039;AMBASSADE D&#039;ESPAGNE A L&#039;ECOLE MATERNELLE\/PRIMAIRE ST SACREMENT<\/title>\n<meta name=\"description\" content=\"Le vendredi 10 juin 2022, l&#039;\u00c9cole Maternelle et Primaire saint Sacrement de Kinshasa a re\u00e7u la visite de Mme Magdalena, personnel de l&#039;ambassade d&#039;Espagne en RDC. Ce fut un moment ponctu\u00e9 par une projection de film, des po\u00e8mes, des chants et une visite des locaux abritant ladite \u00e9cole. Notre h\u00f4te a \u00e9t\u00e9, tout comme les&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Le%20vendredi%2010%20juin%202022,%20l'\u00c9cole%20Maternelle%20et%20Primaire%20saint%20Sacrement%20de%20Kinshasa%20a%20re\u00e7u%20la%20visite%20de%20Mme%20Magdalena,%20personnel%20de%20l'ambassade%20d'Espagne%20en%20RDC.%20Ce%20fut%20un%20moment%20ponctu\u00e9%20par%20une%20projection%20de%20film,%20des%20po\u00e8mes,%20des%20chants%20et%20une%20visite%20des%20locaux%20abritant%20ladite%20\u00e9cole.%20Notre%20h\u00f4te%20a%20\u00e9t\u00e9,%20tout%20comme%20les&hellip;\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LE PERSONNEL DE L&#039;AMBASSADE D&#039;ESPAGNE A L&#039;ECOLE MATERNELLE\/PRIMAIRE ST SACREMENT\" \/>\n<meta property=\"og:description\" content=\"Le vendredi 10 juin 2022, l&#039;\u00c9cole Maternelle et Primaire saint Sacrement de Kinshasa a re\u00e7u la visite de Mme Magdalena, personnel de l&#039;ambassade d&#039;Espagne en RDC. Ce fut un moment ponctu\u00e9 par une projection de film, des po\u00e8mes, des chants et une visite des locaux abritant ladite \u00e9cole. Notre h\u00f4te a \u00e9t\u00e9, tout comme les&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-14T15:49:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"LE PERSONNEL DE L'AMBASSADE D'ESPAGNE A L'ECOLE MATERNELLE\\\/PRIMAIRE ST SACREMENT\",\"datePublished\":\"2022-06-14T15:49:58+00:00\",\"dateModified\":\"2023-11-28T11:35:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/\"},\"wordCount\":107,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg\",\"keywords\":[\"campagne de solidarit\u00e9\",\"\u00e9ducation\"],\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/\",\"name\":\"LE PERSONNEL DE L'AMBASSADE D'ESPAGNE A L'ECOLE MATERNELLE\\\/PRIMAIRE ST SACREMENT - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg\",\"datePublished\":\"2022-06-14T15:49:58+00:00\",\"dateModified\":\"2023-11-28T11:35:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2022\\\/06\\\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LE PERSONNEL DE L'AMBASSADE D'ESPAGNE A L'ECOLE MATERNELLE\\\/PRIMAIRE ST SACREMENT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LE PERSONNEL DE L'AMBASSADE D'ESPAGNE A L'ECOLE MATERNELLE\/PRIMAIRE ST SACREMENT","description":"Le vendredi 10 juin 2022, l'\u00c9cole Maternelle et Primaire saint Sacrement de Kinshasa a re\u00e7u la visite de Mme Magdalena, personnel de l'ambassade d'Espagne en RDC. Ce fut un moment ponctu\u00e9 par une projection de film, des po\u00e8mes, des chants et une visite des locaux abritant ladite \u00e9cole. Notre h\u00f4te a \u00e9t\u00e9, tout comme les&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Le vendredi 10 juin 2022, l'\u00c9cole Maternelle et Primaire saint Sacrement de Kinshasa a re\u00e7u la visite de Mme Magdalena, personnel de l'ambassade d'Espagne en RDC. Ce fut un moment ponctu\u00e9 par une projection de film, des po\u00e8mes, des chants et une visite des locaux abritant ladite \u00e9cole. Notre h\u00f4te a \u00e9t\u00e9, tout comme les&hellip;","og_locale":"en_US","og_type":"article","og_title":"LE PERSONNEL DE L'AMBASSADE D'ESPAGNE A L'ECOLE MATERNELLE\/PRIMAIRE ST SACREMENT","og_description":"Le vendredi 10 juin 2022, l'\u00c9cole Maternelle et Primaire saint Sacrement de Kinshasa a re\u00e7u la visite de Mme Magdalena, personnel de l'ambassade d'Espagne en RDC. Ce fut un moment ponctu\u00e9 par une projection de film, des po\u00e8mes, des chants et une visite des locaux abritant ladite \u00e9cole. Notre h\u00f4te a \u00e9t\u00e9, tout comme les&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/","og_site_name":"Itaka-Escolapios","article_published_time":"2022-06-14T15:49:58+00:00","article_modified_time":"2023-11-28T11:35:44+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg","type":"image\/jpeg"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Written by":"itakaescolapios"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"LE PERSONNEL DE L'AMBASSADE D'ESPAGNE A L'ECOLE MATERNELLE\/PRIMAIRE ST SACREMENT","datePublished":"2022-06-14T15:49:58+00:00","dateModified":"2023-11-28T11:35:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/"},"wordCount":107,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg","keywords":["campagne de solidarit\u00e9","\u00e9ducation"],"articleSection":["R.D. Congo"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/","name":"LE PERSONNEL DE L'AMBASSADE D'ESPAGNE A L'ECOLE MATERNELLE\/PRIMAIRE ST SACREMENT - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg","datePublished":"2022-06-14T15:49:58+00:00","dateModified":"2023-11-28T11:35:44+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-14-at-16.38.57.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2022\/06\/le-personnel-de-lambassade-despagne-a-lecole-maternelle-primaire-st-sacrement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"LE PERSONNEL DE L'AMBASSADE D'ESPAGNE A L'ECOLE MATERNELLE\/PRIMAIRE ST SACREMENT"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/37023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=37023"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/37023\/revisions"}],"predecessor-version":[{"id":43892,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/37023\/revisions\/43892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/37032"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=37023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=37023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=37023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}