{"id":42917,"date":"2023-09-21T16:31:14","date_gmt":"2023-09-21T15:31:14","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=42917"},"modified":"2023-11-28T12:35:30","modified_gmt":"2023-11-28T11:35:30","slug":"english-first-meeting-of-the-itaka-central-office","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/","title":{"rendered":"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL"},"content":{"rendered":"<p>Hoy, jueves 21 de septiembre de 2023, ha tenido lugar en Yaund\u00e9 la primera reuni\u00f3n de la oficina central de ITAKA ESCOLAPIOS \u00c1frica Central (Oficina Central de Itaka Escolapios \u00c1frica Central). Durante esta reuni\u00f3n, se trataba de poner los puntos sobre el lugar de cada departamento de la oficina central y sobre todo sobre la importancia de la comunicaci\u00f3n y de la colaboraci\u00f3n entre los colaboradores. Con el nuevo provincial en la persona del Padre Moses y el nuevo coordinador de Itaka \u00c1frica Central en la persona del Padre Peter AFOUKEZE han sentado las nuevas bases para el equipo de la oficina central de Itaka.<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, jueves 21 de septiembre de 2023, ha tenido lugar en Yaund\u00e9 la primera reuni\u00f3n de la oficina central de ITAKA ESCOLAPIOS \u00c1frica Central (Oficina Central de Itaka Escolapios \u00c1frica [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":42919,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,10],"tags":[],"class_list":["post-42917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-camerun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL<\/title>\n<meta name=\"description\" content=\"Hoy, jueves 21 de septiembre de 2023, ha tenido lugar en Yaund\u00e9 la primera reuni\u00f3n de la oficina central de ITAKA ESCOLAPIOS \u00c1frica Central (Oficina Central de Itaka Escolapios \u00c1frica Central). Durante esta reuni\u00f3n, se trataba de poner los puntos sobre el lugar de cada departamento de la oficina central y sobre todo sobre la&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Hoy,%20jueves%2021%20de%20septiembre%20de%202023,%20ha%20tenido%20lugar%20en%20Yaund\u00e9%20la%20primera%20reuni\u00f3n%20de%20la%20oficina%20central%20de%20ITAKA%20ESCOLAPIOS%20\u00c1frica%20Central%20(Oficina%20Central%20de%20Itaka%20Escolapios%20\u00c1frica%20Central).%20Durante%20esta%20reuni\u00f3n,%20se%20trataba%20de%20poner%20los%20puntos%20sobre%20el%20lugar%20de%20cada%20departamento%20de%20la%20oficina%20central%20y%20sobre%20todo%20sobre%20la&hellip;\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL\" \/>\n<meta property=\"og:description\" content=\"Hoy, jueves 21 de septiembre de 2023, ha tenido lugar en Yaund\u00e9 la primera reuni\u00f3n de la oficina central de ITAKA ESCOLAPIOS \u00c1frica Central (Oficina Central de Itaka Escolapios \u00c1frica Central). Durante esta reuni\u00f3n, se trataba de poner los puntos sobre el lugar de cada departamento de la oficina central y sobre todo sobre la&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-21T15:31:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/unnamed-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL\",\"datePublished\":\"2023-09-21T15:31:14+00:00\",\"dateModified\":\"2023-11-28T11:35:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/\"},\"wordCount\":119,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/unnamed-1-scaled.jpg\",\"articleSection\":[\"Erdialdeko Afrika\",\"Kamerun\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/\",\"name\":\"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/unnamed-1-scaled.jpg\",\"datePublished\":\"2023-09-21T15:31:14+00:00\",\"dateModified\":\"2023-11-28T11:35:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/unnamed-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/unnamed-1-scaled.jpg\",\"width\":1500,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/2023\\\/09\\\/english-first-meeting-of-the-itaka-central-office\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/eu\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL","description":"Hoy, jueves 21 de septiembre de 2023, ha tenido lugar en Yaund\u00e9 la primera reuni\u00f3n de la oficina central de ITAKA ESCOLAPIOS \u00c1frica Central (Oficina Central de Itaka Escolapios \u00c1frica Central). Durante esta reuni\u00f3n, se trataba de poner los puntos sobre el lugar de cada departamento de la oficina central y sobre todo sobre la&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Hoy, jueves 21 de septiembre de 2023, ha tenido lugar en Yaund\u00e9 la primera reuni\u00f3n de la oficina central de ITAKA ESCOLAPIOS \u00c1frica Central (Oficina Central de Itaka Escolapios \u00c1frica Central). Durante esta reuni\u00f3n, se trataba de poner los puntos sobre el lugar de cada departamento de la oficina central y sobre todo sobre la&hellip;","og_locale":"en_US","og_type":"article","og_title":"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL","og_description":"Hoy, jueves 21 de septiembre de 2023, ha tenido lugar en Yaund\u00e9 la primera reuni\u00f3n de la oficina central de ITAKA ESCOLAPIOS \u00c1frica Central (Oficina Central de Itaka Escolapios \u00c1frica Central). Durante esta reuni\u00f3n, se trataba de poner los puntos sobre el lugar de cada departamento de la oficina central y sobre todo sobre la&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/","og_site_name":"Itaka-Escolapios","article_published_time":"2023-09-21T15:31:14+00:00","article_modified_time":"2023-11-28T11:35:30+00:00","og_image":[{"width":1500,"height":1125,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/unnamed-1-scaled.jpg","type":"image\/jpeg"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"Written by":"cameroun01","Est. reading time":"1 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL","datePublished":"2023-09-21T15:31:14+00:00","dateModified":"2023-11-28T11:35:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/"},"wordCount":119,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/unnamed-1-scaled.jpg","articleSection":["Erdialdeko Afrika","Kamerun"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/","url":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/","name":"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/unnamed-1-scaled.jpg","datePublished":"2023-09-21T15:31:14+00:00","dateModified":"2023-11-28T11:35:30+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/unnamed-1-scaled.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/09\/unnamed-1-scaled.jpg","width":1500,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/eu\/2023\/09\/english-first-meeting-of-the-itaka-central-office\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"PRIMERA REUNI\u00d3N DE LA OFICINA PRINCIPAL DE ITAKA ESCOLAPIOS AFRICA CENTRAL"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/eu\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/42917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/comments?post=42917"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/42917\/revisions"}],"predecessor-version":[{"id":43523,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/posts\/42917\/revisions\/43523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media\/42919"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/media?parent=42917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/categories?post=42917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/eu\/wp-json\/wp\/v2\/tags?post=42917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}