{"id":24885,"date":"2018-10-17T14:26:05","date_gmt":"2018-10-17T13:26:05","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?page_id=24885"},"modified":"2023-11-28T12:37:11","modified_gmt":"2023-11-28T11:37:11","slug":"amawole","status":"publish","type":"page","link":"https:\/\/www.itakaescolapios.org\/fr\/amawole\/","title":{"rendered":"AMAWOL\u00c9"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"Amawol\u00e9 - Comptine congolaise pour maternelles\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/Uw3pprp_btw?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>La musique est l\u2019un des \u00e9l\u00e9ments centraux de la vie en R\u00e9publique D\u00e9mocratique du Congo. Pendant des d\u00e9cennies, la R\u00e9publique D\u00e9mocratique du Congo a r\u00e9pandu sa musique sur le reste du continent africain, et m\u00eame au-del\u00e0 du continent. Dans les ann\u00e9es 50 et 60, c\u2019\u00e9tait le soukous, et actuellement c&rsquo;est un rythme r\u00e9adapt\u00e9, le ndombolo.<\/p>\n<p>Beaucoup de stars congolaises marquent le rythme \u00e0 niveau international. BLA nous propose par le biais de cette activit\u00e9 de nous convertir en stars de la musique et d&rsquo;internationaliser une chanson typique de la R\u00e9publique D\u00e9mocratique du Congo, AMAWOL\u00c9.<\/p>\n<p>Il s&rsquo;agit d&rsquo;une chanson que les jeunes filles et gar\u00e7ons chantent en classes de primaire, dans leurs groupes de scout ou pendant qu\u2019ils s\u2019entrainent \u00e0 diff\u00e9rents sports.<\/p>\n<p>T\u00e9l\u00e9chargez la FICHE D\u2019ACTIVIT\u00c9:\u00a0<strong><span style=\"color: #808000;\"><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/FICHA-AMAWOL\u00c9.pdf\" target=\"_blank\"><span style=\"color: #808000;\">AMAWOL\u00c9<\/span><\/a><\/span><\/strong><\/p>\n<p>Descarga la\u00a0<strong><span style=\"color: #808000;\"><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/Amawol\u00e9-letra1.pdf\" target=\"_blank\"><span style=\"color: #808000;\">LETRA<\/span><\/a><\/span><\/strong><\/p>\n<p>T\u00e9l\u00e9charger la <strong><span style=\"color: #808000;\"><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/Amawole-partitura1.pdf\" target=\"_blank\"><span style=\"color: #808000;\">PAROLE DE LA CHANSON<\/span><\/a><\/span><\/strong><\/p>\n<p>MP3:<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-24885-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/3_Amawole-gui\u0301a-para-grabar-116BPM.mp3?_=1\" \/><a href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/3_Amawole-gui\u0301a-para-grabar-116BPM.mp3\">https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/10\/3_Amawole-gui\u0301a-para-grabar-116BPM.mp3<\/a><\/audio>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/s7c-7240QBA\" height=\"134\" width=\"238\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe> <iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/sByHQp4O2-A\" height=\"134\" width=\"238\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La musique est l\u2019un des \u00e9l\u00e9ments centraux de la vie en R\u00e9publique D\u00e9mocratique du Congo. Pendant des d\u00e9cennies, la R\u00e9publique D\u00e9mocratique du Congo a r\u00e9pandu sa musique sur le reste [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-24885","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMAWOL\u00c9<\/title>\n<meta name=\"description\" content=\"https:\/\/youtu.be\/Uw3pprp_btw La musique est l\u2019un des \u00e9l\u00e9ments centraux de la vie en R\u00e9publique D\u00e9mocratique du Congo. Pendant des d\u00e9cennies, la R\u00e9publique D\u00e9mocratique du Congo a r\u00e9pandu sa musique sur le reste du continent africain, et m\u00eame au-del\u00e0 du continent. Dans les ann\u00e9es 50 et 60, c\u2019\u00e9tait le soukous, et actuellement c&#039;est un rythme r\u00e9adapt\u00e9, le\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/amawole\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMAWOL\u00c9\" \/>\n<meta property=\"og:description\" content=\"https:\/\/youtu.be\/Uw3pprp_btw La musique est l\u2019un des \u00e9l\u00e9ments centraux de la vie en R\u00e9publique D\u00e9mocratique du Congo. Pendant des d\u00e9cennies, la R\u00e9publique D\u00e9mocratique du Congo a r\u00e9pandu sa musique sur le reste du continent africain, et m\u00eame au-del\u00e0 du continent. Dans les ann\u00e9es 50 et 60, c\u2019\u00e9tait le soukous, et actuellement c&#039;est un rythme r\u00e9adapt\u00e9, le\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/amawole\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:37:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/amawole\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/amawole\\\/\",\"name\":\"AMAWOL\u00c9 - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"datePublished\":\"2018-10-17T13:26:05+00:00\",\"dateModified\":\"2023-11-28T11:37:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/amawole\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/amawole\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/amawole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMAWOL\u00c9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMAWOL\u00c9","description":"https:\/\/youtu.be\/Uw3pprp_btw La musique est l\u2019un des \u00e9l\u00e9ments centraux de la vie en R\u00e9publique D\u00e9mocratique du Congo. Pendant des d\u00e9cennies, la R\u00e9publique D\u00e9mocratique du Congo a r\u00e9pandu sa musique sur le reste du continent africain, et m\u00eame au-del\u00e0 du continent. Dans les ann\u00e9es 50 et 60, c\u2019\u00e9tait le soukous, et actuellement c'est un rythme r\u00e9adapt\u00e9, le\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/amawole\/","og_locale":"fr_FR","og_type":"article","og_title":"AMAWOL\u00c9","og_description":"https:\/\/youtu.be\/Uw3pprp_btw La musique est l\u2019un des \u00e9l\u00e9ments centraux de la vie en R\u00e9publique D\u00e9mocratique du Congo. Pendant des d\u00e9cennies, la R\u00e9publique D\u00e9mocratique du Congo a r\u00e9pandu sa musique sur le reste du continent africain, et m\u00eame au-del\u00e0 du continent. Dans les ann\u00e9es 50 et 60, c\u2019\u00e9tait le soukous, et actuellement c'est un rythme r\u00e9adapt\u00e9, le\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/amawole\/","og_site_name":"Itaka-Escolapios","article_modified_time":"2023-11-28T11:37:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/amawole\/","url":"https:\/\/www.itakaescolapios.org\/fr\/amawole\/","name":"AMAWOL\u00c9 - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"datePublished":"2018-10-17T13:26:05+00:00","dateModified":"2023-11-28T11:37:11+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/amawole\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/amawole\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/amawole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"AMAWOL\u00c9"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/pages\/24885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=24885"}],"version-history":[{"count":46,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/pages\/24885\/revisions"}],"predecessor-version":[{"id":46236,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/pages\/24885\/revisions\/46236"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=24885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}