{"id":18971,"date":"2017-04-26T11:49:28","date_gmt":"2017-04-26T10:49:28","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=18971"},"modified":"2023-11-28T12:38:05","modified_gmt":"2023-11-28T11:38:05","slug":"los-valores-de-itaka-escolapios","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/","title":{"rendered":"LOS VALORES DE ITAKA - ESCOLAPIOS"},"content":{"rendered":"<p>Los principios y valores en una entidad son los rasgos fundamentales que definen la forma de actuar y ser.<\/p>\n<p>Aqu\u00ed recordamos los principios y valores de la Red Itaka &#8211; Escolapios:<\/p>\n<ol>\n<li>Identidad cristiana y escolapia. Partiendo del Evangelio como inspiraci\u00f3n fundamental, Itaka-Escolapios participa en la Iglesia desde el carisma de Calasanz y la misi\u00f3n espec\u00edfica de las Escuelas P\u00edas, a las que pertenece.<\/li>\n<li>Opci\u00f3n por los pobres. Itaka-Escolapios responde a la realidad de las personas empobrecidas y trabaja para eliminar las causas que generan pobreza y exclusi\u00f3n, con especial atenci\u00f3n a las necesidades de ni\u00f1os, ni\u00f1as y j\u00f3venes.<\/li>\n<li>Misi\u00f3n integral. Itaka-Escolapios act\u00faa en las tres dimensiones de la misi\u00f3n escolapia (educativa, evangelizadora y de transformaci\u00f3n social), desde el convencimiento de que estas se enriquecen y retroalimentan.<\/li>\n<li>Compromiso voluntario. Itaka-Escolapios fundamenta su acci\u00f3n en el voluntariado, abre espacios al mismo y lo prioriza y promueve en todos sus proyectos, por su valor educativo y como expresi\u00f3n de compromiso generoso a favor de otras personas.<\/li>\n<li>Gesti\u00f3n responsable. Itaka-Escolapios apuesta por el trabajo en equipo, la generaci\u00f3n de confianza y la austeridad en su funcionamiento, as\u00ed como la sostenibilidad (de personas, identidad y recursos econ\u00f3micos) a largo plazo de sus proyectos.<\/li>\n<li>Trabajo en red. Itaka-Escolapios se entiende a s\u00ed misma como una red escolapia que funciona con criterios de solidaridad, interdependencia y corresponsabilidad.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Los principios y valores en una entidad son los rasgos fundamentales que definen la forma de actuar y ser. Aqu\u00ed recordamos los principios y valores de la Red Itaka &#8211; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-18971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LOS VALORES DE ITAKA - ESCOLAPIOS<\/title>\n<meta name=\"description\" content=\"Los principios y valores en una entidad son los rasgos fundamentales que definen la forma de actuar y ser. Aqu\u00ed recordamos los principios y valores de la Red Itaka - Escolapios: Identidad cristiana y escolapia. Partiendo del Evangelio como inspiraci\u00f3n fundamental, Itaka-Escolapios participa en la Iglesia desde el carisma de Calasanz y la misi\u00f3n espec\u00edfica\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOS VALORES DE ITAKA - ESCOLAPIOS\" \/>\n<meta property=\"og:description\" content=\"Los principios y valores en una entidad son los rasgos fundamentales que definen la forma de actuar y ser. Aqu\u00ed recordamos los principios y valores de la Red Itaka - Escolapios: Identidad cristiana y escolapia. Partiendo del Evangelio como inspiraci\u00f3n fundamental, Itaka-Escolapios participa en la Iglesia desde el carisma de Calasanz y la misi\u00f3n espec\u00edfica\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-26T10:49:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:38:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-principios-y-valores.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"329\" \/>\n\t<meta property=\"og:image:height\" content=\"212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"LOS VALORES DE ITAKA - ESCOLAPIOS\",\"datePublished\":\"2017-04-26T10:49:28+00:00\",\"dateModified\":\"2023-11-28T11:38:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/\"},\"wordCount\":245,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1-principios-y-valores.gif\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/\",\"name\":\"LOS VALORES DE ITAKA - ESCOLAPIOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1-principios-y-valores.gif\",\"datePublished\":\"2017-04-26T10:49:28+00:00\",\"dateModified\":\"2023-11-28T11:38:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1-principios-y-valores.gif\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1-principios-y-valores.gif\",\"width\":329,\"height\":212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2017\\\/04\\\/los-valores-de-itaka-escolapios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LOS VALORES DE ITAKA - ESCOLAPIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LOS VALORES DE ITAKA - ESCOLAPIOS","description":"Los principios y valores en una entidad son los rasgos fundamentales que definen la forma de actuar y ser. Aqu\u00ed recordamos los principios y valores de la Red Itaka - Escolapios: Identidad cristiana y escolapia. Partiendo del Evangelio como inspiraci\u00f3n fundamental, Itaka-Escolapios participa en la Iglesia desde el carisma de Calasanz y la misi\u00f3n espec\u00edfica\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Los principios y valores en una entidad son los rasgos fundamentales que definen la forma de actuar y ser. Aqu\u00ed recordamos los principios y valores de la Red Itaka - Escolapios: Identidad cristiana y escolapia. Partiendo del Evangelio como inspiraci\u00f3n fundamental, Itaka-Escolapios participa en la Iglesia desde el carisma de Calasanz y la misi\u00f3n espec\u00edfica\u2026","og_locale":"fr_FR","og_type":"article","og_title":"LOS VALORES DE ITAKA - ESCOLAPIOS","og_description":"Los principios y valores en una entidad son los rasgos fundamentales que definen la forma de actuar y ser. Aqu\u00ed recordamos los principios y valores de la Red Itaka - Escolapios: Identidad cristiana y escolapia. Partiendo del Evangelio como inspiraci\u00f3n fundamental, Itaka-Escolapios participa en la Iglesia desde el carisma de Calasanz y la misi\u00f3n espec\u00edfica\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/","og_site_name":"Itaka-Escolapios","article_published_time":"2017-04-26T10:49:28+00:00","article_modified_time":"2023-11-28T11:38:05+00:00","og_image":[{"width":329,"height":212,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-principios-y-valores.gif","type":"image\/gif"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"LOS VALORES DE ITAKA - ESCOLAPIOS","datePublished":"2017-04-26T10:49:28+00:00","dateModified":"2023-11-28T11:38:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/"},"wordCount":245,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-principios-y-valores.gif","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/","name":"LOS VALORES DE ITAKA - ESCOLAPIOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-principios-y-valores.gif","datePublished":"2017-04-26T10:49:28+00:00","dateModified":"2023-11-28T11:38:05+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-principios-y-valores.gif","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2017\/04\/1-principios-y-valores.gif","width":329,"height":212},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2017\/04\/los-valores-de-itaka-escolapios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"LOS VALORES DE ITAKA - ESCOLAPIOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/18971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=18971"}],"version-history":[{"count":6,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/18971\/revisions"}],"predecessor-version":[{"id":47744,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/18971\/revisions\/47744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/18972"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=18971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=18971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=18971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}