{"id":24345,"date":"2018-08-11T11:41:10","date_gmt":"2018-08-11T10:41:10","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=24345"},"modified":"2023-11-28T12:37:17","modified_gmt":"2023-11-28T11:37:17","slug":"itaca-de-constantino-cavafis","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/","title":{"rendered":"\u00cdTACA, DE CONSTANTINO CAVAFIS"},"content":{"rendered":"<p style=\"text-align: right;\"><a href=\"https:\/\/www.itakaescolapios.org\/2018\/08\/itaca-de-constantino-cavafis\/1itaca-196x300\/\" rel=\"attachment wp-att-24346\"><img decoding=\"async\" class=\"size-full wp-image-24346 alignright\" alt=\"1itaca-196x300\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/08\/1itaca-196x300.jpg\" width=\"196\" height=\"300\" \/><\/a><\/p>\n<p style=\"text-align: left;\">Una obra editada por\u00a0<a title=\"N\u00f3rdica editorial\" href=\"https:\/\/www.librosyliteratura.es\/editoriales\/nordica-editoriales\">N\u00f3rdica<\/a>: \u00cdtaca, de Cavafis: puedo decir que es mi poema preferido\u00a0y los fil\u00f3logos dicen que es uno de los poemas m\u00e1s importantes del siglo XX, y sin duda alguna lo es porque en pocas palabras te dice cosas que si las escuchas, te har\u00e1 pensar durante d\u00edas, pero que si escuchas bien, te acompa\u00f1ar\u00e1 el resto de tu vida.<\/p>\n<p>Antes de recomendaros comprar este \u00cdtaca de Cavafis editado por N\u00f3rdica, os tengo que advertir de una cosa. No es el t\u00edpico libro que compras para leer durante horas y pasarlo bien. Es otra cosa distinta. Es un caramelo que compras para leerlo despacio, durante unos minutos, hoje\u00e1ndolo, disfrutando de las ilustraciones, asimilando cada una de las palabras como aut\u00e9nticas perlas de sabidur\u00eda. Es un libro para reflexionar mientras lo tienes en las manos, y tambi\u00e9n mucho tiempo despu\u00e9s de haberlo dejado en la estanter\u00eda. Es un libro para guardar, para ense\u00f1ar a las visitas, para d\u00e1rselo a tus hijos adolescentes y obligarles a prestar atenci\u00f3n; probablemente no aprendan nada, pero quiz\u00e1 plantes el germen de la sabidur\u00eda en sus alocadas cabezas. Este libro es una joya; quiz\u00e1 no sea el libro m\u00e1s \u00fatil como herramienta de entretenimiento, porque se lee en un suspiro intenso y lleno de aroma a especias y mar salada, pero es una obra brillante, majestuosa, que te dar\u00e1 muchos momentos de placer al admirarla, como el m\u00e1s puro de los diamantes. Como una aut\u00e9ntica joya literaria.<\/p>\n<p>Un precioso v\u00eddeo que nos acerca a esta obra:\u00a0<a href=\"https:\/\/www.youtube.com\/watch?time_continue=112&amp;v=30Zy71AOKo0\">https:\/\/www.youtube.com\/watch?time_continue=112&amp;v=30Zy71AOKo0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una obra editada por\u00a0N\u00f3rdica: \u00cdtaca, de Cavafis: puedo decir que es mi poema preferido\u00a0y los fil\u00f3logos dicen que es uno de los poemas m\u00e1s importantes del siglo XX, y sin [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-24345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00cdTACA, DE CONSTANTINO CAVAFIS<\/title>\n<meta name=\"description\" content=\"Una obra editada por\u00a0N\u00f3rdica: \u00cdtaca, de Cavafis: puedo decir que es mi poema preferido\u00a0y los fil\u00f3logos dicen que es uno de los poemas m\u00e1s importantes del siglo XX, y sin duda alguna lo es porque en pocas palabras te dice cosas que si las escuchas, te har\u00e1 pensar durante d\u00edas, pero que si escuchas bien,\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00cdTACA, DE CONSTANTINO CAVAFIS\" \/>\n<meta property=\"og:description\" content=\"Una obra editada por\u00a0N\u00f3rdica: \u00cdtaca, de Cavafis: puedo decir que es mi poema preferido\u00a0y los fil\u00f3logos dicen que es uno de los poemas m\u00e1s importantes del siglo XX, y sin duda alguna lo es porque en pocas palabras te dice cosas que si las escuchas, te har\u00e1 pensar durante d\u00edas, pero que si escuchas bien,\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-11T10:41:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:37:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/08\/1itaca-196x300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"196\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"\u00cdTACA, DE CONSTANTINO CAVAFIS\",\"datePublished\":\"2018-08-11T10:41:10+00:00\",\"dateModified\":\"2023-11-28T11:37:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/\"},\"wordCount\":290,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/1itaca-196x300.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/\",\"name\":\"\u00cdTACA, DE CONSTANTINO CAVAFIS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/1itaca-196x300.jpg\",\"datePublished\":\"2018-08-11T10:41:10+00:00\",\"dateModified\":\"2023-11-28T11:37:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/1itaca-196x300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/1itaca-196x300.jpg\",\"width\":196,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2018\\\/08\\\/itaca-de-constantino-cavafis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00cdTACA, DE CONSTANTINO CAVAFIS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00cdTACA, DE CONSTANTINO CAVAFIS","description":"Una obra editada por\u00a0N\u00f3rdica: \u00cdtaca, de Cavafis: puedo decir que es mi poema preferido\u00a0y los fil\u00f3logos dicen que es uno de los poemas m\u00e1s importantes del siglo XX, y sin duda alguna lo es porque en pocas palabras te dice cosas que si las escuchas, te har\u00e1 pensar durante d\u00edas, pero que si escuchas bien,\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Una obra editada por\u00a0N\u00f3rdica: \u00cdtaca, de Cavafis: puedo decir que es mi poema preferido\u00a0y los fil\u00f3logos dicen que es uno de los poemas m\u00e1s importantes del siglo XX, y sin duda alguna lo es porque en pocas palabras te dice cosas que si las escuchas, te har\u00e1 pensar durante d\u00edas, pero que si escuchas bien,\u2026","og_locale":"fr_FR","og_type":"article","og_title":"\u00cdTACA, DE CONSTANTINO CAVAFIS","og_description":"Una obra editada por\u00a0N\u00f3rdica: \u00cdtaca, de Cavafis: puedo decir que es mi poema preferido\u00a0y los fil\u00f3logos dicen que es uno de los poemas m\u00e1s importantes del siglo XX, y sin duda alguna lo es porque en pocas palabras te dice cosas que si las escuchas, te har\u00e1 pensar durante d\u00edas, pero que si escuchas bien,\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/","og_site_name":"Itaka-Escolapios","article_published_time":"2018-08-11T10:41:10+00:00","article_modified_time":"2023-11-28T11:37:17+00:00","og_image":[{"width":196,"height":300,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/08\/1itaca-196x300.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"\u00cdTACA, DE CONSTANTINO CAVAFIS","datePublished":"2018-08-11T10:41:10+00:00","dateModified":"2023-11-28T11:37:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/"},"wordCount":290,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/08\/1itaca-196x300.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/","name":"\u00cdTACA, DE CONSTANTINO CAVAFIS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/08\/1itaca-196x300.jpg","datePublished":"2018-08-11T10:41:10+00:00","dateModified":"2023-11-28T11:37:17+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/08\/1itaca-196x300.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/08\/1itaca-196x300.jpg","width":196,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2018\/08\/itaca-de-constantino-cavafis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00cdTACA, DE CONSTANTINO CAVAFIS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/24345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=24345"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/24345\/revisions"}],"predecessor-version":[{"id":46428,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/24345\/revisions\/46428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/24346"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=24345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=24345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=24345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}