{"id":27238,"date":"2019-04-01T09:21:03","date_gmt":"2019-04-01T08:21:03","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=27238"},"modified":"2023-11-28T12:36:54","modified_gmt":"2023-11-28T11:36:54","slug":"francais-kikonka-les-femmes-passent-de-theorie-en-pratique","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/","title":{"rendered":"Kikonka : Les femmes passent de th\u00e9orie en pratique !"},"content":{"rendered":"<p>Les femmes de Kikonka sont d\u00e9sormais sur terrain.  Elles pratiquent les th\u00e9ories apprises en agriculture lors de leurs diff\u00e9rentes formations. Dans un terrain grand d\u2019un hectare offert  par la paroisse saint Pierre, ces femmes de Kikonka labourent et cultivent  sous l\u2019\u0153il vigilant de leur formateur, le P\u00e8re Mililngi, piariste et vicaire de la paroisse.  Tr\u00e8s actives, ces femmes remercient entre autre les P\u00e8res Piaristes pour les formations et l\u2019encadrement dont elles sont b\u00e9n\u00e9ficiaires. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les femmes de Kikonka sont d\u00e9sormais sur terrain. Elles pratiquent les th\u00e9ories apprises en agriculture lors de leurs diff\u00e9rentes formations. Dans un terrain grand d\u2019un hectare offert par la paroisse [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":27239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,337],"tags":[],"class_list":["post-27238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-r-d-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kikonka : Les femmes passent de th\u00e9orie en pratique !<\/title>\n<meta name=\"description\" content=\"Les femmes de Kikonka sont d\u00e9sormais sur terrain. Elles pratiquent les th\u00e9ories apprises en agriculture lors de leurs diff\u00e9rentes formations. Dans un terrain grand d\u2019un hectare offert par la paroisse saint Pierre, ces femmes de Kikonka labourent et cultivent sous l\u2019\u0153il vigilant de leur formateur, le P\u00e8re Mililngi, piariste et vicaire de la paroisse. Tr\u00e8s\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Les%20femmes%20de%20Kikonka%20sont%20d\u00e9sormais%20sur%20terrain.%20Elles%20pratiquent%20les%20th\u00e9ories%20apprises%20en%20agriculture%20lors%20de%20leurs%20diff\u00e9rentes%20formations.%20Dans%20un%20terrain%20grand%20d\u2019un%20hectare%20offert%20par%20la%20paroisse%20saint%20Pierre,%20ces%20femmes%20de%20Kikonka%20labourent%20et%20cultivent%20sous%20l\u2019\u0153il%20vigilant%20de%20leur%20formateur,%20le%20P\u00e8re%20Mililngi,%20piariste%20et%20vicaire%20de%20la%20paroisse.%20Tr\u00e8s\u2026\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kikonka : Les femmes passent de th\u00e9orie en pratique !\" \/>\n<meta property=\"og:description\" content=\"Les femmes de Kikonka sont d\u00e9sormais sur terrain. Elles pratiquent les th\u00e9ories apprises en agriculture lors de leurs diff\u00e9rentes formations. Dans un terrain grand d\u2019un hectare offert par la paroisse saint Pierre, ces femmes de Kikonka labourent et cultivent sous l\u2019\u0153il vigilant de leur formateur, le P\u00e8re Mililngi, piariste et vicaire de la paroisse. Tr\u00e8s\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-01T08:21:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/04\/femmes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"Kikonka : Les femmes passent de th\u00e9orie en pratique !\",\"datePublished\":\"2019-04-01T08:21:03+00:00\",\"dateModified\":\"2023-11-28T11:36:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/\"},\"wordCount\":95,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/femmes.jpg\",\"articleSection\":[\"Afrique centrale\",\"R.D. Congo\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/\",\"name\":\"KIKONKA: Las mujeres pasan de la teor\u00eda a la pr\u00e1ctica - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/femmes.jpg\",\"datePublished\":\"2019-04-01T08:21:03+00:00\",\"dateModified\":\"2023-11-28T11:36:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/femmes.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/femmes.jpg\",\"width\":900,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/04\\\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kikonka : Les femmes passent de th\u00e9orie en pratique !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kikonka : Les femmes passent de th\u00e9orie en pratique !","description":"Les femmes de Kikonka sont d\u00e9sormais sur terrain. Elles pratiquent les th\u00e9ories apprises en agriculture lors de leurs diff\u00e9rentes formations. Dans un terrain grand d\u2019un hectare offert par la paroisse saint Pierre, ces femmes de Kikonka labourent et cultivent sous l\u2019\u0153il vigilant de leur formateur, le P\u00e8re Mililngi, piariste et vicaire de la paroisse. Tr\u00e8s\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Les femmes de Kikonka sont d\u00e9sormais sur terrain. Elles pratiquent les th\u00e9ories apprises en agriculture lors de leurs diff\u00e9rentes formations. Dans un terrain grand d\u2019un hectare offert par la paroisse saint Pierre, ces femmes de Kikonka labourent et cultivent sous l\u2019\u0153il vigilant de leur formateur, le P\u00e8re Mililngi, piariste et vicaire de la paroisse. Tr\u00e8s\u2026","og_locale":"fr_FR","og_type":"article","og_title":"Kikonka : Les femmes passent de th\u00e9orie en pratique !","og_description":"Les femmes de Kikonka sont d\u00e9sormais sur terrain. Elles pratiquent les th\u00e9ories apprises en agriculture lors de leurs diff\u00e9rentes formations. Dans un terrain grand d\u2019un hectare offert par la paroisse saint Pierre, ces femmes de Kikonka labourent et cultivent sous l\u2019\u0153il vigilant de leur formateur, le P\u00e8re Mililngi, piariste et vicaire de la paroisse. Tr\u00e8s\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-04-01T08:21:03+00:00","article_modified_time":"2023-11-28T11:36:54+00:00","og_image":[{"width":900,"height":540,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/04\/femmes.jpg","type":"image\/jpeg"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cameroun01"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"Kikonka : Les femmes passent de th\u00e9orie en pratique !","datePublished":"2019-04-01T08:21:03+00:00","dateModified":"2023-11-28T11:36:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/"},"wordCount":95,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/04\/femmes.jpg","articleSection":["Afrique centrale","R.D. Congo"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/","name":"KIKONKA: Las mujeres pasan de la teor\u00eda a la pr\u00e1ctica - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/04\/femmes.jpg","datePublished":"2019-04-01T08:21:03+00:00","dateModified":"2023-11-28T11:36:54+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/04\/femmes.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/04\/femmes.jpg","width":900,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/04\/francais-kikonka-les-femmes-passent-de-theorie-en-pratique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Kikonka : Les femmes passent de th\u00e9orie en pratique !"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/27238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=27238"}],"version-history":[{"count":5,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/27238\/revisions"}],"predecessor-version":[{"id":45773,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/27238\/revisions\/45773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/27239"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=27238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=27238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=27238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}