{"id":28181,"date":"2019-08-29T13:37:02","date_gmt":"2019-08-29T12:37:02","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28181"},"modified":"2023-11-28T12:36:44","modified_gmt":"2023-11-28T11:36:44","slug":"itaka-escolapios-trabaja-por-la-paz-2","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/","title":{"rendered":"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ"},"content":{"rendered":"<p>Desde sus inicios, Itaka &#8211; Escolapios se ha caracterizado por el trabajo por la paz, especialmente a trav\u00e9s de la sensibilizaci\u00f3n, la educaci\u00f3n y con la oferta de canales para potenciar el compromiso por la paz.<\/p>\n<p>Destacamos dos de acciones de otras muchas (objeci\u00f3n de conciencia, objeci\u00f3n fiscal, charlas, testimonios, difusi\u00f3n en medios de comunicaci\u00f3n y acontecimientos, comisiones y grupos por la paz&#8230;) que podr\u00edamos citar:<\/p>\n<ol>\n<li>El Gesto por la paz que hicimos nacer junto con la primera asociaci\u00f3n Itaka (1985) que fue una iniciativa de mucho influjo social para trabajar por la paz en Euskal Herria. Recientemente han publicados interesantes libros sobre ello.<\/li>\n<li>Las Semanas y Jornadas por la paz que hoy se desarrollan en muchos lugares y pa\u00edses con los materiales que desarrollamos desde la Red (desde 2012) y que podemos encontrar en\u00a0<a href=\"https:\/\/www.itakaescolapios.org\/semanas-de-la-paz\/2018-2019-la-paz-esta-en-tus-manos\/\">https:\/\/www.itakaescolapios.org\/semanas-de-la-paz\/2018-2019-la-paz-esta-en-tus-manos\/<\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Desde sus inicios, Itaka &#8211; Escolapios se ha caracterizado por el trabajo por la paz, especialmente a trav\u00e9s de la sensibilizaci\u00f3n, la educaci\u00f3n y con la oferta de canales para [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ<\/title>\n<meta name=\"description\" content=\"Desde sus inicios, Itaka - Escolapios se ha caracterizado por el trabajo por la paz, especialmente a trav\u00e9s de la sensibilizaci\u00f3n, la educaci\u00f3n y con la oferta de canales para potenciar el compromiso por la paz. Destacamos dos de acciones de otras muchas (objeci\u00f3n de conciencia, objeci\u00f3n fiscal, charlas, testimonios, difusi\u00f3n en medios de comunicaci\u00f3n\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ\" \/>\n<meta property=\"og:description\" content=\"Desde sus inicios, Itaka - Escolapios se ha caracterizado por el trabajo por la paz, especialmente a trav\u00e9s de la sensibilizaci\u00f3n, la educaci\u00f3n y con la oferta de canales para potenciar el compromiso por la paz. Destacamos dos de acciones de otras muchas (objeci\u00f3n de conciencia, objeci\u00f3n fiscal, charlas, testimonios, difusi\u00f3n en medios de comunicaci\u00f3n\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-29T12:37:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/gesto-libros.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"903\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ\",\"datePublished\":\"2019-08-29T12:37:02+00:00\",\"dateModified\":\"2023-11-28T11:36:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/\"},\"wordCount\":157,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/gesto-libros.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/gesto-libros.jpg\",\"datePublished\":\"2019-08-29T12:37:02+00:00\",\"dateModified\":\"2023-11-28T11:36:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/gesto-libros.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/gesto-libros.jpg\",\"width\":903,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/08\\\/itaka-escolapios-trabaja-por-la-paz-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ","description":"Desde sus inicios, Itaka - Escolapios se ha caracterizado por el trabajo por la paz, especialmente a trav\u00e9s de la sensibilizaci\u00f3n, la educaci\u00f3n y con la oferta de canales para potenciar el compromiso por la paz. Destacamos dos de acciones de otras muchas (objeci\u00f3n de conciencia, objeci\u00f3n fiscal, charlas, testimonios, difusi\u00f3n en medios de comunicaci\u00f3n\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/","og_locale":"fr_FR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ","og_description":"Desde sus inicios, Itaka - Escolapios se ha caracterizado por el trabajo por la paz, especialmente a trav\u00e9s de la sensibilizaci\u00f3n, la educaci\u00f3n y con la oferta de canales para potenciar el compromiso por la paz. Destacamos dos de acciones de otras muchas (objeci\u00f3n de conciencia, objeci\u00f3n fiscal, charlas, testimonios, difusi\u00f3n en medios de comunicaci\u00f3n\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-08-29T12:37:02+00:00","article_modified_time":"2023-11-28T11:36:44+00:00","og_image":[{"width":903,"height":670,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/gesto-libros.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ","datePublished":"2019-08-29T12:37:02+00:00","dateModified":"2023-11-28T11:36:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/"},"wordCount":157,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/gesto-libros.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/","name":"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/gesto-libros.jpg","datePublished":"2019-08-29T12:37:02+00:00","dateModified":"2023-11-28T11:36:44+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/gesto-libros.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/gesto-libros.jpg","width":903,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/08\/itaka-escolapios-trabaja-por-la-paz-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... TRABAJA POR LA PAZ"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=28181"}],"version-history":[{"count":5,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28181\/revisions"}],"predecessor-version":[{"id":45509,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28181\/revisions\/45509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/28182"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=28181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=28181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=28181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}