{"id":28568,"date":"2019-10-22T13:13:09","date_gmt":"2019-10-22T12:13:09","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28568"},"modified":"2023-11-28T12:36:41","modified_gmt":"2023-11-28T11:36:41","slug":"un-voluntariado-muy-especial","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/","title":{"rendered":"UN VOLUNTARIADO MUY ESPECIAL"},"content":{"rendered":"<p>En Itaka &#8211; Escolapios impulsamos un voluntariado muy especial: no es simplemente acciones con personas que se acercan, sino todo un proceso que ayuda a la personas voluntaria y que transforma la realidad donde se lleva a cabo.<\/p>\n<p>Por eso, nuestro voluntariado cuenta con una formaci\u00f3n previa, un acompa\u00f1amiento permanente, un desarrollo en grupo, un compromiso mutuo por un tiempo determinado, una formaci\u00f3n permanente, una evaluaci\u00f3n adecuada, un trabajo con proyectos sostenibles en el tiempo, un marco de desarrollo transformador, una propuesta para que la persona viva el voluntariado como un estilo de vida que va ganando espacios en ella&#8230;<\/p>\n<p>Nuestro voluntariado es muy especial&#8230; \u00a1y maravilloso!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Itaka &#8211; Escolapios impulsamos un voluntariado muy especial: no es simplemente acciones con personas que se acercan, sino todo un proceso que ayuda a la personas voluntaria y que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UN VOLUNTARIADO MUY ESPECIAL<\/title>\n<meta name=\"description\" content=\"En Itaka - Escolapios impulsamos un voluntariado muy especial: no es simplemente acciones con personas que se acercan, sino todo un proceso que ayuda a la personas voluntaria y que transforma la realidad donde se lleva a cabo. Por eso, nuestro voluntariado cuenta con una formaci\u00f3n previa, un acompa\u00f1amiento permanente, un desarrollo en grupo, un\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UN VOLUNTARIADO MUY ESPECIAL\" \/>\n<meta property=\"og:description\" content=\"En Itaka - Escolapios impulsamos un voluntariado muy especial: no es simplemente acciones con personas que se acercan, sino todo un proceso que ayuda a la personas voluntaria y que transforma la realidad donde se lleva a cabo. Por eso, nuestro voluntariado cuenta con una formaci\u00f3n previa, un acompa\u00f1amiento permanente, un desarrollo en grupo, un\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-22T12:13:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/FOTO-mc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"UN VOLUNTARIADO MUY ESPECIAL\",\"datePublished\":\"2019-10-22T12:13:09+00:00\",\"dateModified\":\"2023-11-28T11:36:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/\"},\"wordCount\":115,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/FOTO-mc.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/\",\"name\":\"UN VOLUNTARIADO MUY ESPECIAL - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/FOTO-mc.jpg\",\"datePublished\":\"2019-10-22T12:13:09+00:00\",\"dateModified\":\"2023-11-28T11:36:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/FOTO-mc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/FOTO-mc.jpg\",\"width\":2000,\"height\":1414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/un-voluntariado-muy-especial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UN VOLUNTARIADO MUY ESPECIAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UN VOLUNTARIADO MUY ESPECIAL","description":"En Itaka - Escolapios impulsamos un voluntariado muy especial: no es simplemente acciones con personas que se acercan, sino todo un proceso que ayuda a la personas voluntaria y que transforma la realidad donde se lleva a cabo. Por eso, nuestro voluntariado cuenta con una formaci\u00f3n previa, un acompa\u00f1amiento permanente, un desarrollo en grupo, un\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/","og_locale":"fr_FR","og_type":"article","og_title":"UN VOLUNTARIADO MUY ESPECIAL","og_description":"En Itaka - Escolapios impulsamos un voluntariado muy especial: no es simplemente acciones con personas que se acercan, sino todo un proceso que ayuda a la personas voluntaria y que transforma la realidad donde se lleva a cabo. Por eso, nuestro voluntariado cuenta con una formaci\u00f3n previa, un acompa\u00f1amiento permanente, un desarrollo en grupo, un\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-10-22T12:13:09+00:00","article_modified_time":"2023-11-28T11:36:41+00:00","og_image":[{"width":2000,"height":1414,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/FOTO-mc.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"UN VOLUNTARIADO MUY ESPECIAL","datePublished":"2019-10-22T12:13:09+00:00","dateModified":"2023-11-28T11:36:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/"},"wordCount":115,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/FOTO-mc.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/","name":"UN VOLUNTARIADO MUY ESPECIAL - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/FOTO-mc.jpg","datePublished":"2019-10-22T12:13:09+00:00","dateModified":"2023-11-28T11:36:41+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/FOTO-mc.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/FOTO-mc.jpg","width":2000,"height":1414},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/un-voluntariado-muy-especial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"UN VOLUNTARIADO MUY ESPECIAL"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=28568"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28568\/revisions"}],"predecessor-version":[{"id":45415,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28568\/revisions\/45415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/28416"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=28568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=28568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=28568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}