{"id":28594,"date":"2019-10-27T11:29:21","date_gmt":"2019-10-27T10:29:21","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28594"},"modified":"2023-11-28T12:36:40","modified_gmt":"2023-11-28T11:36:40","slug":"itaka-escolapios-preciosa-historia-que-continua","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/","title":{"rendered":"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA"},"content":{"rendered":"<p>Cuando miramos hacia atr\u00e1s en los 34 a\u00f1os de nuestra historia vemos preciosos cap\u00edtulo de personas que dejan huella, de proyectos transformadores incre\u00edbles, de generosidad en grandes cantidades, de sue\u00f1os que nos animan a seguir adelante, de desaf\u00edos que nos impulsar a esforzar m\u00e1s y m\u00e1s&#8230;<\/p>\n<p>Y, sobre todo, vemos que el horizonte sigue all\u00e1 a lo lejos marcando un camino y una historia que tiene que continuar con nuevas personas, en nuevos lugares y pa\u00edses, con nuevos proyectos y planes.<\/p>\n<p>Itaka &#8211; Escolapios es una preciosa historia&#8230; con mucho futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando miramos hacia atr\u00e1s en los 34 a\u00f1os de nuestra historia vemos preciosos cap\u00edtulo de personas que dejan huella, de proyectos transformadores incre\u00edbles, de generosidad en grandes cantidades, de sue\u00f1os [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA<\/title>\n<meta name=\"description\" content=\"Cuando miramos hacia atr\u00e1s en los 34 a\u00f1os de nuestra historia vemos preciosos cap\u00edtulo de personas que dejan huella, de proyectos transformadores incre\u00edbles, de generosidad en grandes cantidades, de sue\u00f1os que nos animan a seguir adelante, de desaf\u00edos que nos impulsar a esforzar m\u00e1s y m\u00e1s... Y, sobre todo, vemos que el horizonte sigue all\u00e1\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA\" \/>\n<meta property=\"og:description\" content=\"Cuando miramos hacia atr\u00e1s en los 34 a\u00f1os de nuestra historia vemos preciosos cap\u00edtulo de personas que dejan huella, de proyectos transformadores incre\u00edbles, de generosidad en grandes cantidades, de sue\u00f1os que nos animan a seguir adelante, de desaf\u00edos que nos impulsar a esforzar m\u00e1s y m\u00e1s... Y, sobre todo, vemos que el horizonte sigue all\u00e1\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-27T10:29:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1futuroo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA\",\"datePublished\":\"2019-10-27T10:29:21+00:00\",\"dateModified\":\"2023-11-28T11:36:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/\"},\"wordCount\":107,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1futuroo.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1futuroo.jpg\",\"datePublished\":\"2019-10-27T10:29:21+00:00\",\"dateModified\":\"2023-11-28T11:36:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1futuroo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1futuroo.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-preciosa-historia-que-continua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA","description":"Cuando miramos hacia atr\u00e1s en los 34 a\u00f1os de nuestra historia vemos preciosos cap\u00edtulo de personas que dejan huella, de proyectos transformadores incre\u00edbles, de generosidad en grandes cantidades, de sue\u00f1os que nos animan a seguir adelante, de desaf\u00edos que nos impulsar a esforzar m\u00e1s y m\u00e1s... Y, sobre todo, vemos que el horizonte sigue all\u00e1\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/","og_locale":"fr_FR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA","og_description":"Cuando miramos hacia atr\u00e1s en los 34 a\u00f1os de nuestra historia vemos preciosos cap\u00edtulo de personas que dejan huella, de proyectos transformadores incre\u00edbles, de generosidad en grandes cantidades, de sue\u00f1os que nos animan a seguir adelante, de desaf\u00edos que nos impulsar a esforzar m\u00e1s y m\u00e1s... Y, sobre todo, vemos que el horizonte sigue all\u00e1\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-10-27T10:29:21+00:00","article_modified_time":"2023-11-28T11:36:40+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1futuroo.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA","datePublished":"2019-10-27T10:29:21+00:00","dateModified":"2023-11-28T11:36:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/"},"wordCount":107,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1futuroo.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/","name":"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1futuroo.jpg","datePublished":"2019-10-27T10:29:21+00:00","dateModified":"2023-11-28T11:36:40+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1futuroo.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1futuroo.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-preciosa-historia-que-continua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... PRECIOSA HISTORIA QUE CONTIN\u00daA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=28594"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28594\/revisions"}],"predecessor-version":[{"id":45403,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28594\/revisions\/45403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/28595"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=28594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=28594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=28594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}