{"id":28676,"date":"2019-10-30T11:53:29","date_gmt":"2019-10-30T10:53:29","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28676"},"modified":"2023-11-28T12:36:39","modified_gmt":"2023-11-28T11:36:39","slug":"itaka-escolapios-para-transformarnos-2","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/","title":{"rendered":"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS)"},"content":{"rendered":"<p>Nuestra Red Itaka &#8211; Escolapios es una realidad que transforma nuestro entorno, la sociedad entera y el mundo por medio de la educaci\u00f3n formal y no formal, la propuesta de valores cristianos y los proyectos de transformaci\u00f3n social.<\/p>\n<p>Y, a la vez, es un \u00e1mbito que nos transforma a todas las personas que estamos implicadas en ella: a los destinatarios de los proyectos, a los voluntarios, a los profesionales, a los colaboradores de diferentes maneras&#8230; porque nos hace ver \u00ab\u00a0otro mundo\u00a0\u00bb lleno de posibilidades y va llenado nuestra vida de sentido y nuestro entorno de felicidad.<\/p>\n<p>Itaka &#8211; Escolapios transforma el mundo \u00a1y nos transforma a nosotros!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Red Itaka &#8211; Escolapios es una realidad que transforma nuestro entorno, la sociedad entera y el mundo por medio de la educaci\u00f3n formal y no formal, la propuesta de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS)<\/title>\n<meta name=\"description\" content=\"Nuestra Red Itaka - Escolapios es una realidad que transforma nuestro entorno, la sociedad entera y el mundo por medio de la educaci\u00f3n formal y no formal, la propuesta de valores cristianos y los proyectos de transformaci\u00f3n social. Y, a la vez, es un \u00e1mbito que nos transforma a todas las personas que estamos implicadas\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS)\" \/>\n<meta property=\"og:description\" content=\"Nuestra Red Itaka - Escolapios es una realidad que transforma nuestro entorno, la sociedad entera y el mundo por medio de la educaci\u00f3n formal y no formal, la propuesta de valores cristianos y los proyectos de transformaci\u00f3n social. Y, a la vez, es un \u00e1mbito que nos transforma a todas las personas que estamos implicadas\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-30T10:53:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1transformar-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"816\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS)\",\"datePublished\":\"2019-10-30T10:53:29+00:00\",\"dateModified\":\"2023-11-28T11:36:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/\"},\"wordCount\":115,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1transformar-web.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS) - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1transformar-web.jpg\",\"datePublished\":\"2019-10-30T10:53:29+00:00\",\"dateModified\":\"2023-11-28T11:36:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1transformar-web.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1transformar-web.jpg\",\"width\":816,\"height\":614},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/10\\\/itaka-escolapios-para-transformarnos-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS)","description":"Nuestra Red Itaka - Escolapios es una realidad que transforma nuestro entorno, la sociedad entera y el mundo por medio de la educaci\u00f3n formal y no formal, la propuesta de valores cristianos y los proyectos de transformaci\u00f3n social. Y, a la vez, es un \u00e1mbito que nos transforma a todas las personas que estamos implicadas\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/","og_locale":"fr_FR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS)","og_description":"Nuestra Red Itaka - Escolapios es una realidad que transforma nuestro entorno, la sociedad entera y el mundo por medio de la educaci\u00f3n formal y no formal, la propuesta de valores cristianos y los proyectos de transformaci\u00f3n social. Y, a la vez, es un \u00e1mbito que nos transforma a todas las personas que estamos implicadas\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-10-30T10:53:29+00:00","article_modified_time":"2023-11-28T11:36:39+00:00","og_image":[{"width":816,"height":614,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1transformar-web.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS)","datePublished":"2019-10-30T10:53:29+00:00","dateModified":"2023-11-28T11:36:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/"},"wordCount":115,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1transformar-web.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/","name":"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS) - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1transformar-web.jpg","datePublished":"2019-10-30T10:53:29+00:00","dateModified":"2023-11-28T11:36:39+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1transformar-web.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1transformar-web.jpg","width":816,"height":614},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/10\/itaka-escolapios-para-transformarnos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... PARA TRANSFORMAR(NOS)"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=28676"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28676\/revisions"}],"predecessor-version":[{"id":45372,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/28676\/revisions\/45372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/28677"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=28676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=28676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=28676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}