{"id":29337,"date":"2019-12-02T10:36:01","date_gmt":"2019-12-02T09:36:01","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29337"},"modified":"2023-11-28T12:36:36","modified_gmt":"2023-11-28T11:36:36","slug":"itaka-escolapios-una-oportunidad","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/","title":{"rendered":"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD"},"content":{"rendered":"<p>Nuestra Red internacional Itaka &#8211; Escolapios es una oportunidad para miles de personas que no tienen muchas posibilidades de salir adelante: ni\u00f1os que precisan una escuela mejor y comer cada d\u00eda, j\u00f3venes que no ven presente ni futuro, gentes empobrecidas por diferentes situaciones, pueblos y barrios donde la vida es especialmente dura&#8230; y para tenemos decenas de acciones solidarias, de proyectos de transformaci\u00f3n social.<\/p>\n<p>Y tambi\u00e9n Itaka &#8211; Escolapios es una oportunidad para quien tiene de todo&#8230; menos un motivo para sentirse feliz y para ver que su vida tiene sentido. Nuestra Red ofrece la posibilidad de crecer en humanidad, en solidaridad, en ser feliz haciendo felices a los dem\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Red internacional Itaka &#8211; Escolapios es una oportunidad para miles de personas que no tienen muchas posibilidades de salir adelante: ni\u00f1os que precisan una escuela mejor y comer cada [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-29337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD<\/title>\n<meta name=\"description\" content=\"Nuestra Red internacional Itaka - Escolapios es una oportunidad para miles de personas que no tienen muchas posibilidades de salir adelante: ni\u00f1os que precisan una escuela mejor y comer cada d\u00eda, j\u00f3venes que no ven presente ni futuro, gentes empobrecidas por diferentes situaciones, pueblos y barrios donde la vida es especialmente dura... y para tenemos\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD\" \/>\n<meta property=\"og:description\" content=\"Nuestra Red internacional Itaka - Escolapios es una oportunidad para miles de personas que no tienen muchas posibilidades de salir adelante: ni\u00f1os que precisan una escuela mejor y comer cada d\u00eda, j\u00f3venes que no ven presente ni futuro, gentes empobrecidas por diferentes situaciones, pueblos y barrios donde la vida es especialmente dura... y para tenemos\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-02T09:36:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD\",\"datePublished\":\"2019-12-02T09:36:01+00:00\",\"dateModified\":\"2023-11-28T11:36:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1a.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1a.jpg\",\"datePublished\":\"2019-12-02T09:36:01+00:00\",\"dateModified\":\"2023-11-28T11:36:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1a.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1a.jpg\",\"width\":850,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2019\\\/12\\\/itaka-escolapios-una-oportunidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD","description":"Nuestra Red internacional Itaka - Escolapios es una oportunidad para miles de personas que no tienen muchas posibilidades de salir adelante: ni\u00f1os que precisan una escuela mejor y comer cada d\u00eda, j\u00f3venes que no ven presente ni futuro, gentes empobrecidas por diferentes situaciones, pueblos y barrios donde la vida es especialmente dura... y para tenemos\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/","og_locale":"fr_FR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD","og_description":"Nuestra Red internacional Itaka - Escolapios es una oportunidad para miles de personas que no tienen muchas posibilidades de salir adelante: ni\u00f1os que precisan una escuela mejor y comer cada d\u00eda, j\u00f3venes que no ven presente ni futuro, gentes empobrecidas por diferentes situaciones, pueblos y barrios donde la vida es especialmente dura... y para tenemos\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-12-02T09:36:01+00:00","article_modified_time":"2023-11-28T11:36:36+00:00","og_image":[{"width":850,"height":400,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1a.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD","datePublished":"2019-12-02T09:36:01+00:00","dateModified":"2023-11-28T11:36:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/"},"wordCount":121,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1a.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/","name":"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1a.jpg","datePublished":"2019-12-02T09:36:01+00:00","dateModified":"2023-11-28T11:36:36+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1a.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/12\/1a.jpg","width":850,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2019\/12\/itaka-escolapios-una-oportunidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... UNA OPORTUNIDAD"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=29337"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29337\/revisions"}],"predecessor-version":[{"id":45280,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29337\/revisions\/45280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/29338"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=29337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=29337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=29337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}