{"id":29631,"date":"2020-01-05T14:13:49","date_gmt":"2020-01-05T13:13:49","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29631"},"modified":"2023-11-28T12:36:33","modified_gmt":"2023-11-28T11:36:33","slug":"la-novedad-de-itaka-escolapios","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/","title":{"rendered":"LA NOVEDAD DE ITAKA - ESCOLAPIOS"},"content":{"rendered":"<p>Nuestra red Itaka &#8211; Escolapios es una novedad, tan rica que no siempre es f\u00e1cil de comprender en su globalidad&#8230; porque es una ONGD pero es m\u00e1s, una red internacional, una plataforma de misi\u00f3n compartida, una oportunidad para la Orden y la Fraternidad escolapias, un lugar de encuentro de miles de personas, una iniciativa de solidaridad, una manera de llevar adelante muchos proyectos educativos transformadores, una puerta abierta al futuro&#8230; y m\u00e1s, mucho m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra red Itaka &#8211; Escolapios es una novedad, tan rica que no siempre es f\u00e1cil de comprender en su globalidad&#8230; porque es una ONGD pero es m\u00e1s, una red internacional, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-29631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA NOVEDAD DE ITAKA - ESCOLAPIOS<\/title>\n<meta name=\"description\" content=\"Nuestra red Itaka - Escolapios es una novedad, tan rica que no siempre es f\u00e1cil de comprender en su globalidad... porque es una ONGD pero es m\u00e1s, una red internacional, una plataforma de misi\u00f3n compartida, una oportunidad para la Orden y la Fraternidad escolapias, un lugar de encuentro de miles de personas, una iniciativa de\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA NOVEDAD DE ITAKA - ESCOLAPIOS\" \/>\n<meta property=\"og:description\" content=\"Nuestra red Itaka - Escolapios es una novedad, tan rica que no siempre es f\u00e1cil de comprender en su globalidad... porque es una ONGD pero es m\u00e1s, una red internacional, una plataforma de misi\u00f3n compartida, una oportunidad para la Orden y la Fraternidad escolapias, un lugar de encuentro de miles de personas, una iniciativa de\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-05T13:13:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1m\u00e1s.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"LA NOVEDAD DE ITAKA - ESCOLAPIOS\",\"datePublished\":\"2020-01-05T13:13:49+00:00\",\"dateModified\":\"2023-11-28T11:36:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/\"},\"wordCount\":85,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1m\u00e1s.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/\",\"name\":\"LA NOVEDAD DE ITAKA - ESCOLAPIOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1m\u00e1s.jpg\",\"datePublished\":\"2020-01-05T13:13:49+00:00\",\"dateModified\":\"2023-11-28T11:36:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1m\u00e1s.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1m\u00e1s.jpg\",\"width\":980,\"height\":606},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/la-novedad-de-itaka-escolapios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA NOVEDAD DE ITAKA - ESCOLAPIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA NOVEDAD DE ITAKA - ESCOLAPIOS","description":"Nuestra red Itaka - Escolapios es una novedad, tan rica que no siempre es f\u00e1cil de comprender en su globalidad... porque es una ONGD pero es m\u00e1s, una red internacional, una plataforma de misi\u00f3n compartida, una oportunidad para la Orden y la Fraternidad escolapias, un lugar de encuentro de miles de personas, una iniciativa de\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/","og_locale":"fr_FR","og_type":"article","og_title":"LA NOVEDAD DE ITAKA - ESCOLAPIOS","og_description":"Nuestra red Itaka - Escolapios es una novedad, tan rica que no siempre es f\u00e1cil de comprender en su globalidad... porque es una ONGD pero es m\u00e1s, una red internacional, una plataforma de misi\u00f3n compartida, una oportunidad para la Orden y la Fraternidad escolapias, un lugar de encuentro de miles de personas, una iniciativa de\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-01-05T13:13:49+00:00","article_modified_time":"2023-11-28T11:36:33+00:00","og_image":[{"width":980,"height":606,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1m\u00e1s.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"LA NOVEDAD DE ITAKA - ESCOLAPIOS","datePublished":"2020-01-05T13:13:49+00:00","dateModified":"2023-11-28T11:36:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/"},"wordCount":85,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1m\u00e1s.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/","name":"LA NOVEDAD DE ITAKA - ESCOLAPIOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1m\u00e1s.jpg","datePublished":"2020-01-05T13:13:49+00:00","dateModified":"2023-11-28T11:36:33+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1m\u00e1s.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1m\u00e1s.jpg","width":980,"height":606},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/la-novedad-de-itaka-escolapios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"LA NOVEDAD DE ITAKA - ESCOLAPIOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=29631"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29631\/revisions"}],"predecessor-version":[{"id":45190,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29631\/revisions\/45190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/29632"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=29631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=29631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=29631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}