{"id":29787,"date":"2020-01-20T09:58:12","date_gmt":"2020-01-20T08:58:12","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29787"},"modified":"2023-11-28T12:36:31","modified_gmt":"2023-11-28T11:36:31","slug":"arbol-de-navidad-en-africa-del-oeste","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/","title":{"rendered":"Arbre de No\u00ebl en Afrique de l'Ouest"},"content":{"rendered":"<p>L\u2019 \u00ab Arbre de No\u00ebl \u00bb est une activit\u00e9, r\u00e9alis\u00e9e dans les lieux de pr\u00e9sence piariste (\u00e9coles, paroisses, maisons de formation), qui a pour objectif, le partage de la joie de No\u00ebl avec tous les enfants, de pr\u00e9f\u00e9rence ceux issus de famille ou de milieu modeste. Cette ann\u00e9e, elle a eu lieu entre le 20 d\u00e9cembre et le 29 d\u00e9cembre, autour des th\u00e9matiques li\u00e9es \u00e0 la compassion et \u00e0 la g\u00e9n\u00e9rosit\u00e9.<\/p>\n<p>L\u2019arbre de No\u00ebl a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9 dans les pr\u00e9sences piaristes, au S\u00e9n\u00e9gal et en C\u00f4te d\u2019Ivoire.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-29789\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png\" alt=\"\" width=\"500\" height=\"1884\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png 398w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019-80x300.png 80w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019-768x2894.png 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019-272x1024.png 272w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019-250x942.png 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019 \u00ab Arbre de No\u00ebl \u00bb est une activit\u00e9, r\u00e9alis\u00e9e dans les lieux de pr\u00e9sence piariste (\u00e9coles, paroisses, maisons de formation), qui a pour objectif, le partage de la joie [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":29789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[282],"tags":[362,76,431],"class_list":["post-29787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senegal","tag-costa-de-marfil","tag-navidad","tag-senegal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arbre de No\u00ebl en Afrique de l&#039;Ouest<\/title>\n<meta name=\"description\" content=\"L\u2019 \u00ab Arbre de No\u00ebl \u00bb est une activit\u00e9, r\u00e9alis\u00e9e dans les lieux de pr\u00e9sence piariste (\u00e9coles, paroisses, maisons de formation), qui a pour objectif, le partage de la joie de No\u00ebl avec tous les enfants, de pr\u00e9f\u00e9rence ceux issus de famille ou de milieu modeste. Cette ann\u00e9e, elle a eu lieu entre le 20\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/L\u2019%20\u00ab%20Arbre%20de%20No\u00ebl%20\u00bb%20est%20une%20activit\u00e9,%20r\u00e9alis\u00e9e%20dans%20les%20lieux%20de%20pr\u00e9sence%20piariste%20(\u00e9coles,%20paroisses,%20maisons%20de%20formation),%20qui%20a%20pour%20objectif,%20le%20partage%20de%20la%20joie%20de%20No\u00ebl%20avec%20tous%20les%20enfants,%20de%20pr\u00e9f\u00e9rence%20ceux%20issus%20de%20famille%20ou%20de%20milieu%20modeste.%20Cette%20ann\u00e9e,%20elle%20a%20eu%20lieu%20entre%20le%2020\u2026\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbre de No\u00ebl en Afrique de l&#039;Ouest\" \/>\n<meta property=\"og:description\" content=\"L\u2019 \u00ab Arbre de No\u00ebl \u00bb est une activit\u00e9, r\u00e9alis\u00e9e dans les lieux de pr\u00e9sence piariste (\u00e9coles, paroisses, maisons de formation), qui a pour objectif, le partage de la joie de No\u00ebl avec tous les enfants, de pr\u00e9f\u00e9rence ceux issus de famille ou de milieu modeste. Cette ann\u00e9e, elle a eu lieu entre le 20\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-20T08:58:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png\" \/>\n\t<meta property=\"og:image:width\" content=\"398\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"Arbre de No\u00ebl en Afrique de l'Ouest\",\"datePublished\":\"2020-01-20T08:58:12+00:00\",\"dateModified\":\"2023-11-28T11:36:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\"},\"wordCount\":108,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/arbre-de-No\u00ebl-Itaka-2019.png\",\"keywords\":[\"Costa de Marfil\",\"Navidad\",\"Senegal\"],\"articleSection\":[\"Senegal\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\",\"name\":\"\u00c1rbol de Navidad en \u00c1frica del Oeste - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/arbre-de-No\u00ebl-Itaka-2019.png\",\"datePublished\":\"2020-01-20T08:58:12+00:00\",\"dateModified\":\"2023-11-28T11:36:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/arbre-de-No\u00ebl-Itaka-2019.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/arbre-de-No\u00ebl-Itaka-2019.png\",\"width\":398,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arbre de No\u00ebl en Afrique de l'Ouest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arbre de No\u00ebl en Afrique de l'Ouest","description":"L\u2019 \u00ab Arbre de No\u00ebl \u00bb est une activit\u00e9, r\u00e9alis\u00e9e dans les lieux de pr\u00e9sence piariste (\u00e9coles, paroisses, maisons de formation), qui a pour objectif, le partage de la joie de No\u00ebl avec tous les enfants, de pr\u00e9f\u00e9rence ceux issus de famille ou de milieu modeste. Cette ann\u00e9e, elle a eu lieu entre le 20\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"L\u2019 \u00ab Arbre de No\u00ebl \u00bb est une activit\u00e9, r\u00e9alis\u00e9e dans les lieux de pr\u00e9sence piariste (\u00e9coles, paroisses, maisons de formation), qui a pour objectif, le partage de la joie de No\u00ebl avec tous les enfants, de pr\u00e9f\u00e9rence ceux issus de famille ou de milieu modeste. Cette ann\u00e9e, elle a eu lieu entre le 20\u2026","og_locale":"fr_FR","og_type":"article","og_title":"Arbre de No\u00ebl en Afrique de l'Ouest","og_description":"L\u2019 \u00ab Arbre de No\u00ebl \u00bb est une activit\u00e9, r\u00e9alis\u00e9e dans les lieux de pr\u00e9sence piariste (\u00e9coles, paroisses, maisons de formation), qui a pour objectif, le partage de la joie de No\u00ebl avec tous les enfants, de pr\u00e9f\u00e9rence ceux issus de famille ou de milieu modeste. Cette ann\u00e9e, elle a eu lieu entre le 20\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-01-20T08:58:12+00:00","article_modified_time":"2023-11-28T11:36:31+00:00","og_image":[{"width":398,"height":1500,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","type":"image\/png"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itakaescolapios","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"Arbre de No\u00ebl en Afrique de l'Ouest","datePublished":"2020-01-20T08:58:12+00:00","dateModified":"2023-11-28T11:36:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/"},"wordCount":108,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","keywords":["Costa de Marfil","Navidad","Senegal"],"articleSection":["Senegal"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/","name":"\u00c1rbol de Navidad en \u00c1frica del Oeste - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","datePublished":"2020-01-20T08:58:12+00:00","dateModified":"2023-11-28T11:36:31+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","width":398,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Arbre de No\u00ebl en Afrique de l'Ouest"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=29787"}],"version-history":[{"count":11,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29787\/revisions"}],"predecessor-version":[{"id":45146,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29787\/revisions\/45146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/29789"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=29787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=29787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=29787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}