{"id":29836,"date":"2020-01-25T13:41:40","date_gmt":"2020-01-25T12:41:40","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29836"},"modified":"2023-11-28T12:36:31","modified_gmt":"2023-11-28T11:36:31","slug":"francais-itaka-escolapios-trabajando-por-la-paz","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/","title":{"rendered":"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ"},"content":{"rendered":"<p>Trabajar por la paz es renunciar a toda violencia, denunciar las situaciones de injusticia y trabajar por eliminarlas, educar para un mundo que resuelve sus diferencias con el di\u00e1logo, concienciar sobre la necesidad de un mundo en paz, descubrir caminos de paz&#8230; todo eso es una tarea que nuestra Red Itaka &#8211; Escolapios asume como propia.<\/p>\n<p>Y, especialmente en esta semana pr\u00f3xima al D\u00eda internacional escolar de la Paz y no violencia\u00a0\u00bb proponemos una serie de actividades que podemos encontrar en <a href=\"https:\/\/www.itakaescolapios.org\/semanas-de-la-paz\/2019-2020-vive-la-paz\/\">https:\/\/www.itakaescolapios.org\/semanas-de-la-paz\/2019-2020-vive-la-paz\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabajar por la paz es renunciar a toda violencia, denunciar las situaciones de injusticia y trabajar por eliminarlas, educar para un mundo que resuelve sus diferencias con el di\u00e1logo, concienciar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29837,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-29836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ<\/title>\n<meta name=\"description\" content=\"Trabajar por la paz es renunciar a toda violencia, denunciar las situaciones de injusticia y trabajar por eliminarlas, educar para un mundo que resuelve sus diferencias con el di\u00e1logo, concienciar sobre la necesidad de un mundo en paz, descubrir caminos de paz... todo eso es una tarea que nuestra Red Itaka - Escolapios asume como\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ\" \/>\n<meta property=\"og:description\" content=\"Trabajar por la paz es renunciar a toda violencia, denunciar las situaciones de injusticia y trabajar por eliminarlas, educar para un mundo que resuelve sus diferencias con el di\u00e1logo, concienciar sobre la necesidad de un mundo en paz, descubrir caminos de paz... todo eso es una tarea que nuestra Red Itaka - Escolapios asume como\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-25T12:41:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"353\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ\",\"datePublished\":\"2020-01-25T12:41:40+00:00\",\"dateModified\":\"2023-11-28T11:36:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/\"},\"wordCount\":98,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg\",\"datePublished\":\"2020-01-25T12:41:40+00:00\",\"dateModified\":\"2023-11-28T11:36:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg\",\"width\":250,\"height\":353},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/01\\\/francais-itaka-escolapios-trabajando-por-la-paz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ","description":"Trabajar por la paz es renunciar a toda violencia, denunciar las situaciones de injusticia y trabajar por eliminarlas, educar para un mundo que resuelve sus diferencias con el di\u00e1logo, concienciar sobre la necesidad de un mundo en paz, descubrir caminos de paz... todo eso es una tarea que nuestra Red Itaka - Escolapios asume como\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/","og_locale":"fr_FR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ","og_description":"Trabajar por la paz es renunciar a toda violencia, denunciar las situaciones de injusticia y trabajar por eliminarlas, educar para un mundo que resuelve sus diferencias con el di\u00e1logo, concienciar sobre la necesidad de un mundo en paz, descubrir caminos de paz... todo eso es una tarea que nuestra Red Itaka - Escolapios asume como\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-01-25T12:41:40+00:00","article_modified_time":"2023-11-28T11:36:31+00:00","og_image":[{"width":250,"height":353,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ","datePublished":"2020-01-25T12:41:40+00:00","dateModified":"2023-11-28T11:36:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/"},"wordCount":98,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/","name":"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg","datePublished":"2020-01-25T12:41:40+00:00","dateModified":"2023-11-28T11:36:31+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1-CARTEL-CAMPA\u00d1A-PAZ-1920-250x353-1.jpg","width":250,"height":353},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/01\/francais-itaka-escolapios-trabajando-por-la-paz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... TRABAJANDO POR LA PAZ"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=29836"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29836\/revisions"}],"predecessor-version":[{"id":45136,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/29836\/revisions\/45136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/29837"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=29836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=29836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=29836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}