{"id":30216,"date":"2020-03-08T11:46:53","date_gmt":"2020-03-08T10:46:53","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30216"},"modified":"2023-11-28T12:36:27","modified_gmt":"2023-11-28T11:36:27","slug":"falta-un-dia","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/","title":{"rendered":"FALTA UN D\u00cdA..."},"content":{"rendered":"<p>Itaka \u2013 Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o\u2026 y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.<br \/>\nCientos de personas en muchos pa\u00edses del mundo lo est\u00e1n comprobando en nuestra Red Itaka \u2013 Escolapios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Itaka \u2013 Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FALTA UN D\u00cdA...<\/title>\n<meta name=\"description\" content=\"Itaka \u2013 Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o\u2026 y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FALTA UN D\u00cdA...\" \/>\n<meta property=\"og:description\" content=\"Itaka \u2013 Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o\u2026 y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-08T10:46:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/dia-int-vol-2020-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1449\" \/>\n\t<meta property=\"og:image:height\" content=\"1137\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"FALTA UN D\u00cdA...\",\"datePublished\":\"2020-03-08T10:46:53+00:00\",\"dateModified\":\"2023-11-28T11:36:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/\"},\"wordCount\":80,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/dia-int-vol-2020-01.png\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/\",\"name\":\"FALTA UN D\u00cdA... - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/dia-int-vol-2020-01.png\",\"datePublished\":\"2020-03-08T10:46:53+00:00\",\"dateModified\":\"2023-11-28T11:36:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/dia-int-vol-2020-01.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/dia-int-vol-2020-01.png\",\"width\":1449,\"height\":1137},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/03\\\/falta-un-dia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FALTA UN D\u00cdA...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FALTA UN D\u00cdA...","description":"Itaka \u2013 Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o\u2026 y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/","og_locale":"fr_FR","og_type":"article","og_title":"FALTA UN D\u00cdA...","og_description":"Itaka \u2013 Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o\u2026 y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-03-08T10:46:53+00:00","article_modified_time":"2023-11-28T11:36:27+00:00","og_image":[{"width":1449,"height":1137,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/dia-int-vol-2020-01.png","type":"image\/png"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"FALTA UN D\u00cdA...","datePublished":"2020-03-08T10:46:53+00:00","dateModified":"2023-11-28T11:36:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/"},"wordCount":80,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/dia-int-vol-2020-01.png","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/","name":"FALTA UN D\u00cdA... - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/dia-int-vol-2020-01.png","datePublished":"2020-03-08T10:46:53+00:00","dateModified":"2023-11-28T11:36:27+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/dia-int-vol-2020-01.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/dia-int-vol-2020-01.png","width":1449,"height":1137},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/03\/falta-un-dia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"FALTA UN D\u00cdA..."}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/30216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=30216"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/30216\/revisions"}],"predecessor-version":[{"id":45020,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/30216\/revisions\/45020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/30217"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=30216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=30216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=30216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}