{"id":30647,"date":"2020-05-10T10:44:48","date_gmt":"2020-05-10T09:44:48","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30647"},"modified":"2023-11-28T12:36:21","modified_gmt":"2023-11-28T11:36:21","slug":"itaka-escolapios-para-reforzar-otros-proyectos","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/","title":{"rendered":"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS"},"content":{"rendered":"<p>Nuestra Red Itaka &#8211; Escolapios lleva adelante muchos proyectos compartidos con la Orden y la Fraternidad, a la vez que refuerza otros proyectos escolapios: hace m\u00e1s fuerte al Movimiento Calasanz ofreciendo una red de posibilidades formativas y solidarias, a los colegios ofreciendo nuevos espacios educativos, a las parroquias con propuestas de sensibilizaci\u00f3n y voluntariado, a los centros culturales y sociales con una red de recursos de todo tipo, a las distintas modalidades de participaci\u00f3n en las Escuelas P\u00edas con caminos ya abiertos en muchos lugares, a la misi\u00f3n escolapia con una entidad de probada eficiencia, a la presencia escolapia con un abanico de posibilidades&#8230;<\/p>\n<p>Itaka &#8211; Escolapios siempre suma&#8230; \u00a1y multiplica!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Red Itaka &#8211; Escolapios lleva adelante muchos proyectos compartidos con la Orden y la Fraternidad, a la vez que refuerza otros proyectos escolapios: hace m\u00e1s fuerte al Movimiento Calasanz [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS<\/title>\n<meta name=\"description\" content=\"Nuestra Red Itaka - Escolapios lleva adelante muchos proyectos compartidos con la Orden y la Fraternidad, a la vez que refuerza otros proyectos escolapios: hace m\u00e1s fuerte al Movimiento Calasanz ofreciendo una red de posibilidades formativas y solidarias, a los colegios ofreciendo nuevos espacios educativos, a las parroquias con propuestas de sensibilizaci\u00f3n y voluntariado, a\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS\" \/>\n<meta property=\"og:description\" content=\"Nuestra Red Itaka - Escolapios lleva adelante muchos proyectos compartidos con la Orden y la Fraternidad, a la vez que refuerza otros proyectos escolapios: hace m\u00e1s fuerte al Movimiento Calasanz ofreciendo una red de posibilidades formativas y solidarias, a los colegios ofreciendo nuevos espacios educativos, a las parroquias con propuestas de sensibilizaci\u00f3n y voluntariado, a\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-10T09:44:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1multi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"312\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS\",\"datePublished\":\"2020-05-10T09:44:48+00:00\",\"dateModified\":\"2023-11-28T11:36:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/\"},\"wordCount\":123,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1multi.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/\",\"name\":\"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1multi.jpg\",\"datePublished\":\"2020-05-10T09:44:48+00:00\",\"dateModified\":\"2023-11-28T11:36:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1multi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1multi.jpg\",\"width\":820,\"height\":312},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/itaka-escolapios-para-reforzar-otros-proyectos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS","description":"Nuestra Red Itaka - Escolapios lleva adelante muchos proyectos compartidos con la Orden y la Fraternidad, a la vez que refuerza otros proyectos escolapios: hace m\u00e1s fuerte al Movimiento Calasanz ofreciendo una red de posibilidades formativas y solidarias, a los colegios ofreciendo nuevos espacios educativos, a las parroquias con propuestas de sensibilizaci\u00f3n y voluntariado, a\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/","og_locale":"fr_FR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS","og_description":"Nuestra Red Itaka - Escolapios lleva adelante muchos proyectos compartidos con la Orden y la Fraternidad, a la vez que refuerza otros proyectos escolapios: hace m\u00e1s fuerte al Movimiento Calasanz ofreciendo una red de posibilidades formativas y solidarias, a los colegios ofreciendo nuevos espacios educativos, a las parroquias con propuestas de sensibilizaci\u00f3n y voluntariado, a\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-05-10T09:44:48+00:00","article_modified_time":"2023-11-28T11:36:21+00:00","og_image":[{"width":820,"height":312,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1multi.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS","datePublished":"2020-05-10T09:44:48+00:00","dateModified":"2023-11-28T11:36:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/"},"wordCount":123,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1multi.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/","name":"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1multi.jpg","datePublished":"2020-05-10T09:44:48+00:00","dateModified":"2023-11-28T11:36:21+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1multi.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1multi.jpg","width":820,"height":312},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/itaka-escolapios-para-reforzar-otros-proyectos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS PARA REFORZAR OTROS PROYECTOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/30647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=30647"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/30647\/revisions"}],"predecessor-version":[{"id":44850,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/30647\/revisions\/44850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/30648"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=30647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=30647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=30647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}