{"id":30962,"date":"2020-05-31T10:36:34","date_gmt":"2020-05-31T09:36:34","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30962"},"modified":"2023-11-28T12:36:18","modified_gmt":"2023-11-28T11:36:18","slug":"necesitamos-tu-colaboracion-2","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/","title":{"rendered":"NECESITAMOS TU COLABORACI\u00d3N"},"content":{"rendered":"<p>Nuestra Red internacional Itaka &#8211; Escolapios necesita tu ayuda, en estos momentos en que muchas de las entradas econ\u00f3micas habituales han desaparecido o se han reducido mucho, porque&#8230;<\/p>\n<ul>\n<li>queremos seguir con los proyectos educativos y sociales que siguen siendo necesarios,<\/li>\n<li>queremos responder a las nuevas necesidades de emergencia (alimentaci\u00f3n, salud y urgencias b\u00e1sicas&#8230;)<\/li>\n<li>queremos mantener el compromiso salarial con los profesionales (la mayor\u00eda son educadores de los cuatro continentes)<\/li>\n<li>queremos avanzar hacia un mundo m\u00e1s solidario donde compartamos con quien m\u00e1s lo necesita<\/li>\n<li>queremos ofrecerte un canal de solidaridad compartiendo tiempo y dinero<\/li>\n<li>queremos ayudarte a descubrir que la felicidad solo es posible haciendo felices a los dem\u00e1s.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Red internacional Itaka &#8211; Escolapios necesita tu ayuda, en estos momentos en que muchas de las entradas econ\u00f3micas habituales han desaparecido o se han reducido mucho, porque&#8230; queremos seguir [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NECESITAMOS TU COLABORACI\u00d3N<\/title>\n<meta name=\"description\" content=\"Nuestra Red internacional Itaka - Escolapios necesita tu ayuda, en estos momentos en que muchas de las entradas econ\u00f3micas habituales han desaparecido o se han reducido mucho, porque... queremos seguir con los proyectos educativos y sociales que siguen siendo necesarios, queremos responder a las nuevas necesidades de emergencia (alimentaci\u00f3n, salud y urgencias b\u00e1sicas...) queremos mantener\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NECESITAMOS TU COLABORACI\u00d3N\" \/>\n<meta property=\"og:description\" content=\"Nuestra Red internacional Itaka - Escolapios necesita tu ayuda, en estos momentos en que muchas de las entradas econ\u00f3micas habituales han desaparecido o se han reducido mucho, porque... queremos seguir con los proyectos educativos y sociales que siguen siendo necesarios, queremos responder a las nuevas necesidades de emergencia (alimentaci\u00f3n, salud y urgencias b\u00e1sicas...) queremos mantener\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-31T09:36:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1images.png\" \/>\n\t<meta property=\"og:image:width\" content=\"290\" \/>\n\t<meta property=\"og:image:height\" content=\"174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"NECESITAMOS TU COLABORACI\u00d3N\",\"datePublished\":\"2020-05-31T09:36:34+00:00\",\"dateModified\":\"2023-11-28T11:36:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/\"},\"wordCount\":119,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1images.png\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/\",\"name\":\"NECESITAMOS TU COLABORACI\u00d3N - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1images.png\",\"datePublished\":\"2020-05-31T09:36:34+00:00\",\"dateModified\":\"2023-11-28T11:36:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1images.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1images.png\",\"width\":290,\"height\":174},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/05\\\/necesitamos-tu-colaboracion-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NECESITAMOS TU COLABORACI\u00d3N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NECESITAMOS TU COLABORACI\u00d3N","description":"Nuestra Red internacional Itaka - Escolapios necesita tu ayuda, en estos momentos en que muchas de las entradas econ\u00f3micas habituales han desaparecido o se han reducido mucho, porque... queremos seguir con los proyectos educativos y sociales que siguen siendo necesarios, queremos responder a las nuevas necesidades de emergencia (alimentaci\u00f3n, salud y urgencias b\u00e1sicas...) queremos mantener\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/","og_locale":"fr_FR","og_type":"article","og_title":"NECESITAMOS TU COLABORACI\u00d3N","og_description":"Nuestra Red internacional Itaka - Escolapios necesita tu ayuda, en estos momentos en que muchas de las entradas econ\u00f3micas habituales han desaparecido o se han reducido mucho, porque... queremos seguir con los proyectos educativos y sociales que siguen siendo necesarios, queremos responder a las nuevas necesidades de emergencia (alimentaci\u00f3n, salud y urgencias b\u00e1sicas...) queremos mantener\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-05-31T09:36:34+00:00","article_modified_time":"2023-11-28T11:36:18+00:00","og_image":[{"width":290,"height":174,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1images.png","type":"image\/png"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"NECESITAMOS TU COLABORACI\u00d3N","datePublished":"2020-05-31T09:36:34+00:00","dateModified":"2023-11-28T11:36:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/"},"wordCount":119,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1images.png","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/","name":"NECESITAMOS TU COLABORACI\u00d3N - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1images.png","datePublished":"2020-05-31T09:36:34+00:00","dateModified":"2023-11-28T11:36:18+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1images.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1images.png","width":290,"height":174},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/05\/necesitamos-tu-colaboracion-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"NECESITAMOS TU COLABORACI\u00d3N"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/30962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=30962"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/30962\/revisions"}],"predecessor-version":[{"id":44772,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/30962\/revisions\/44772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/30963"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=30962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=30962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=30962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}