{"id":31059,"date":"2020-06-12T13:39:41","date_gmt":"2020-06-12T12:39:41","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=31059"},"modified":"2023-11-28T12:36:17","modified_gmt":"2023-11-28T11:36:17","slug":"itaka-escolapios-si-quieres-crecer-en-humanidad","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/","title":{"rendered":"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD"},"content":{"rendered":"<p>Crecer en humanidad es ser cada d\u00eda m\u00e1s humano, m\u00e1s hermano, m\u00e1s solidario, m\u00e1s familia, m\u00e1s preocupado por el bien del otro, m\u00e1s descentrado de uno mismo para dedicarse m\u00e1s al otro, m\u00e1s capaz de so\u00f1ar un mundo mejor para toda la humanidad, m\u00e1s eficiente e inteligente en esta labor de humanizar nuestra sociedad, m\u00e1s conocedor de los caminos que llevan a esa finalidad, m\u00e1s&#8230;<\/p>\n<p>Si quieres, tienes un sitio en Itaka &#8211; Escolapios para crecer en humanidad, para ayudarnos a crecer en humanid<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crecer en humanidad es ser cada d\u00eda m\u00e1s humano, m\u00e1s hermano, m\u00e1s solidario, m\u00e1s familia, m\u00e1s preocupado por el bien del otro, m\u00e1s descentrado de uno mismo para dedicarse m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-31059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD<\/title>\n<meta name=\"description\" content=\"Crecer en humanidad es ser cada d\u00eda m\u00e1s humano, m\u00e1s hermano, m\u00e1s solidario, m\u00e1s familia, m\u00e1s preocupado por el bien del otro, m\u00e1s descentrado de uno mismo para dedicarse m\u00e1s al otro, m\u00e1s capaz de so\u00f1ar un mundo mejor para toda la humanidad, m\u00e1s eficiente e inteligente en esta labor de humanizar nuestra sociedad, m\u00e1s\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD\" \/>\n<meta property=\"og:description\" content=\"Crecer en humanidad es ser cada d\u00eda m\u00e1s humano, m\u00e1s hermano, m\u00e1s solidario, m\u00e1s familia, m\u00e1s preocupado por el bien del otro, m\u00e1s descentrado de uno mismo para dedicarse m\u00e1s al otro, m\u00e1s capaz de so\u00f1ar un mundo mejor para toda la humanidad, m\u00e1s eficiente e inteligente en esta labor de humanizar nuestra sociedad, m\u00e1s\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-12T12:39:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD\",\"datePublished\":\"2020-06-12T12:39:41+00:00\",\"dateModified\":\"2023-11-28T11:36:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/\"},\"wordCount\":105,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg\",\"datePublished\":\"2020-06-12T12:39:41+00:00\",\"dateModified\":\"2023-11-28T11:36:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg\",\"width\":600,\"height\":646},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/itaka-escolapios-si-quieres-crecer-en-humanidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD","description":"Crecer en humanidad es ser cada d\u00eda m\u00e1s humano, m\u00e1s hermano, m\u00e1s solidario, m\u00e1s familia, m\u00e1s preocupado por el bien del otro, m\u00e1s descentrado de uno mismo para dedicarse m\u00e1s al otro, m\u00e1s capaz de so\u00f1ar un mundo mejor para toda la humanidad, m\u00e1s eficiente e inteligente en esta labor de humanizar nuestra sociedad, m\u00e1s\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/","og_locale":"fr_FR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD","og_description":"Crecer en humanidad es ser cada d\u00eda m\u00e1s humano, m\u00e1s hermano, m\u00e1s solidario, m\u00e1s familia, m\u00e1s preocupado por el bien del otro, m\u00e1s descentrado de uno mismo para dedicarse m\u00e1s al otro, m\u00e1s capaz de so\u00f1ar un mundo mejor para toda la humanidad, m\u00e1s eficiente e inteligente en esta labor de humanizar nuestra sociedad, m\u00e1s\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-06-12T12:39:41+00:00","article_modified_time":"2023-11-28T11:36:17+00:00","og_image":[{"width":600,"height":646,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD","datePublished":"2020-06-12T12:39:41+00:00","dateModified":"2023-11-28T11:36:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/"},"wordCount":105,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/","name":"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg","datePublished":"2020-06-12T12:39:41+00:00","dateModified":"2023-11-28T11:36:17+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1-4ebd5f041bb6519d12e2d1c2ad97c1f7.jpg","width":600,"height":646},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/itaka-escolapios-si-quieres-crecer-en-humanidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... SI QUIERES CRECER EN HUMANIDAD"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/31059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=31059"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/31059\/revisions"}],"predecessor-version":[{"id":44736,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/31059\/revisions\/44736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/31060"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=31059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=31059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=31059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}