{"id":31171,"date":"2020-06-30T11:59:18","date_gmt":"2020-06-30T10:59:18","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=31171"},"modified":"2023-11-28T12:36:15","modified_gmt":"2023-11-28T11:36:15","slug":"reunion-del-patronato-de-itaka-escolapios-4","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/","title":{"rendered":"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS"},"content":{"rendered":"<p>Ayer, 29 de junio, tuvo lugar una nueva reuni\u00f3n (en esta ocasi\u00f3n virtual) del Patronato de Itaka &#8211; Escolapios con la<span class=\"text_exposed_show\">\u00a0novedad de la presencia de los dos nuevos miembros: P. Emmanuel Su\u00e1rez (M\u00e9xico) y P. Felicien Mouendji (R. D. Congo).<br \/>\nDespu\u00e9s del saludo de bienvenida a todos, y especialmente a los nuevos miembros, fuimos desarrollando el orden del d\u00eda previsto con la oraci\u00f3n inicial, la aprobaci\u00f3n del acta de la reuni\u00f3n anterior, la presentaci\u00f3n y comentario de la situaci\u00f3n actual en los distintos lugares y equipos de la Red a partir de una publicaci\u00f3n que daremos a conocer en breve, la presentaci\u00f3n y aprobaci\u00f3n del presupuesto para el pr\u00f3ximo ejercicios 2020-2021, una primera reflexi\u00f3n sobre el IV Consejo Asesor que celebraremos en marzo de 2021 y del proceso de elaboraci\u00f3n del nuevo Plan Estrat\u00e9gico 2021-2027, para concluir con algunas decisiones concretas sobre la pol\u00edtica de calidad de la Red, el nombramiento de representante para el nuevo proyecto de Itaka &#8211; Escolapios en Zazagoza (Le damos la vuelta) y marcar la fecha de la pr\u00f3xima reuni\u00f3n.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer, 29 de junio, tuvo lugar una nueva reuni\u00f3n (en esta ocasi\u00f3n virtual) del Patronato de Itaka &#8211; Escolapios con la\u00a0novedad de la presencia de los dos nuevos miembros: P. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-31171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS<\/title>\n<meta name=\"description\" content=\"Ayer, 29 de junio, tuvo lugar una nueva reuni\u00f3n (en esta ocasi\u00f3n virtual) del Patronato de Itaka - Escolapios con la\u00a0novedad de la presencia de los dos nuevos miembros: P. Emmanuel Su\u00e1rez (M\u00e9xico) y P. Felicien Mouendji (R. D. Congo). Despu\u00e9s del saludo de bienvenida a todos, y especialmente a los nuevos miembros, fuimos desarrollando\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS\" \/>\n<meta property=\"og:description\" content=\"Ayer, 29 de junio, tuvo lugar una nueva reuni\u00f3n (en esta ocasi\u00f3n virtual) del Patronato de Itaka - Escolapios con la\u00a0novedad de la presencia de los dos nuevos miembros: P. Emmanuel Su\u00e1rez (M\u00e9xico) y P. Felicien Mouendji (R. D. Congo). Despu\u00e9s del saludo de bienvenida a todos, y especialmente a los nuevos miembros, fuimos desarrollando\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-30T10:59:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1patro-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS\",\"datePublished\":\"2020-06-30T10:59:18+00:00\",\"dateModified\":\"2023-11-28T11:36:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/\"},\"wordCount\":203,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1patro-11.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/\",\"name\":\"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1patro-11.jpg\",\"datePublished\":\"2020-06-30T10:59:18+00:00\",\"dateModified\":\"2023-11-28T11:36:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1patro-11.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/1patro-11.jpg\",\"width\":1366,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2020\\\/06\\\/reunion-del-patronato-de-itaka-escolapios-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS","description":"Ayer, 29 de junio, tuvo lugar una nueva reuni\u00f3n (en esta ocasi\u00f3n virtual) del Patronato de Itaka - Escolapios con la\u00a0novedad de la presencia de los dos nuevos miembros: P. Emmanuel Su\u00e1rez (M\u00e9xico) y P. Felicien Mouendji (R. D. Congo). Despu\u00e9s del saludo de bienvenida a todos, y especialmente a los nuevos miembros, fuimos desarrollando\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/","og_locale":"fr_FR","og_type":"article","og_title":"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS","og_description":"Ayer, 29 de junio, tuvo lugar una nueva reuni\u00f3n (en esta ocasi\u00f3n virtual) del Patronato de Itaka - Escolapios con la\u00a0novedad de la presencia de los dos nuevos miembros: P. Emmanuel Su\u00e1rez (M\u00e9xico) y P. Felicien Mouendji (R. D. Congo). Despu\u00e9s del saludo de bienvenida a todos, y especialmente a los nuevos miembros, fuimos desarrollando\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-06-30T10:59:18+00:00","article_modified_time":"2023-11-28T11:36:15+00:00","og_image":[{"width":1366,"height":768,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1patro-11.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"itaka","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS","datePublished":"2020-06-30T10:59:18+00:00","dateModified":"2023-11-28T11:36:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/"},"wordCount":203,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1patro-11.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/","name":"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1patro-11.jpg","datePublished":"2020-06-30T10:59:18+00:00","dateModified":"2023-11-28T11:36:15+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1patro-11.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/06\/1patro-11.jpg","width":1366,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2020\/06\/reunion-del-patronato-de-itaka-escolapios-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"REUNI\u00d3N DEL PATRONATO DE ITAKA - ESCOLAPIOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/31171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=31171"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/31171\/revisions"}],"predecessor-version":[{"id":44692,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/31171\/revisions\/44692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/31172"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=31171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=31171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=31171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}