{"id":325286,"date":"2024-06-01T09:24:41","date_gmt":"2024-06-01T08:24:41","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=44811"},"modified":"2025-03-07T18:28:20","modified_gmt":"2025-03-07T17:28:20","slug":"dia-del-arbol-en-benin","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/","title":{"rendered":"Journ\u00e9e de l'arbre au B\u00e9nin"},"content":{"rendered":"<p>Aujourd\u2019hui 1er Juin au B\u00e9nin en Afrique de l\u2019Ouest est c\u00e9l\u00e9br\u00e9e la journ\u00e9e de l\u2019arbre pour la protection et l\u2019entretien de l\u2019environnement. Les enfants du coll\u00e8ge piariste Saint Fautino Miguez de Za-Agbogbom\u00e8 ne sont rest\u00e9s insensibles. Il ont c\u00e9l\u00e9br\u00e9 cette journ\u00e9e en plantant quelques plantes dans l\u2019enceinte du coll\u00e8ge. Quelques photos.<\/p>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui 1er Juin au B\u00e9nin en Afrique de l\u2019Ouest est c\u00e9l\u00e9br\u00e9e la journ\u00e9e de l\u2019arbre pour la protection et l\u2019entretien de l\u2019environnement. Les enfants du coll\u00e8ge piariste Saint Fautino Miguez [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":325864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[446],"tags":[],"class_list":["post-325286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-del-oeste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journ\u00e9e de l&#039;arbre au B\u00e9nin<\/title>\n<meta name=\"description\" content=\"Aujourd\u2019hui 1er Juin au B\u00e9nin en Afrique de l\u2019Ouest est c\u00e9l\u00e9br\u00e9e la journ\u00e9e de l\u2019arbre pour la protection et l\u2019entretien de l\u2019environnement. Les enfants du coll\u00e8ge piariste Saint Fautino Miguez de Za-Agbogbom\u00e8 ne sont rest\u00e9s insensibles. Il ont c\u00e9l\u00e9br\u00e9 cette journ\u00e9e en plantant quelques plantes dans l\u2019enceinte du coll\u00e8ge. Quelques photos. &nbsp; [gallery ids=&quot;44821,44820,44819,44818,44817,44816,44815,44814,44813,44812&quot;]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Aujourd\u2019hui%201er%20Juin%20au%20B\u00e9nin%20en%20Afrique%20de%20l\u2019Ouest%20est%20c\u00e9l\u00e9br\u00e9e%20la%20journ\u00e9e%20de%20l\u2019arbre%20pour%20la%20protection%20et%20l\u2019entretien%20de%20l\u2019environnement.%20Les%20enfants%20du%20coll\u00e8ge%20piariste%20Saint%20Fautino%20Miguez%20de%20Za-Agbogbom\u00e8%20ne%20sont%20rest\u00e9s%20insensibles.%20Il%20ont%20c\u00e9l\u00e9br\u00e9%20cette%20journ\u00e9e%20en%20plantant%20quelques%20plantes%20dans%20l\u2019enceinte%20du%20coll\u00e8ge.%20Quelques%20photos.%20&nbsp;%20[gallery%20ids=44821,44820,44819,44818,44817,44816,44815,44814,44813,44812]\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journ\u00e9e de l&#039;arbre au B\u00e9nin\" \/>\n<meta property=\"og:description\" content=\"Aujourd\u2019hui 1er Juin au B\u00e9nin en Afrique de l\u2019Ouest est c\u00e9l\u00e9br\u00e9e la journ\u00e9e de l\u2019arbre pour la protection et l\u2019entretien de l\u2019environnement. Les enfants du coll\u00e8ge piariste Saint Fautino Miguez de Za-Agbogbom\u00e8 ne sont rest\u00e9s insensibles. Il ont c\u00e9l\u00e9br\u00e9 cette journ\u00e9e en plantant quelques plantes dans l\u2019enceinte du coll\u00e8ge. Quelques photos. &nbsp; [gallery ids=&quot;44821,44820,44819,44818,44817,44816,44815,44814,44813,44812&quot;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-01T08:24:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/IMG-20240601-WA0006-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administrador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrador\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/\"},\"author\":{\"name\":\"administrador\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/aaa10333558991c1d6ad358b7721fe71\"},\"headline\":\"Journ\u00e9e de l'arbre au B\u00e9nin\",\"datePublished\":\"2024-06-01T08:24:41+00:00\",\"dateModified\":\"2025-03-07T17:28:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/\"},\"wordCount\":61,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG-20240601-WA0006-1.jpg\",\"articleSection\":[\"Afrique de l'Ouest\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/\",\"name\":\"D\u00cdA DEL \u00c1RBOL EN BEN\u00cdN - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG-20240601-WA0006-1.jpg\",\"datePublished\":\"2024-06-01T08:24:41+00:00\",\"dateModified\":\"2025-03-07T17:28:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG-20240601-WA0006-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG-20240601-WA0006-1.jpg\",\"width\":1080,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2024\\\/06\\\/dia-del-arbol-en-benin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journ\u00e9e de l'arbre au B\u00e9nin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/aaa10333558991c1d6ad358b7721fe71\",\"name\":\"administrador\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/administrador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journ\u00e9e de l'arbre au B\u00e9nin","description":"Aujourd\u2019hui 1er Juin au B\u00e9nin en Afrique de l\u2019Ouest est c\u00e9l\u00e9br\u00e9e la journ\u00e9e de l\u2019arbre pour la protection et l\u2019entretien de l\u2019environnement. Les enfants du coll\u00e8ge piariste Saint Fautino Miguez de Za-Agbogbom\u00e8 ne sont rest\u00e9s insensibles. Il ont c\u00e9l\u00e9br\u00e9 cette journ\u00e9e en plantant quelques plantes dans l\u2019enceinte du coll\u00e8ge. Quelques photos. &nbsp; [gallery ids=\"44821,44820,44819,44818,44817,44816,44815,44814,44813,44812\"]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Aujourd\u2019hui 1er Juin au B\u00e9nin en Afrique de l\u2019Ouest est c\u00e9l\u00e9br\u00e9e la journ\u00e9e de l\u2019arbre pour la protection et l\u2019entretien de l\u2019environnement. Les enfants du coll\u00e8ge piariste Saint Fautino Miguez de Za-Agbogbom\u00e8 ne sont rest\u00e9s insensibles. Il ont c\u00e9l\u00e9br\u00e9 cette journ\u00e9e en plantant quelques plantes dans l\u2019enceinte du coll\u00e8ge. Quelques photos. &nbsp; [gallery ids=\"44821,44820,44819,44818,44817,44816,44815,44814,44813,44812\"]","og_locale":"fr_FR","og_type":"article","og_title":"Journ\u00e9e de l'arbre au B\u00e9nin","og_description":"Aujourd\u2019hui 1er Juin au B\u00e9nin en Afrique de l\u2019Ouest est c\u00e9l\u00e9br\u00e9e la journ\u00e9e de l\u2019arbre pour la protection et l\u2019entretien de l\u2019environnement. Les enfants du coll\u00e8ge piariste Saint Fautino Miguez de Za-Agbogbom\u00e8 ne sont rest\u00e9s insensibles. Il ont c\u00e9l\u00e9br\u00e9 cette journ\u00e9e en plantant quelques plantes dans l\u2019enceinte du coll\u00e8ge. Quelques photos. &nbsp; [gallery ids=\"44821,44820,44819,44818,44817,44816,44815,44814,44813,44812\"]","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/","og_site_name":"Itaka-Escolapios","article_published_time":"2024-06-01T08:24:41+00:00","article_modified_time":"2025-03-07T17:28:20+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/IMG-20240601-WA0006-1.jpg","type":"image\/jpeg"}],"author":"administrador","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administrador"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/"},"author":{"name":"administrador","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/aaa10333558991c1d6ad358b7721fe71"},"headline":"Journ\u00e9e de l'arbre au B\u00e9nin","datePublished":"2024-06-01T08:24:41+00:00","dateModified":"2025-03-07T17:28:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/"},"wordCount":61,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/IMG-20240601-WA0006-1.jpg","articleSection":["Afrique de l'Ouest"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/","name":"D\u00cdA DEL \u00c1RBOL EN BEN\u00cdN - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/IMG-20240601-WA0006-1.jpg","datePublished":"2024-06-01T08:24:41+00:00","dateModified":"2025-03-07T17:28:20+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/IMG-20240601-WA0006-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/06\/IMG-20240601-WA0006-1.jpg","width":1080,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2024\/06\/dia-del-arbol-en-benin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Journ\u00e9e de l'arbre au B\u00e9nin"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/aaa10333558991c1d6ad358b7721fe71","name":"administrador","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/administrador\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/325286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=325286"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/325286\/revisions"}],"predecessor-version":[{"id":326250,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/325286\/revisions\/326250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/325864"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=325286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=325286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=325286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}