{"id":42553,"date":"2023-06-12T10:49:15","date_gmt":"2023-06-12T09:49:15","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=42553"},"modified":"2023-11-28T12:35:31","modified_gmt":"2023-11-28T11:35:31","slug":"english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/","title":{"rendered":"Activit\u00e9s dans le cadre de la campagne de Solidarit\u00e9 \u00e0 Akurenam (Guin\u00e9e Equatoriale)"},"content":{"rendered":"<p>Depuis deux semaines une s\u00e9rie d&rsquo;activit\u00e9s sont organis\u00e9es \u00e0 Akurenam (Guin\u00e9e Equatoriale) dans le cadre de la campagne de solidarit\u00e9. Entre autre nous avons eu une semaine de vente de produits alimentaires,\u00a0 sensibilisation sur la salubrit\u00e9 et le maintien de l&rsquo;harmonie entre les diff\u00e9rentes composantes de notre ville: autres coll\u00e8ges de la ville, autorit\u00e9s administratives etc&#8230; samedi dernier 11 juin 2023 nous avons eu le lavage des voitures de la ville \u00ab\u00a0lavado solidario de coches\u00a0\u00bb. Nous comptons participer \u00e0 notre mani\u00e8re \u00e0 la campagne de cette ann\u00e9e.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-42554 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-10-at-10.43.18-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1152\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-10-at-10.43.18-scaled.jpeg 2000w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-10-at-10.43.18-300x135.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-10-at-10.43.18-1024x461.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-10-at-10.43.18-768x346.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-10-at-10.43.18-1536x691.jpeg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-10-at-10.43.18-2048x922.jpeg 2048w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-10-at-10.43.18-250x113.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-10-at-10.43.18-1080x486.jpeg 1080w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis deux semaines une s\u00e9rie d&rsquo;activit\u00e9s sont organis\u00e9es \u00e0 Akurenam (Guin\u00e9e Equatoriale) dans le cadre de la campagne de solidarit\u00e9. Entre autre nous avons eu une semaine de vente de [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":42555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,533],"tags":[],"class_list":["post-42553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-guinea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Activit\u00e9s dans le cadre de la campagne de Solidarit\u00e9 \u00e0 Akurenam (Guin\u00e9e Equatoriale)<\/title>\n<meta name=\"description\" content=\"Depuis deux semaines une s\u00e9rie d&#039;activit\u00e9s sont organis\u00e9es \u00e0 Akurenam (Guin\u00e9e Equatoriale) dans le cadre de la campagne de solidarit\u00e9. Entre autre nous avons eu une semaine de vente de produits alimentaires,\u00a0 sensibilisation sur la salubrit\u00e9 et le maintien de l&#039;harmonie entre les diff\u00e9rentes composantes de notre ville: autres coll\u00e8ges de la ville, autorit\u00e9s administratives\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Activit\u00e9s dans le cadre de la campagne de Solidarit\u00e9 \u00e0 Akurenam (Guin\u00e9e Equatoriale)\" \/>\n<meta property=\"og:description\" content=\"Depuis deux semaines une s\u00e9rie d&#039;activit\u00e9s sont organis\u00e9es \u00e0 Akurenam (Guin\u00e9e Equatoriale) dans le cadre de la campagne de solidarit\u00e9. Entre autre nous avons eu une semaine de vente de produits alimentaires,\u00a0 sensibilisation sur la salubrit\u00e9 et le maintien de l&#039;harmonie entre les diff\u00e9rentes composantes de notre ville: autres coll\u00e8ges de la ville, autorit\u00e9s administratives\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T09:49:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/voiture2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"Activit\u00e9s dans le cadre de la campagne de Solidarit\u00e9 \u00e0 Akurenam (Guin\u00e9e Equatoriale)\",\"datePublished\":\"2023-06-12T09:49:15+00:00\",\"dateModified\":\"2023-11-28T11:35:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/\"},\"wordCount\":110,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/voiture2.png\",\"articleSection\":[\"Afrique centrale\",\"Guinea\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/\",\"name\":\"ACTIVIDADES EN EL MARCO DE LA CAMPA\u00d1A DE SOLIDARIDAD EN AKURENAM - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/voiture2.png\",\"datePublished\":\"2023-06-12T09:49:15+00:00\",\"dateModified\":\"2023-11-28T11:35:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/voiture2.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/voiture2.png\",\"width\":1150,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/2023\\\/06\\\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activit\u00e9s dans le cadre de la campagne de Solidarit\u00e9 \u00e0 Akurenam (Guin\u00e9e Equatoriale)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/fr\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activit\u00e9s dans le cadre de la campagne de Solidarit\u00e9 \u00e0 Akurenam (Guin\u00e9e Equatoriale)","description":"Depuis deux semaines une s\u00e9rie d'activit\u00e9s sont organis\u00e9es \u00e0 Akurenam (Guin\u00e9e Equatoriale) dans le cadre de la campagne de solidarit\u00e9. Entre autre nous avons eu une semaine de vente de produits alimentaires,\u00a0 sensibilisation sur la salubrit\u00e9 et le maintien de l'harmonie entre les diff\u00e9rentes composantes de notre ville: autres coll\u00e8ges de la ville, autorit\u00e9s administratives\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Depuis deux semaines une s\u00e9rie d'activit\u00e9s sont organis\u00e9es \u00e0 Akurenam (Guin\u00e9e Equatoriale) dans le cadre de la campagne de solidarit\u00e9. Entre autre nous avons eu une semaine de vente de produits alimentaires,\u00a0 sensibilisation sur la salubrit\u00e9 et le maintien de l'harmonie entre les diff\u00e9rentes composantes de notre ville: autres coll\u00e8ges de la ville, autorit\u00e9s administratives\u2026","og_locale":"fr_FR","og_type":"article","og_title":"Activit\u00e9s dans le cadre de la campagne de Solidarit\u00e9 \u00e0 Akurenam (Guin\u00e9e Equatoriale)","og_description":"Depuis deux semaines une s\u00e9rie d'activit\u00e9s sont organis\u00e9es \u00e0 Akurenam (Guin\u00e9e Equatoriale) dans le cadre de la campagne de solidarit\u00e9. Entre autre nous avons eu une semaine de vente de produits alimentaires,\u00a0 sensibilisation sur la salubrit\u00e9 et le maintien de l'harmonie entre les diff\u00e9rentes composantes de notre ville: autres coll\u00e8ges de la ville, autorit\u00e9s administratives\u2026","og_url":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/","og_site_name":"Itaka-Escolapios","article_published_time":"2023-06-12T09:49:15+00:00","article_modified_time":"2023-11-28T11:35:31+00:00","og_image":[{"width":1150,"height":666,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/voiture2.png","type":"image\/png"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cameroun01"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"Activit\u00e9s dans le cadre de la campagne de Solidarit\u00e9 \u00e0 Akurenam (Guin\u00e9e Equatoriale)","datePublished":"2023-06-12T09:49:15+00:00","dateModified":"2023-11-28T11:35:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/"},"wordCount":110,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/voiture2.png","articleSection":["Afrique centrale","Guinea"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/","url":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/","name":"ACTIVIDADES EN EL MARCO DE LA CAMPA\u00d1A DE SOLIDARIDAD EN AKURENAM - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/voiture2.png","datePublished":"2023-06-12T09:49:15+00:00","dateModified":"2023-11-28T11:35:31+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/voiture2.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/06\/voiture2.png","width":1150,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/fr\/2023\/06\/english-activities-within-the-framework-of-the-solidarity-campaign-in-akurenam-equatorial-guinea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Activit\u00e9s dans le cadre de la campagne de Solidarit\u00e9 \u00e0 Akurenam (Guin\u00e9e Equatoriale)"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/fr\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/42553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/comments?post=42553"}],"version-history":[{"count":7,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/42553\/revisions"}],"predecessor-version":[{"id":43582,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/posts\/42553\/revisions\/43582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media\/42555"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/media?parent=42553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/categories?post=42553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/fr\/wp-json\/wp\/v2\/tags?post=42553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}