{"id":32677,"date":"2021-03-11T17:07:45","date_gmt":"2021-03-11T16:07:45","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?page_id=32677"},"modified":"2023-11-28T12:36:03","modified_gmt":"2023-11-28T11:36:03","slug":"regimen-fiscal-agencia-tributaria","status":"publish","type":"page","link":"https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/","title":{"rendered":"R\u00c9GIMEN FISCAL AGENCIA TRIBUTARIA"},"content":{"rendered":"<p>Descarga <strong><span style=\"color: #333300;\"><a style=\"color: #333300;\" href=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/03\/BOE-A-2002-25039.pdf\">la Ley 49\/2002<\/a><\/span><\/strong><\/p>\n<table width=\"294\">\n<tbody>\n<tr>\n<td width=\"214\">IRPF<\/td>\n<td width=\"80\"><\/td>\n<\/tr>\n<tr>\n<td width=\"214\">Primeros 150 \u20ac<\/td>\n<td width=\"80\">75%<\/td>\n<\/tr>\n<tr>\n<td width=\"214\">Resto<\/td>\n<td width=\"80\">30%<\/td>\n<\/tr>\n<tr>\n<td width=\"214\">Donaciones plurianuales (importe o valor igual o superior a la misma entidad durante al menos los dos ejercicios anteriores &gt;150 \u20ac)<\/td>\n<td width=\"80\">35%<\/td>\n<\/tr>\n<tr>\n<td width=\"214\">L\u00edmite deducci\u00f3n base liquidable<\/td>\n<td width=\"80\">10%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Descarga la Ley 49\/2002 IRPF Primeros 150 \u20ac 75% Resto 30% Donaciones plurianuales (importe o valor igual o superior a la misma entidad durante al menos los dos ejercicios anteriores [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-32677","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00c9GIMEN FISCAL AGENCIA TRIBUTARIA<\/title>\n<meta name=\"description\" content=\"Descarga la Ley 49\/2002 IRPF Primeros 150 \u20ac 75% Resto 30% Donaciones plurianuales (importe o valor igual o superior a la misma entidad durante al menos los dos ejercicios anteriores &gt;150 \u20ac) 35% L\u00edmite deducci\u00f3n base liquidable 10%\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00c9GIMEN FISCAL AGENCIA TRIBUTARIA\" \/>\n<meta property=\"og:description\" content=\"Descarga la Ley 49\/2002 IRPF Primeros 150 \u20ac 75% Resto 30% Donaciones plurianuales (importe o valor igual o superior a la misma entidad durante al menos los dos ejercicios anteriores &gt;150 \u20ac) 35% L\u00edmite deducci\u00f3n base liquidable 10%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/regimen-fiscal-agencia-tributaria\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/regimen-fiscal-agencia-tributaria\\\/\",\"name\":\"R\u00c9GIMEN FISCAL AGENCIA TRIBUTARIA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"datePublished\":\"2021-03-11T16:07:45+00:00\",\"dateModified\":\"2023-11-28T11:36:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/regimen-fiscal-agencia-tributaria\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/regimen-fiscal-agencia-tributaria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/regimen-fiscal-agencia-tributaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00c9GIMEN FISCAL AGENCIA TRIBUTARIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00c9GIMEN FISCAL AGENCIA TRIBUTARIA","description":"Descarga la Ley 49\/2002 IRPF Primeros 150 \u20ac 75% Resto 30% Donaciones plurianuales (importe o valor igual o superior a la misma entidad durante al menos los dos ejercicios anteriores &gt;150 \u20ac) 35% L\u00edmite deducci\u00f3n base liquidable 10%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/","og_locale":"pt_BR","og_type":"article","og_title":"R\u00c9GIMEN FISCAL AGENCIA TRIBUTARIA","og_description":"Descarga la Ley 49\/2002 IRPF Primeros 150 \u20ac 75% Resto 30% Donaciones plurianuales (importe o valor igual o superior a la misma entidad durante al menos los dos ejercicios anteriores &gt;150 \u20ac) 35% L\u00edmite deducci\u00f3n base liquidable 10%","og_url":"https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/","og_site_name":"Itaka-Escolapios","article_modified_time":"2023-11-28T11:36:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/","url":"https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/","name":"R\u00c9GIMEN FISCAL AGENCIA TRIBUTARIA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"datePublished":"2021-03-11T16:07:45+00:00","dateModified":"2023-11-28T11:36:03+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/regimen-fiscal-agencia-tributaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"R\u00c9GIMEN FISCAL AGENCIA TRIBUTARIA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/pages\/32677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=32677"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/pages\/32677\/revisions"}],"predecessor-version":[{"id":44363,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/pages\/32677\/revisions\/44363"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=32677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}