{"id":22431,"date":"2018-03-19T10:41:20","date_gmt":"2018-03-19T09:41:20","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=22431"},"modified":"2023-11-28T12:37:34","modified_gmt":"2023-11-28T11:37:34","slug":"itaka-el-significado-de-las-itacas","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/","title":{"rendered":"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS"},"content":{"rendered":"<p>LA HISTORIA DE ULISES<\/p>\n<p>la historia de Ulises y de su patria, \u00cdtaca es una historia fant\u00e1stica, llena de aventuras y de peligros que Homero retrat\u00f3 de forma tan fiel en &#8220;La Odisea&#8221;. Ulises, rey de \u00cdtaca. Cuando se produce la Guerra de Troya a consecuencia del rapto de la bella Helena, el rey Agamen\u00f3n convence a Ulises para que vaya a la guerra. Una vez producida la ca\u00edda de la m\u00edtica Troya con la historia del famoso caballo, Ulises comienza el periplo que habr\u00e1 de llevarle de vuelta a las playas de \u00cdtaca. Lo que \u00e9l no sabe entonces es que tardar\u00e1 en arribar a \u00cdtaca m\u00e1s de veinte a\u00f1os, en los cuales habr\u00e1 de recorrer las aguas de medio Mediterr\u00e1neo y vivir todo tipo de aventuras, buenas y malas, conocer nuevos territorios, nuevas gentes, la ira de los dioses y la obsesi\u00f3n por \u00e9l de alguna diosa, incluso el canto de las sirenas que hace que los hombre enloquezcan.<\/p>\n<p>Pero Ulises finalmente regresar\u00e1 a \u00cdtaca, tras un largu\u00edsimo viaje, lleno de aventuras y de experiencias, que nunca podr\u00e1 olvidar. En \u00cdtaca le esperan su esposa, la bella y paciente Pen\u00e9lope, y su hijo Tel\u00e9maco. Pen\u00e9lope ha esperado m\u00e1s de veinte a\u00f1os la llegada de Ulises y ni por un momento ha pensado que no regresar\u00eda; ante la presi\u00f3n de los numerosos pretendientes que quer\u00edan casarse con ella para conseguir el trono de \u00cdtaca, finalmente acepta casarse con uno de ellos cuando finalice la mortaja de su anciano padre, pero el mito cuenta que lo que tej\u00eda por el d\u00eda los destej\u00eda por la noche, ganando tiempo para el regreso de Ulises. Pen\u00e9lope y Tel\u00e9maco siguen teniendo el mismo amor por Ulises que ten\u00edan el d\u00eda que lo despidieron en una de las bah\u00edas de \u00cdtaca y nunca han pensado que no regresar\u00eda. Ulises al llegar a \u00cdtaca se disfraza durante un tiempo hasta recuperar por sus propios medios el trono de \u00cdtaca al enfrentarse a todos los pretendientes y vencerlos. Pen\u00e9lope reconocer\u00e1 en \u00e9l a su esposo y con ello esta historia tiene un final feliz.<\/p>\n<p>EL SIGNIFICADO DE \u00cdTACA<br \/>\nLa historia de Ulises puede ser en s\u00ed misma muy bonita, fant\u00e1stica, llena de aventuras, con todos los ingredientes necesarios para una gran novela, y tal es as\u00ed que\u00a0<span style=\"text-decoration: underline;\"><b>La Odisea<\/b><\/span>es sin duda una de las mejores novelas de todos los tiempo y una referencia bibliogr\u00e1fica imprescindible. Pero el verdadero significado de \u00cdtaca es algo mucho m\u00e1s \u00edntimo y sencillo, un esp\u00edritu que Kavafis, milenios despu\u00e9s de la historia de \u00cdtaca, supo reflejar perfectamente en el maravilloso poema que podr\u00e9is leer al final .<\/p>\n<p><b>\u00cdtaca es el camino, \u00cdtaca es la vida misma.\u00a0<\/b>La VIDA es lo mejor que tenemos y muchas veces la dejamos pasar sin pena ni gloria, permitimos que la rutina y los d\u00edas grises nos anulen y nos olvidamos de lo que verdaderamente tiene importancia. El concepto de \u00cdtaca encarna el concepto de la sabidur\u00eda, de lo que aprendemos a lo largo de nuestro camino y nuestra existencia, de lo que vamos acumulando poco a poco en la mochila de nuestras vivencias y nuestros recuerdos, aquello que siempre llevamos con nosotros mismos.<\/p>\n<p>Kavafis fue capaz de realizar un poema sencillamente precioso, porque hablar de la historia m\u00edtica de Ulises pero interpret\u00e1ndola desde el verdadero sentido de la vida. Sus palabras han traspasado milenios, de la Grecia antigua a nuestros d\u00edas, haciendo que ambos mundos se den la mano y se miren cara a cara. \u00a0Por eso la &#8220;Itaca&#8221; de Kavafis es una aut\u00e9ntica oda a la vida y a nosotros mismos. \u00a1\u00d3jala lo tengamos presente siempre. !!<\/p>\n<div><\/div>\n<p><i>\u00cdtaca<\/i><br \/>\n<i><br \/>\n<\/i><i>Constantino Cavafis<\/i><br \/>\n<i><br \/>\n<\/i><i>Cuando te encuentres de camino a \u00cdtaca,\u00a0<\/i><br \/>\n<i>desea que sea largo el camino,\u00a0<\/i><br \/>\n<i>lleno de aventuras, lleno de conocimientos.\u00a0<\/i><br \/>\n<i>A los Lestrigones y a los C\u00edclopes,\u00a0<\/i><br \/>\n<i>al enojado Poseid\u00f3n no temas,<\/i><br \/>\n<i>tales en tu camino nunca encontrar\u00e1s,\u00a0<\/i><br \/>\n<i>si mantienes tu pensamiento elevado, y selecta\u00a0<\/i><br \/>\n<i>emoci\u00f3n tu esp\u00edritu y tu cuerpo tienta.\u00a0<\/i><br \/>\n<i>A los Lestrigones y a los C\u00edclopes,<\/i><br \/>\n<i>al fiero Poseid\u00f3n no encontrar\u00e1s,\u00a0<\/i><br \/>\n<i>si no los llevas dentro de tu alma,\u00a0<\/i><br \/>\n<i>si tu alma no los coloca ante ti.<\/i><br \/>\n<i><br \/>\n<\/i><i>Desea que sea largo el camino.\u00a0<\/i><br \/>\n<i>Que sean muchas las ma\u00f1anas estivales\u00a0<\/i><br \/>\n<i>en que con qu\u00e9 alegr\u00eda, con qu\u00e9 gozo\u00a0<\/i><br \/>\n<i>arribes a puertos nunca antes vistos,\u00a0<\/i><br \/>\n<i>det\u00e9nte en los emporios fenicios,\u00a0<\/i><br \/>\n<i>y adquiere mercanc\u00edas preciosas,\u00a0<\/i><br \/>\n<i>n\u00e1cares y corales, \u00e1mbar y \u00e9bano,\u00a0<\/i><br \/>\n<i>y perfumes sensuales de todo tipo,\u00a0<\/i><br \/>\n<i>cu\u00e1ntos m\u00e1s perfumes sensuales puedas,\u00a0<\/i><br \/>\n<i>ve a ciudades de Egipto, a muchas,\u00a0<\/i><br \/>\n<i>aprende y aprende de los instruidos.<\/i><br \/>\n<i><br \/>\n<\/i><i>Ten siempre en tu mente a \u00cdtaca.\u00a0<\/i><br \/>\n<i>La llegada all\u00ed es tu destino.\u00a0<\/i><br \/>\n<i>Pero no apresures tu viaje en absoluto.\u00a0<\/i><br \/>\n<i>Mejor que dure muchos a\u00f1os,\u00a0<\/i><br \/>\n<i>y ya anciano recales en la isla,\u00a0<\/i><br \/>\n<i>rico con cuanto ganaste en el camino,\u00a0<\/i><br \/>\n<i>sin esperar que te d\u00e9 riquezas \u00cdtaca.<\/i><br \/>\n<i><br \/>\n<\/i><i>\u00cdtaca te dio el bello viaje.\u00a0<\/i><br \/>\n<i>Sin ella no habr\u00edas emprendido el camino.\u00a0<\/i><br \/>\n<i>Pero no tiene m\u00e1s que darte.<\/i><br \/>\n<i><br \/>\n<\/i><i>Y si pobre la encuentras, \u00cdtaca no te enga\u00f1\u00f3.\u00a0<\/i><br \/>\n<i>As\u00ed sabio como te hiciste, con tanta experiencia,<\/i><br \/>\n<i><b>comprender\u00e1s ya qu\u00e9 significan las \u00cdtacas.<\/b><\/i><br \/>\n<i><b><br \/>\n<\/b><\/i>Aqu\u00ed os lo dejo en boca de Ismael Serrano:\u00a0<a href=\"https:\/\/www.youtube.com\/watch?time_continue=91&amp;v=8uIknlFeLZ4\">https:\/\/www.youtube.com\/watch?time_continue=91&amp;v=8uIknlFeLZ4<\/a><\/p>\n<p>Tomado de <a href=\"https:\/\/www.youtube.com\/watch?time_continue=91&amp;v=8uIknlFeLZ4\">http:\/\/clasesmarian.blogspot.com.br\/2015\/09\/itaca-cada-uno-busca-su-itaca-el.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA HISTORIA DE ULISES la historia de Ulises y de su patria, \u00cdtaca es una historia fant\u00e1stica, llena de aventuras y de peligros que Homero retrat\u00f3 de forma tan fiel [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-22431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS<\/title>\n<meta name=\"description\" content=\"LA HISTORIA DE ULISES la historia de Ulises y de su patria, \u00cdtaca es una historia fant\u00e1stica, llena de aventuras y de peligros que Homero retrat\u00f3 de forma tan fiel en &quot;La Odisea&quot;. Ulises, rey de \u00cdtaca. Cuando se produce la Guerra de Troya a consecuencia del rapto de la bella Helena, el rey Agamen\u00f3n&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/LA%20HISTORIA%20DE%20ULISES%20la%20historia%20de%20Ulises%20y%20de%20su%20patria,%20\u00cdtaca%20es%20una%20historia%20fant\u00e1stica,%20llena%20de%20aventuras%20y%20de%20peligros%20que%20Homero%20retrat\u00f3%20de%20forma%20tan%20fiel%20en%20La%20Odisea.%20Ulises,%20rey%20de%20\u00cdtaca.%20Cuando%20se%20produce%20la%20Guerra%20de%20Troya%20a%20consecuencia%20del%20rapto%20de%20la%20bella%20Helena,%20el%20rey%20Agamen\u00f3n&hellip;\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS\" \/>\n<meta property=\"og:description\" content=\"LA HISTORIA DE ULISES la historia de Ulises y de su patria, \u00cdtaca es una historia fant\u00e1stica, llena de aventuras y de peligros que Homero retrat\u00f3 de forma tan fiel en &quot;La Odisea&quot;. Ulises, rey de \u00cdtaca. Cuando se produce la Guerra de Troya a consecuencia del rapto de la bella Helena, el rey Agamen\u00f3n&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-19T09:41:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:37:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/03\/1itakas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"605\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS\",\"datePublished\":\"2018-03-19T09:41:20+00:00\",\"dateModified\":\"2023-11-28T11:37:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/\"},\"wordCount\":929,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/1itakas.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/\",\"name\":\"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/1itakas.jpg\",\"datePublished\":\"2018-03-19T09:41:20+00:00\",\"dateModified\":\"2023-11-28T11:37:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/1itakas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/1itakas.jpg\",\"width\":500,\"height\":605},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/03\\\/itaka-el-significado-de-las-itacas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS","description":"LA HISTORIA DE ULISES la historia de Ulises y de su patria, \u00cdtaca es una historia fant\u00e1stica, llena de aventuras y de peligros que Homero retrat\u00f3 de forma tan fiel en \"La Odisea\". Ulises, rey de \u00cdtaca. Cuando se produce la Guerra de Troya a consecuencia del rapto de la bella Helena, el rey Agamen\u00f3n&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"LA HISTORIA DE ULISES la historia de Ulises y de su patria, \u00cdtaca es una historia fant\u00e1stica, llena de aventuras y de peligros que Homero retrat\u00f3 de forma tan fiel en \"La Odisea\". Ulises, rey de \u00cdtaca. Cuando se produce la Guerra de Troya a consecuencia del rapto de la bella Helena, el rey Agamen\u00f3n&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS","og_description":"LA HISTORIA DE ULISES la historia de Ulises y de su patria, \u00cdtaca es una historia fant\u00e1stica, llena de aventuras y de peligros que Homero retrat\u00f3 de forma tan fiel en \"La Odisea\". Ulises, rey de \u00cdtaca. Cuando se produce la Guerra de Troya a consecuencia del rapto de la bella Helena, el rey Agamen\u00f3n&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/","og_site_name":"Itaka-Escolapios","article_published_time":"2018-03-19T09:41:20+00:00","article_modified_time":"2023-11-28T11:37:34+00:00","og_image":[{"width":500,"height":605,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/03\/1itakas.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS","datePublished":"2018-03-19T09:41:20+00:00","dateModified":"2023-11-28T11:37:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/"},"wordCount":929,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/03\/1itakas.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/","name":"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/03\/1itakas.jpg","datePublished":"2018-03-19T09:41:20+00:00","dateModified":"2023-11-28T11:37:34+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/03\/1itakas.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/03\/1itakas.jpg","width":500,"height":605},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/03\/itaka-el-significado-de-las-itacas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA: EL SIGNIFICADO DE LAS \u00cdTACAS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/22431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=22431"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/22431\/revisions"}],"predecessor-version":[{"id":46914,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/22431\/revisions\/46914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/22432"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=22431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=22431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=22431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}