{"id":26049,"date":"2018-12-11T10:47:02","date_gmt":"2018-12-11T09:47:02","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=26049"},"modified":"2023-11-28T12:37:05","modified_gmt":"2023-11-28T11:37:05","slug":"colonias-de-verano-en-senegal-y-costa-de-marfil-2018","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/","title":{"rendered":"Colonias de verano en Senegal y Costa de Marfil"},"content":{"rendered":"<p>Una vez m\u00e1s, las Escuelas Pias de \u00c1frica del Oeste organizaron sus colonias de verano para ni\u00f1os y ni\u00f1as de Senegal y Costa de Marfil. M\u00e1s de 1000 j\u00f3venes asistieron a las colonias, 800 de ellos en situaci\u00f3n precaria.<\/p>\n<p>Adjuntamos la <a href=\"https:\/\/issuu.com\/ecolespiesafriqueouest\/docs\/rapport_colonies_de_vacances_2018\" target=\"_blank\" rel=\"noopener\">memoria de las actividades realizadas (en franc\u00e9s)<\/a> que se acaba de publicar.<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una vez m\u00e1s, las Escuelas Pias de \u00c1frica del Oeste organizaron sus colonias de verano para ni\u00f1os y ni\u00f1as de Senegal y Costa de Marfil. M\u00e1s de 1000 j\u00f3venes asistieron [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":26050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[282],"tags":[364,365,360,361,362,363,431],"class_list":["post-26049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senegal","tag-africa-del-oeste","tag-afrique-de-louest","tag-colonias-de-verano","tag-colonies-de-vacances","tag-costa-de-marfil","tag-cote-divoire","tag-senegal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colonias de verano en Senegal y Costa de Marfil<\/title>\n<meta name=\"description\" content=\"Una vez m\u00e1s, las Escuelas Pias de \u00c1frica del Oeste organizaron sus colonias de verano para ni\u00f1os y ni\u00f1as de Senegal y Costa de Marfil. M\u00e1s de 1000 j\u00f3venes asistieron a las colonias, 800 de ellos en situaci\u00f3n precaria. Adjuntamos la memoria de las actividades realizadas (en franc\u00e9s) que se acaba de publicar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Una%20vez%20m\u00e1s,%20las%20Escuelas%20Pias%20de%20\u00c1frica%20del%20Oeste%20organizaron%20sus%20colonias%20de%20verano%20para%20ni\u00f1os%20y%20ni\u00f1as%20de%20Senegal%20y%20Costa%20de%20Marfil.%20M\u00e1s%20de%201000%20j\u00f3venes%20asistieron%20a%20las%20colonias,%20800%20de%20ellos%20en%20situaci\u00f3n%20precaria.%20Adjuntamos%20la%20memoria%20de%20las%20actividades%20realizadas%20(en%20franc\u00e9s)%20que%20se%20acaba%20de%20publicar.\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colonias de verano en Senegal y Costa de Marfil\" \/>\n<meta property=\"og:description\" content=\"Una vez m\u00e1s, las Escuelas Pias de \u00c1frica del Oeste organizaron sus colonias de verano para ni\u00f1os y ni\u00f1as de Senegal y Costa de Marfil. M\u00e1s de 1000 j\u00f3venes asistieron a las colonias, 800 de ellos en situaci\u00f3n precaria. Adjuntamos la memoria de las actividades realizadas (en franc\u00e9s) que se acaba de publicar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-11T09:47:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/12\/Captura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1123\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"Colonias de verano en Senegal y Costa de Marfil\",\"datePublished\":\"2018-12-11T09:47:02+00:00\",\"dateModified\":\"2023-11-28T11:37:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/\"},\"wordCount\":67,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Captura.png\",\"keywords\":[\"Africa del Oeste\",\"Afrique de l'Ouest\",\"Colonias de verano\",\"Colonies de vacances\",\"Costa de Marfil\",\"C\u00f4te d'Ivoire\",\"Senegal\"],\"articleSection\":[\"Senegal\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/\",\"name\":\"Colonias de verano en Senegal y Costa de Marfil - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Captura.png\",\"datePublished\":\"2018-12-11T09:47:02+00:00\",\"dateModified\":\"2023-11-28T11:37:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Captura.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Captura.png\",\"width\":1123,\"height\":867},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2018\\\/12\\\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colonias de verano en Senegal y Costa de Marfil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colonias de verano en Senegal y Costa de Marfil","description":"Una vez m\u00e1s, las Escuelas Pias de \u00c1frica del Oeste organizaron sus colonias de verano para ni\u00f1os y ni\u00f1as de Senegal y Costa de Marfil. M\u00e1s de 1000 j\u00f3venes asistieron a las colonias, 800 de ellos en situaci\u00f3n precaria. Adjuntamos la memoria de las actividades realizadas (en franc\u00e9s) que se acaba de publicar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Una vez m\u00e1s, las Escuelas Pias de \u00c1frica del Oeste organizaron sus colonias de verano para ni\u00f1os y ni\u00f1as de Senegal y Costa de Marfil. M\u00e1s de 1000 j\u00f3venes asistieron a las colonias, 800 de ellos en situaci\u00f3n precaria. Adjuntamos la memoria de las actividades realizadas (en franc\u00e9s) que se acaba de publicar.","og_locale":"pt_BR","og_type":"article","og_title":"Colonias de verano en Senegal y Costa de Marfil","og_description":"Una vez m\u00e1s, las Escuelas Pias de \u00c1frica del Oeste organizaron sus colonias de verano para ni\u00f1os y ni\u00f1as de Senegal y Costa de Marfil. M\u00e1s de 1000 j\u00f3venes asistieron a las colonias, 800 de ellos en situaci\u00f3n precaria. Adjuntamos la memoria de las actividades realizadas (en franc\u00e9s) que se acaba de publicar.","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/","og_site_name":"Itaka-Escolapios","article_published_time":"2018-12-11T09:47:02+00:00","article_modified_time":"2023-11-28T11:37:05+00:00","og_image":[{"width":1123,"height":867,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/12\/Captura.png","type":"image\/png"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itakaescolapios"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"Colonias de verano en Senegal y Costa de Marfil","datePublished":"2018-12-11T09:47:02+00:00","dateModified":"2023-11-28T11:37:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/"},"wordCount":67,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/12\/Captura.png","keywords":["Africa del Oeste","Afrique de l'Ouest","Colonias de verano","Colonies de vacances","Costa de Marfil","C\u00f4te d'Ivoire","Senegal"],"articleSection":["Senegal"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/","name":"Colonias de verano en Senegal y Costa de Marfil - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/12\/Captura.png","datePublished":"2018-12-11T09:47:02+00:00","dateModified":"2023-11-28T11:37:05+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/12\/Captura.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2018\/12\/Captura.png","width":1123,"height":867},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2018\/12\/colonias-de-verano-en-senegal-y-costa-de-marfil-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Colonias de verano en Senegal y Costa de Marfil"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/26049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=26049"}],"version-history":[{"count":7,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/26049\/revisions"}],"predecessor-version":[{"id":46068,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/26049\/revisions\/46068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/26050"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=26049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=26049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=26049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}