{"id":28103,"date":"2019-08-15T12:46:26","date_gmt":"2019-08-15T11:46:26","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28103"},"modified":"2023-11-28T12:36:45","modified_gmt":"2023-11-28T11:36:45","slug":"itaka-escolapios-escuela-de-voluntariado","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/","title":{"rendered":"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO"},"content":{"rendered":"<p>Nuestra Red es una escuela de voluntariado, no solo porque tiene en su seno cientos de voluntarios de muchos pa\u00edses del mundo, sino tambi\u00e9n porque ense\u00f1a siempre el valor de la gratuidad y el servicio, porque sensibiliza ante las necesidades de millones de personas, porque muestra caminos de solidaridad para todas las edades, porque tiene referencias de personas y grupos concretos que viven felices desde su compromiso voluntario, porque es signo de una nueva humanidad donde el m\u00e1ximo valor es cada persona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Red es una escuela de voluntariado, no solo porque tiene en su seno cientos de voluntarios de muchos pa\u00edses del mundo, sino tambi\u00e9n porque ense\u00f1a siempre el valor de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO<\/title>\n<meta name=\"description\" content=\"Nuestra Red es una escuela de voluntariado, no solo porque tiene en su seno cientos de voluntarios de muchos pa\u00edses del mundo, sino tambi\u00e9n porque ense\u00f1a siempre el valor de la gratuidad y el servicio, porque sensibiliza ante las necesidades de millones de personas, porque muestra caminos de solidaridad para todas las edades, porque tiene&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO\" \/>\n<meta property=\"og:description\" content=\"Nuestra Red es una escuela de voluntariado, no solo porque tiene en su seno cientos de voluntarios de muchos pa\u00edses del mundo, sino tambi\u00e9n porque ense\u00f1a siempre el valor de la gratuidad y el servicio, porque sensibiliza ante las necesidades de millones de personas, porque muestra caminos de solidaridad para todas las edades, porque tiene&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-15T11:46:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1Escuelavoluntariado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"260\" \/>\n\t<meta property=\"og:image:height\" content=\"260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO\",\"datePublished\":\"2019-08-15T11:46:26+00:00\",\"dateModified\":\"2023-11-28T11:36:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1Escuelavoluntariado.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1Escuelavoluntariado.jpg\",\"datePublished\":\"2019-08-15T11:46:26+00:00\",\"dateModified\":\"2023-11-28T11:36:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1Escuelavoluntariado.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/1Escuelavoluntariado.jpg\",\"width\":260,\"height\":260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/08\\\/itaka-escolapios-escuela-de-voluntariado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO","description":"Nuestra Red es una escuela de voluntariado, no solo porque tiene en su seno cientos de voluntarios de muchos pa\u00edses del mundo, sino tambi\u00e9n porque ense\u00f1a siempre el valor de la gratuidad y el servicio, porque sensibiliza ante las necesidades de millones de personas, porque muestra caminos de solidaridad para todas las edades, porque tiene&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/","og_locale":"pt_BR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO","og_description":"Nuestra Red es una escuela de voluntariado, no solo porque tiene en su seno cientos de voluntarios de muchos pa\u00edses del mundo, sino tambi\u00e9n porque ense\u00f1a siempre el valor de la gratuidad y el servicio, porque sensibiliza ante las necesidades de millones de personas, porque muestra caminos de solidaridad para todas las edades, porque tiene&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-08-15T11:46:26+00:00","article_modified_time":"2023-11-28T11:36:45+00:00","og_image":[{"width":260,"height":260,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1Escuelavoluntariado.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO","datePublished":"2019-08-15T11:46:26+00:00","dateModified":"2023-11-28T11:36:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/"},"wordCount":92,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1Escuelavoluntariado.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/","name":"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1Escuelavoluntariado.jpg","datePublished":"2019-08-15T11:46:26+00:00","dateModified":"2023-11-28T11:36:45+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1Escuelavoluntariado.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/08\/1Escuelavoluntariado.jpg","width":260,"height":260},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/08\/itaka-escolapios-escuela-de-voluntariado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... ESCUELA DE VOLUNTARIADO"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/28103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=28103"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/28103\/revisions"}],"predecessor-version":[{"id":45533,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/28103\/revisions\/45533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/28104"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=28103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=28103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=28103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}