{"id":28562,"date":"2019-10-19T23:19:05","date_gmt":"2019-10-19T22:19:05","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=28562"},"modified":"2023-11-28T12:36:41","modified_gmt":"2023-11-28T11:36:41","slug":"itaka-escolapios-siempre-de-fondo","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/","title":{"rendered":"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO"},"content":{"rendered":"<p>Muchas veces Itaka &#8211; Escolapios est\u00e1 en el fondo de muchos proyectos, actividades, planes, presencias, intuiciones&#8230; y apenas aparece visiblemente.<\/p>\n<p>Muchas veces Itaka &#8211; Escolapios es el horizonte que est\u00e1 al fondo marcando los siguientes pasos aun sin saber claramente hasta d\u00f3nde nos llevar\u00e1.<\/p>\n<p>Muchas veces Itaka &#8211; Escolapios nos lleva al fondo de nuestras opciones m\u00e1s profundas y comunitarias para hacerlas m\u00e1s libres, m\u00e1s humanizadoras, m\u00e1s convocantes, m\u00e1s&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchas veces Itaka &#8211; Escolapios est\u00e1 en el fondo de muchos proyectos, actividades, planes, presencias, intuiciones&#8230; y apenas aparece visiblemente. Muchas veces Itaka &#8211; Escolapios es el horizonte que est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-28562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO<\/title>\n<meta name=\"description\" content=\"Muchas veces Itaka - Escolapios est\u00e1 en el fondo de muchos proyectos, actividades, planes, presencias, intuiciones... y apenas aparece visiblemente. Muchas veces Itaka - Escolapios es el horizonte que est\u00e1 al fondo marcando los siguientes pasos aun sin saber claramente hasta d\u00f3nde nos llevar\u00e1. Muchas veces Itaka - Escolapios nos lleva al fondo de nuestras&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO\" \/>\n<meta property=\"og:description\" content=\"Muchas veces Itaka - Escolapios est\u00e1 en el fondo de muchos proyectos, actividades, planes, presencias, intuiciones... y apenas aparece visiblemente. Muchas veces Itaka - Escolapios es el horizonte que est\u00e1 al fondo marcando los siguientes pasos aun sin saber claramente hasta d\u00f3nde nos llevar\u00e1. Muchas veces Itaka - Escolapios nos lleva al fondo de nuestras&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-19T22:19:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1alfono.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"298\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO\",\"datePublished\":\"2019-10-19T22:19:05+00:00\",\"dateModified\":\"2023-11-28T11:36:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/\"},\"wordCount\":81,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1alfono.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1alfono.jpg\",\"datePublished\":\"2019-10-19T22:19:05+00:00\",\"dateModified\":\"2023-11-28T11:36:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1alfono.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/1alfono.jpg\",\"width\":450,\"height\":298},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2019\\\/10\\\/itaka-escolapios-siempre-de-fondo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO","description":"Muchas veces Itaka - Escolapios est\u00e1 en el fondo de muchos proyectos, actividades, planes, presencias, intuiciones... y apenas aparece visiblemente. Muchas veces Itaka - Escolapios es el horizonte que est\u00e1 al fondo marcando los siguientes pasos aun sin saber claramente hasta d\u00f3nde nos llevar\u00e1. Muchas veces Itaka - Escolapios nos lleva al fondo de nuestras&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/","og_locale":"pt_BR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO","og_description":"Muchas veces Itaka - Escolapios est\u00e1 en el fondo de muchos proyectos, actividades, planes, presencias, intuiciones... y apenas aparece visiblemente. Muchas veces Itaka - Escolapios es el horizonte que est\u00e1 al fondo marcando los siguientes pasos aun sin saber claramente hasta d\u00f3nde nos llevar\u00e1. Muchas veces Itaka - Escolapios nos lleva al fondo de nuestras&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/","og_site_name":"Itaka-Escolapios","article_published_time":"2019-10-19T22:19:05+00:00","article_modified_time":"2023-11-28T11:36:41+00:00","og_image":[{"width":450,"height":298,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1alfono.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO","datePublished":"2019-10-19T22:19:05+00:00","dateModified":"2023-11-28T11:36:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/"},"wordCount":81,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1alfono.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/","name":"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1alfono.jpg","datePublished":"2019-10-19T22:19:05+00:00","dateModified":"2023-11-28T11:36:41+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1alfono.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2019\/10\/1alfono.jpg","width":450,"height":298},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2019\/10\/itaka-escolapios-siempre-de-fondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... SIEMPRE DE FONDO"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/28562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=28562"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/28562\/revisions"}],"predecessor-version":[{"id":45419,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/28562\/revisions\/45419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/28563"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=28562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=28562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=28562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}