{"id":29787,"date":"2020-01-20T09:58:12","date_gmt":"2020-01-20T08:58:12","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29787"},"modified":"2023-11-28T12:36:31","modified_gmt":"2023-11-28T11:36:31","slug":"arbol-de-navidad-en-africa-del-oeste","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/","title":{"rendered":"\u00c1rbol de Navidad en \u00c1frica del Oeste"},"content":{"rendered":"<p>El &#8220;\u00c1rbol de Navidad&#8221; es una actividad que se realiza en los lugares donde los escolapios est\u00e1n presentes en la Provincia de \u00c1frica del Oeste (escuelas, parroquias y casas de formaci\u00f3n), que tiene como objetivo compartir la alegr\u00eda de la Navidad con todos los ni\u00f1os y ni\u00f1as, preferentemente con aquellos que provienen de familias o de entornos modestos. Este a\u00f1o tuvo lugar entre el 20 y el 29 de diciembre, en torno a los temas de la compasi\u00f3n y la generosidad, y se celebr\u00f3 en las presencias escolapias en Senegal y Costa de Marfil.<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-29787 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/arbre-de-noel-itaka-2019-2\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019-90x90.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>El &#8220;\u00c1rbol de Navidad&#8221; es una actividad que se realiza en los lugares donde los escolapios est\u00e1n presentes en la Provincia de \u00c1frica del Oeste (escuelas, parroquias y casas de [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":29789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[282],"tags":[362,76,431],"class_list":["post-29787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senegal","tag-costa-de-marfil","tag-navidad","tag-senegal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c1rbol de Navidad en \u00c1frica del Oeste<\/title>\n<meta name=\"description\" content=\"El &quot;\u00c1rbol de Navidad&quot; es una actividad que se realiza en los lugares donde los escolapios est\u00e1n presentes en la Provincia de \u00c1frica del Oeste (escuelas, parroquias y casas de formaci\u00f3n), que tiene como objetivo compartir la alegr\u00eda de la Navidad con todos los ni\u00f1os y ni\u00f1as, preferentemente con aquellos que provienen de familias o&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/El%20\u00c1rbol%20de%20Navidad%20es%20una%20actividad%20que%20se%20realiza%20en%20los%20lugares%20donde%20los%20escolapios%20est\u00e1n%20presentes%20en%20la%20Provincia%20de%20\u00c1frica%20del%20Oeste%20(escuelas,%20parroquias%20y%20casas%20de%20formaci\u00f3n),%20que%20tiene%20como%20objetivo%20compartir%20la%20alegr\u00eda%20de%20la%20Navidad%20con%20todos%20los%20ni\u00f1os%20y%20ni\u00f1as,%20preferentemente%20con%20aquellos%20que%20provienen%20de%20familias%20o&hellip;\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c1rbol de Navidad en \u00c1frica del Oeste\" \/>\n<meta property=\"og:description\" content=\"El &quot;\u00c1rbol de Navidad&quot; es una actividad que se realiza en los lugares donde los escolapios est\u00e1n presentes en la Provincia de \u00c1frica del Oeste (escuelas, parroquias y casas de formaci\u00f3n), que tiene como objetivo compartir la alegr\u00eda de la Navidad con todos los ni\u00f1os y ni\u00f1as, preferentemente con aquellos que provienen de familias o&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-20T08:58:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png\" \/>\n\t<meta property=\"og:image:width\" content=\"398\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"\u00c1rbol de Navidad en \u00c1frica del Oeste\",\"datePublished\":\"2020-01-20T08:58:12+00:00\",\"dateModified\":\"2023-11-28T11:36:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\"},\"wordCount\":108,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/arbre-de-No\u00ebl-Itaka-2019.png\",\"keywords\":[\"Costa de Marfil\",\"Navidad\",\"Senegal\"],\"articleSection\":[\"Senegal\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\",\"name\":\"\u00c1rbol de Navidad en \u00c1frica del Oeste - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/arbre-de-No\u00ebl-Itaka-2019.png\",\"datePublished\":\"2020-01-20T08:58:12+00:00\",\"dateModified\":\"2023-11-28T11:36:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/arbre-de-No\u00ebl-Itaka-2019.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/arbre-de-No\u00ebl-Itaka-2019.png\",\"width\":398,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/arbol-de-navidad-en-africa-del-oeste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c1rbol de Navidad en \u00c1frica del Oeste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c1rbol de Navidad en \u00c1frica del Oeste","description":"El \"\u00c1rbol de Navidad\" es una actividad que se realiza en los lugares donde los escolapios est\u00e1n presentes en la Provincia de \u00c1frica del Oeste (escuelas, parroquias y casas de formaci\u00f3n), que tiene como objetivo compartir la alegr\u00eda de la Navidad con todos los ni\u00f1os y ni\u00f1as, preferentemente con aquellos que provienen de familias o&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"El \"\u00c1rbol de Navidad\" es una actividad que se realiza en los lugares donde los escolapios est\u00e1n presentes en la Provincia de \u00c1frica del Oeste (escuelas, parroquias y casas de formaci\u00f3n), que tiene como objetivo compartir la alegr\u00eda de la Navidad con todos los ni\u00f1os y ni\u00f1as, preferentemente con aquellos que provienen de familias o&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"\u00c1rbol de Navidad en \u00c1frica del Oeste","og_description":"El \"\u00c1rbol de Navidad\" es una actividad que se realiza en los lugares donde los escolapios est\u00e1n presentes en la Provincia de \u00c1frica del Oeste (escuelas, parroquias y casas de formaci\u00f3n), que tiene como objetivo compartir la alegr\u00eda de la Navidad con todos los ni\u00f1os y ni\u00f1as, preferentemente con aquellos que provienen de familias o&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-01-20T08:58:12+00:00","article_modified_time":"2023-11-28T11:36:31+00:00","og_image":[{"width":398,"height":1500,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","type":"image\/png"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itakaescolapios","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"\u00c1rbol de Navidad en \u00c1frica del Oeste","datePublished":"2020-01-20T08:58:12+00:00","dateModified":"2023-11-28T11:36:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/"},"wordCount":108,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","keywords":["Costa de Marfil","Navidad","Senegal"],"articleSection":["Senegal"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/","name":"\u00c1rbol de Navidad en \u00c1frica del Oeste - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","datePublished":"2020-01-20T08:58:12+00:00","dateModified":"2023-11-28T11:36:31+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/arbre-de-No\u00ebl-Itaka-2019.png","width":398,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/arbol-de-navidad-en-africa-del-oeste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00c1rbol de Navidad en \u00c1frica del Oeste"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/29787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=29787"}],"version-history":[{"count":11,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/29787\/revisions"}],"predecessor-version":[{"id":45146,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/29787\/revisions\/45146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/29789"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=29787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=29787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=29787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}