{"id":29800,"date":"2020-01-21T13:25:24","date_gmt":"2020-01-21T12:25:24","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=29800"},"modified":"2023-11-28T12:36:31","modified_gmt":"2023-11-28T11:36:31","slug":"itaka-escolapios-adelante-siempre","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/","title":{"rendered":"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE"},"content":{"rendered":"<p>Hay momentos, situaciones, desaf\u00edos, que parecen invencibles&#8230; pero desde nuestra Red internacional Itaka &#8211; Escolapios sabemos muy bien que despu\u00e9s de la tempestad viene la calma, que lo importante es seguir navegando con los ojos puestos en la meta, que juntos podemos vencer las tormentas, que la belleza del viaje supone tambi\u00e9n superarse&#8230; \u00a1Es maravilloso viajar en Itaka &#8211; Escolapios viendo que los frutos van llegando y que merece la pena!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay momentos, situaciones, desaf\u00edos, que parecen invencibles&#8230; pero desde nuestra Red internacional Itaka &#8211; Escolapios sabemos muy bien que despu\u00e9s de la tempestad viene la calma, que lo importante es [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-29800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE<\/title>\n<meta name=\"description\" content=\"Hay momentos, situaciones, desaf\u00edos, que parecen invencibles... pero desde nuestra Red internacional Itaka - Escolapios sabemos muy bien que despu\u00e9s de la tempestad viene la calma, que lo importante es seguir navegando con los ojos puestos en la meta, que juntos podemos vencer las tormentas, que la belleza del viaje supone tambi\u00e9n superarse... \u00a1Es maravilloso&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE\" \/>\n<meta property=\"og:description\" content=\"Hay momentos, situaciones, desaf\u00edos, que parecen invencibles... pero desde nuestra Red internacional Itaka - Escolapios sabemos muy bien que despu\u00e9s de la tempestad viene la calma, que lo importante es seguir navegando con los ojos puestos en la meta, que juntos podemos vencer las tormentas, que la belleza del viaje supone tambi\u00e9n superarse... \u00a1Es maravilloso&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-21T12:25:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1tormenta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"333\" \/>\n\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE\",\"datePublished\":\"2020-01-21T12:25:24+00:00\",\"dateModified\":\"2023-11-28T11:36:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/\"},\"wordCount\":79,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1tormenta.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1tormenta.jpg\",\"datePublished\":\"2020-01-21T12:25:24+00:00\",\"dateModified\":\"2023-11-28T11:36:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1tormenta.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/1tormenta.jpg\",\"width\":333,\"height\":499},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/01\\\/itaka-escolapios-adelante-siempre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE","description":"Hay momentos, situaciones, desaf\u00edos, que parecen invencibles... pero desde nuestra Red internacional Itaka - Escolapios sabemos muy bien que despu\u00e9s de la tempestad viene la calma, que lo importante es seguir navegando con los ojos puestos en la meta, que juntos podemos vencer las tormentas, que la belleza del viaje supone tambi\u00e9n superarse... \u00a1Es maravilloso&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/","og_locale":"pt_BR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE","og_description":"Hay momentos, situaciones, desaf\u00edos, que parecen invencibles... pero desde nuestra Red internacional Itaka - Escolapios sabemos muy bien que despu\u00e9s de la tempestad viene la calma, que lo importante es seguir navegando con los ojos puestos en la meta, que juntos podemos vencer las tormentas, que la belleza del viaje supone tambi\u00e9n superarse... \u00a1Es maravilloso&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-01-21T12:25:24+00:00","article_modified_time":"2023-11-28T11:36:31+00:00","og_image":[{"width":333,"height":499,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1tormenta.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE","datePublished":"2020-01-21T12:25:24+00:00","dateModified":"2023-11-28T11:36:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/"},"wordCount":79,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1tormenta.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/","name":"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1tormenta.jpg","datePublished":"2020-01-21T12:25:24+00:00","dateModified":"2023-11-28T11:36:31+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1tormenta.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/01\/1tormenta.jpg","width":333,"height":499},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/01\/itaka-escolapios-adelante-siempre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... ADELANTE SIEMPRE"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/29800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=29800"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/29800\/revisions"}],"predecessor-version":[{"id":45144,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/29800\/revisions\/45144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/29801"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=29800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=29800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=29800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}