{"id":30078,"date":"2020-02-22T14:13:31","date_gmt":"2020-02-22T13:13:31","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30078"},"modified":"2023-11-28T12:36:28","modified_gmt":"2023-11-28T11:36:28","slug":"itaka-escolapios-es-un-cofre-de-regalos","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/","title":{"rendered":"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS"},"content":{"rendered":"<p>Nuestra Red internacional es m\u00e1s que un regalo: es un gran conjunto de dones que van juntos, aunque no siempre los descubramos. Son proyectos que cambian a las personas (a quienes se ayuda y a quienes prestan esa ayuda), que cambian los entornos en que se hace presente, que cambia el mundo entero porque ese cambio se produce en cada peque\u00f1o lugar, que abre la mente y el coraz\u00f3n de todos, que nos hace sentir m\u00e1s cerca la presencia de Dios, que llena de alegr\u00eda y esperanza all\u00ed donde est\u00e1, que cada d\u00eda descubre nuevos caminos&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Red internacional es m\u00e1s que un regalo: es un gran conjunto de dones que van juntos, aunque no siempre los descubramos. Son proyectos que cambian a las personas (a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS<\/title>\n<meta name=\"description\" content=\"Nuestra Red internacional es m\u00e1s que un regalo: es un gran conjunto de dones que van juntos, aunque no siempre los descubramos. Son proyectos que cambian a las personas (a quienes se ayuda y a quienes prestan esa ayuda), que cambian los entornos en que se hace presente, que cambia el mundo entero porque ese&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS\" \/>\n<meta property=\"og:description\" content=\"Nuestra Red internacional es m\u00e1s que un regalo: es un gran conjunto de dones que van juntos, aunque no siempre los descubramos. Son proyectos que cambian a las personas (a quienes se ayuda y a quienes prestan esa ayuda), que cambian los entornos en que se hace presente, que cambia el mundo entero porque ese&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-22T13:13:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/02\/1cofr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1137\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS\",\"datePublished\":\"2020-02-22T13:13:31+00:00\",\"dateModified\":\"2023-11-28T11:36:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/\"},\"wordCount\":110,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/1cofr.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/\",\"name\":\"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/1cofr.jpg\",\"datePublished\":\"2020-02-22T13:13:31+00:00\",\"dateModified\":\"2023-11-28T11:36:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/1cofr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/1cofr.jpg\",\"width\":1137,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/02\\\/itaka-escolapios-es-un-cofre-de-regalos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS","description":"Nuestra Red internacional es m\u00e1s que un regalo: es un gran conjunto de dones que van juntos, aunque no siempre los descubramos. Son proyectos que cambian a las personas (a quienes se ayuda y a quienes prestan esa ayuda), que cambian los entornos en que se hace presente, que cambia el mundo entero porque ese&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/","og_locale":"pt_BR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS","og_description":"Nuestra Red internacional es m\u00e1s que un regalo: es un gran conjunto de dones que van juntos, aunque no siempre los descubramos. Son proyectos que cambian a las personas (a quienes se ayuda y a quienes prestan esa ayuda), que cambian los entornos en que se hace presente, que cambia el mundo entero porque ese&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-02-22T13:13:31+00:00","article_modified_time":"2023-11-28T11:36:28+00:00","og_image":[{"width":1137,"height":1300,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/02\/1cofr.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS","datePublished":"2020-02-22T13:13:31+00:00","dateModified":"2023-11-28T11:36:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/"},"wordCount":110,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/02\/1cofr.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/","name":"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/02\/1cofr.jpg","datePublished":"2020-02-22T13:13:31+00:00","dateModified":"2023-11-28T11:36:28+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/02\/1cofr.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/02\/1cofr.jpg","width":1137,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/02\/itaka-escolapios-es-un-cofre-de-regalos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS ES UN COFRE DE REGALOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=30078"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30078\/revisions"}],"predecessor-version":[{"id":45068,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30078\/revisions\/45068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/30079"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=30078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=30078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=30078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}