{"id":30209,"date":"2020-03-07T10:55:08","date_gmt":"2020-03-07T09:55:08","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30209"},"modified":"2023-11-28T12:36:27","modified_gmt":"2023-11-28T11:36:27","slug":"voluntariado-una-forma-vivir-dando-vida","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/","title":{"rendered":"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA"},"content":{"rendered":"<p>Itaka &#8211; Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o&#8230; y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.<\/p>\n<p>Cientos de personas en muchos pa\u00edses del mundo lo est\u00e1n comprobando en nuestra Red Itaka &#8211; Escolapios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Itaka &#8211; Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA<\/title>\n<meta name=\"description\" content=\"Itaka - Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o... y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA\" \/>\n<meta property=\"og:description\" content=\"Itaka - Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o... y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-07T09:55:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/voluntariado-1130x570.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1130\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA\",\"datePublished\":\"2020-03-07T09:55:08+00:00\",\"dateModified\":\"2023-11-28T11:36:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/\"},\"wordCount\":85,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/voluntariado-1130x570.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/\",\"name\":\"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/voluntariado-1130x570.jpg\",\"datePublished\":\"2020-03-07T09:55:08+00:00\",\"dateModified\":\"2023-11-28T11:36:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/voluntariado-1130x570.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/voluntariado-1130x570.jpg\",\"width\":1130,\"height\":570},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/03\\\/voluntariado-una-forma-vivir-dando-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA","description":"Itaka - Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o... y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/","og_locale":"pt_BR","og_type":"article","og_title":"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA","og_description":"Itaka - Escolapios sabe bien que el voluntariado cambia la vida de quien est\u00e1 dispuesto a compartir tiempo en ayudar a los dem\u00e1s y cambia la vida de aquellas personas que reciben este regalo de la dedicaci\u00f3n y cari\u00f1o... y con ello va creciendo una ola de solidaridad, de nueva mentalidad, de transformaci\u00f3n del mundo.&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-03-07T09:55:08+00:00","article_modified_time":"2023-11-28T11:36:27+00:00","og_image":[{"width":1130,"height":570,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/voluntariado-1130x570.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA","datePublished":"2020-03-07T09:55:08+00:00","dateModified":"2023-11-28T11:36:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/"},"wordCount":85,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/voluntariado-1130x570.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/","name":"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/voluntariado-1130x570.jpg","datePublished":"2020-03-07T09:55:08+00:00","dateModified":"2023-11-28T11:36:27+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/voluntariado-1130x570.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/03\/voluntariado-1130x570.jpg","width":1130,"height":570},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/03\/voluntariado-una-forma-vivir-dando-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"VOLUNTARIADO... UNA FORMA DE VIVIR DANDO VIDA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=30209"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30209\/revisions"}],"predecessor-version":[{"id":45024,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30209\/revisions\/45024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/30210"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=30209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=30209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=30209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}