{"id":30470,"date":"2020-04-17T10:15:22","date_gmt":"2020-04-17T09:15:22","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30470"},"modified":"2023-11-28T12:36:23","modified_gmt":"2023-11-28T11:36:23","slug":"cuentas-del-ejercicio-2018-2019","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/","title":{"rendered":"CUENTAS DEL EJERCICIO 2018-2019"},"content":{"rendered":"<p>El Patronato de la Fundaci\u00f3n Itaka-Escolapios aprob\u00f3 el pasado 20 de febrero las cuentas anuales del ejercicio 2018-2019. Una vez aprobadas y auditadas externamente, adem\u00e1s de las cuentas completas disponibles en la secci\u00f3n de <a href=\"https:\/\/www.itakaescolapios.org\/quienes-somos\/credibilidad\/\">Credibilidad<\/a> presentamos este resumen con lo m\u00e1s destacado, que completa a la <a href=\"https:\/\/www.itakaescolapios.org\/quienes-somos\/memorias-de-actividad\/\">Memoria de actividad<\/a> que ya fue publicada. Sobre todo, nos gustar\u00eda agradecer a tantas personas que nos ayudan a hacer posible que la educaci\u00f3n cambie el mundo. A todas ellas, \u00a1Muchas gracias!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-30470 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/adenda-informe-economico-1819_pagina_1\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/adenda-informe-economico-1819_pagina_2\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_2-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Patronato de la Fundaci\u00f3n Itaka-Escolapios aprob\u00f3 el pasado 20 de febrero las cuentas anuales del ejercicio 2018-2019. Una vez aprobadas y auditadas externamente, adem\u00e1s de las cuentas completas disponibles [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CUENTAS DEL EJERCICIO 2018-2019<\/title>\n<meta name=\"description\" content=\"El Patronato de la Fundaci\u00f3n Itaka-Escolapios aprob\u00f3 el pasado 20 de febrero las cuentas anuales del ejercicio 2018-2019. Una vez aprobadas y auditadas externamente, adem\u00e1s de las cuentas completas disponibles en la secci\u00f3n de Credibilidad presentamos este resumen con lo m\u00e1s destacado, que completa a la Memoria de actividad que ya fue publicada. Sobre todo,&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CUENTAS DEL EJERCICIO 2018-2019\" \/>\n<meta property=\"og:description\" content=\"El Patronato de la Fundaci\u00f3n Itaka-Escolapios aprob\u00f3 el pasado 20 de febrero las cuentas anuales del ejercicio 2018-2019. Una vez aprobadas y auditadas externamente, adem\u00e1s de las cuentas completas disponibles en la secci\u00f3n de Credibilidad presentamos este resumen con lo m\u00e1s destacado, que completa a la Memoria de actividad que ya fue publicada. Sobre todo,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-17T09:15:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1061\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"CUENTAS DEL EJERCICIO 2018-2019\",\"datePublished\":\"2020-04-17T09:15:22+00:00\",\"dateModified\":\"2023-11-28T11:36:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/\"},\"wordCount\":93,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/\",\"name\":\"CUENTAS DEL EJERCICIO 2018-2019 - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg\",\"datePublished\":\"2020-04-17T09:15:22+00:00\",\"dateModified\":\"2023-11-28T11:36:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg\",\"width\":1061,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/cuentas-del-ejercicio-2018-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CUENTAS DEL EJERCICIO 2018-2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CUENTAS DEL EJERCICIO 2018-2019","description":"El Patronato de la Fundaci\u00f3n Itaka-Escolapios aprob\u00f3 el pasado 20 de febrero las cuentas anuales del ejercicio 2018-2019. Una vez aprobadas y auditadas externamente, adem\u00e1s de las cuentas completas disponibles en la secci\u00f3n de Credibilidad presentamos este resumen con lo m\u00e1s destacado, que completa a la Memoria de actividad que ya fue publicada. Sobre todo,&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/","og_locale":"pt_BR","og_type":"article","og_title":"CUENTAS DEL EJERCICIO 2018-2019","og_description":"El Patronato de la Fundaci\u00f3n Itaka-Escolapios aprob\u00f3 el pasado 20 de febrero las cuentas anuales del ejercicio 2018-2019. Una vez aprobadas y auditadas externamente, adem\u00e1s de las cuentas completas disponibles en la secci\u00f3n de Credibilidad presentamos este resumen con lo m\u00e1s destacado, que completa a la Memoria de actividad que ya fue publicada. Sobre todo,&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-04-17T09:15:22+00:00","article_modified_time":"2023-11-28T11:36:23+00:00","og_image":[{"width":1061,"height":1500,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"CUENTAS DEL EJERCICIO 2018-2019","datePublished":"2020-04-17T09:15:22+00:00","dateModified":"2023-11-28T11:36:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/"},"wordCount":93,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/","name":"CUENTAS DEL EJERCICIO 2018-2019 - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg","datePublished":"2020-04-17T09:15:22+00:00","dateModified":"2023-11-28T11:36:23+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/ADENDA-INFORME-ECONOMICO-1819_P\u00e1gina_1.jpg","width":1061,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/cuentas-del-ejercicio-2018-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"CUENTAS DEL EJERCICIO 2018-2019"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=30470"}],"version-history":[{"count":5,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30470\/revisions"}],"predecessor-version":[{"id":44918,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30470\/revisions\/44918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/30471"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=30470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=30470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=30470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}