{"id":30564,"date":"2020-04-28T12:21:41","date_gmt":"2020-04-28T11:21:41","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30564"},"modified":"2023-11-28T12:36:22","modified_gmt":"2023-11-28T11:36:22","slug":"itaka-escolapios-preocupados-y-esperanzados","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/","title":{"rendered":"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS"},"content":{"rendered":"<p>La situaci\u00f3n actual en todo el mundo provoca en nuestra Red preocupaci\u00f3n por la salud y la vida de muchas personas as\u00ed como la actitud de esperanza confiando en la conciencia y bondad de la buena gente del mundo.<\/p>\n<p>Atender a tanta gente en peligro y ya en situaci\u00f3n de enfermedad, de pobreza, de necesidad&#8230; es un desaf\u00edo m\u00e1s grave y acuciante en estos momentos. Los ingresos y recursos se reducen, las posibilidades de moverse y llegar a los dem\u00e1s se hacen m\u00e1s complicadas, las perspectivas de futuro no son muy halag\u00fce\u00f1as. Pero cada persona que est\u00e1 detr\u00e1s de nuestra Red: los escolapios, la Fraternidad, los profesionales, los voluntarios, los socios, los colaboradores&#8230; est\u00e1n ah\u00ed y juntos seremos capaces de responder \u00a1como siempre!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La situaci\u00f3n actual en todo el mundo provoca en nuestra Red preocupaci\u00f3n por la salud y la vida de muchas personas as\u00ed como la actitud de esperanza confiando en la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS<\/title>\n<meta name=\"description\" content=\"La situaci\u00f3n actual en todo el mundo provoca en nuestra Red preocupaci\u00f3n por la salud y la vida de muchas personas as\u00ed como la actitud de esperanza confiando en la conciencia y bondad de la buena gente del mundo. Atender a tanta gente en peligro y ya en situaci\u00f3n de enfermedad, de pobreza, de necesidad...&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS\" \/>\n<meta property=\"og:description\" content=\"La situaci\u00f3n actual en todo el mundo provoca en nuestra Red preocupaci\u00f3n por la salud y la vida de muchas personas as\u00ed como la actitud de esperanza confiando en la conciencia y bondad de la buena gente del mundo. Atender a tanta gente en peligro y ya en situaci\u00f3n de enfermedad, de pobreza, de necesidad...&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-28T11:21:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1D\u00eda-de-la-buena-Gente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"631\" \/>\n\t<meta property=\"og:image:height\" content=\"349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS\",\"datePublished\":\"2020-04-28T11:21:41+00:00\",\"dateModified\":\"2023-11-28T11:36:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/\"},\"wordCount\":140,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1D\u00eda-de-la-buena-Gente.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/\",\"name\":\"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1D\u00eda-de-la-buena-Gente.jpg\",\"datePublished\":\"2020-04-28T11:21:41+00:00\",\"dateModified\":\"2023-11-28T11:36:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1D\u00eda-de-la-buena-Gente.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1D\u00eda-de-la-buena-Gente.jpg\",\"width\":631,\"height\":349},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/04\\\/itaka-escolapios-preocupados-y-esperanzados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS","description":"La situaci\u00f3n actual en todo el mundo provoca en nuestra Red preocupaci\u00f3n por la salud y la vida de muchas personas as\u00ed como la actitud de esperanza confiando en la conciencia y bondad de la buena gente del mundo. Atender a tanta gente en peligro y ya en situaci\u00f3n de enfermedad, de pobreza, de necesidad...&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/","og_locale":"pt_BR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS","og_description":"La situaci\u00f3n actual en todo el mundo provoca en nuestra Red preocupaci\u00f3n por la salud y la vida de muchas personas as\u00ed como la actitud de esperanza confiando en la conciencia y bondad de la buena gente del mundo. Atender a tanta gente en peligro y ya en situaci\u00f3n de enfermedad, de pobreza, de necesidad...&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-04-28T11:21:41+00:00","article_modified_time":"2023-11-28T11:36:22+00:00","og_image":[{"width":631,"height":349,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1D\u00eda-de-la-buena-Gente.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS","datePublished":"2020-04-28T11:21:41+00:00","dateModified":"2023-11-28T11:36:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/"},"wordCount":140,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1D\u00eda-de-la-buena-Gente.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/","name":"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1D\u00eda-de-la-buena-Gente.jpg","datePublished":"2020-04-28T11:21:41+00:00","dateModified":"2023-11-28T11:36:22+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1D\u00eda-de-la-buena-Gente.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/04\/1D\u00eda-de-la-buena-Gente.jpg","width":631,"height":349},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/04\/itaka-escolapios-preocupados-y-esperanzados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS... PREOCUPADOS Y ESPERANZADOS"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=30564"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30564\/revisions"}],"predecessor-version":[{"id":44884,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30564\/revisions\/44884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/30565"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=30564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=30564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=30564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}