{"id":30950,"date":"2020-05-29T11:50:32","date_gmt":"2020-05-29T10:50:32","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=30950"},"modified":"2023-11-28T12:36:18","modified_gmt":"2023-11-28T11:36:18","slug":"itaka-escolapios-una-red-de-solidaridad-2","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/","title":{"rendered":"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD"},"content":{"rendered":"<p>Nuestra Red internacional Itaka &#8211; Escolapios es una red que alcanza a 19 pa\u00edses, m\u00e1s de 70 localidades, cientos de proyectos, muchas l\u00edneas de acci\u00f3n, much\u00edsimas personas y entidades, e infinitos deseos de seguir trabajando por un mundo mejor para toda la humanidad.<\/p>\n<p>Es maravilloso ver c\u00f3mo alcanza la solidaridad de unas personas con otras, compartiendo dinero, conocimiento, colaboraci\u00f3n com\u00fan, dedicaci\u00f3n en favor de quienes m\u00e1s lo necesitan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra Red internacional Itaka &#8211; Escolapios es una red que alcanza a 19 pa\u00edses, m\u00e1s de 70 localidades, cientos de proyectos, muchas l\u00edneas de acci\u00f3n, much\u00edsimas personas y entidades, e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30951,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-30950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itaka-escolapios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD<\/title>\n<meta name=\"description\" content=\"Nuestra Red internacional Itaka - Escolapios es una red que alcanza a 19 pa\u00edses, m\u00e1s de 70 localidades, cientos de proyectos, muchas l\u00edneas de acci\u00f3n, much\u00edsimas personas y entidades, e infinitos deseos de seguir trabajando por un mundo mejor para toda la humanidad. Es maravilloso ver c\u00f3mo alcanza la solidaridad de unas personas con otras,&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD\" \/>\n<meta property=\"og:description\" content=\"Nuestra Red internacional Itaka - Escolapios es una red que alcanza a 19 pa\u00edses, m\u00e1s de 70 localidades, cientos de proyectos, muchas l\u00edneas de acci\u00f3n, much\u00edsimas personas y entidades, e infinitos deseos de seguir trabajando por un mundo mejor para toda la humanidad. Es maravilloso ver c\u00f3mo alcanza la solidaridad de unas personas con otras,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-29T10:50:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:36:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1solidar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1083\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itaka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itaka\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/\"},\"author\":{\"name\":\"itaka\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\"},\"headline\":\"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD\",\"datePublished\":\"2020-05-29T10:50:32+00:00\",\"dateModified\":\"2023-11-28T11:36:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/\"},\"wordCount\":83,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1solidar.jpg\",\"articleSection\":[\"Itaka Escolapios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/\",\"name\":\"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1solidar.jpg\",\"datePublished\":\"2020-05-29T10:50:32+00:00\",\"dateModified\":\"2023-11-28T11:36:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1solidar.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1solidar.jpg\",\"width\":1083,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2020\\\/05\\\/itaka-escolapios-una-red-de-solidaridad-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/670123daeb1cc31cae1b106740036ccb\",\"name\":\"itaka\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itaka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD","description":"Nuestra Red internacional Itaka - Escolapios es una red que alcanza a 19 pa\u00edses, m\u00e1s de 70 localidades, cientos de proyectos, muchas l\u00edneas de acci\u00f3n, much\u00edsimas personas y entidades, e infinitos deseos de seguir trabajando por un mundo mejor para toda la humanidad. Es maravilloso ver c\u00f3mo alcanza la solidaridad de unas personas con otras,&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/","og_locale":"pt_BR","og_type":"article","og_title":"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD","og_description":"Nuestra Red internacional Itaka - Escolapios es una red que alcanza a 19 pa\u00edses, m\u00e1s de 70 localidades, cientos de proyectos, muchas l\u00edneas de acci\u00f3n, much\u00edsimas personas y entidades, e infinitos deseos de seguir trabajando por un mundo mejor para toda la humanidad. Es maravilloso ver c\u00f3mo alcanza la solidaridad de unas personas con otras,&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/","og_site_name":"Itaka-Escolapios","article_published_time":"2020-05-29T10:50:32+00:00","article_modified_time":"2023-11-28T11:36:18+00:00","og_image":[{"width":1083,"height":1300,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1solidar.jpg","type":"image\/jpeg"}],"author":"itaka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itaka"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/"},"author":{"name":"itaka","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb"},"headline":"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD","datePublished":"2020-05-29T10:50:32+00:00","dateModified":"2023-11-28T11:36:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/"},"wordCount":83,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1solidar.jpg","articleSection":["Itaka Escolapios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/","name":"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1solidar.jpg","datePublished":"2020-05-29T10:50:32+00:00","dateModified":"2023-11-28T11:36:18+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1solidar.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2020\/05\/1solidar.jpg","width":1083,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2020\/05\/itaka-escolapios-una-red-de-solidaridad-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"ITAKA - ESCOLAPIOS, UNA RED DE SOLIDARIDAD"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/670123daeb1cc31cae1b106740036ccb","name":"itaka","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itaka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=30950"}],"version-history":[{"count":3,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30950\/revisions"}],"predecessor-version":[{"id":44776,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/30950\/revisions\/44776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/30951"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=30950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=30950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=30950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}