{"id":325205,"date":"2023-12-14T15:57:56","date_gmt":"2023-12-14T14:57:56","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=43566"},"modified":"2025-03-07T18:28:31","modified_gmt":"2025-03-07T17:28:31","slug":"english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/","title":{"rendered":"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan)"},"content":{"rendered":"<p>Ayer, 15 de diciembre de 2023, el Complexe Scolaire Bilingue Calasanz de Messamendongo acogi\u00f3 la celebraci\u00f3n del \u00e1rbol de Navidad para los alumnos internos y externos. Durante la jornada, los j\u00f3venes celebraron a su manera el nacimiento del Ni\u00f1o Jes\u00fas. El programa incluy\u00f3 canciones, bailes, cuentacuentos, sketches, un concurso para el que m\u00e1s comiera y mucho m\u00e1s. Fue un gran d\u00eda de trabajo colaborativo y diversi\u00f3n. As\u00ed pues, desde CABAC Messamendongo, os deseamos una Feliz Navidad.<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer, 15 de diciembre de 2023, el Complexe Scolaire Bilingue Calasanz de Messamendongo acogi\u00f3 la celebraci\u00f3n del \u00e1rbol de Navidad para los alumnos internos y externos. Durante la jornada, los [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":325418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,10],"tags":[],"class_list":["post-325205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-camerun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan)<\/title>\n<meta name=\"description\" content=\"Ayer, 15 de diciembre de 2023, el Complexe Scolaire Bilingue Calasanz de Messamendongo acogi\u00f3 la celebraci\u00f3n del \u00e1rbol de Navidad para los alumnos internos y externos. Durante la jornada, los j\u00f3venes celebraron a su manera el nacimiento del Ni\u00f1o Jes\u00fas. El programa incluy\u00f3 canciones, bailes, cuentacuentos, sketches, un concurso para el que m\u00e1s comiera y&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Ayer,%2015%20de%20diciembre%20de%202023,%20el%20Complexe%20Scolaire%20Bilingue%20Calasanz%20de%20Messamendongo%20acogi\u00f3%20la%20celebraci\u00f3n%20del%20\u00e1rbol%20de%20Navidad%20para%20los%20alumnos%20internos%20y%20externos.%20Durante%20la%20jornada,%20los%20j\u00f3venes%20celebraron%20a%20su%20manera%20el%20nacimiento%20del%20Ni\u00f1o%20Jes\u00fas.%20El%20programa%20incluy\u00f3%20canciones,%20bailes,%20cuentacuentos,%20sketches,%20un%20concurso%20para%20el%20que%20m\u00e1s%20comiera%20y&hellip;\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan)\" \/>\n<meta property=\"og:description\" content=\"Ayer, 15 de diciembre de 2023, el Complexe Scolaire Bilingue Calasanz de Messamendongo acogi\u00f3 la celebraci\u00f3n del \u00e1rbol de Navidad para los alumnos internos y externos. Durante la jornada, los j\u00f3venes celebraron a su manera el nacimiento del Ni\u00f1o Jes\u00fas. El programa incluy\u00f3 canciones, bailes, cuentacuentos, sketches, un concurso para el que m\u00e1s comiera y&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-14T14:57:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"809\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan)\",\"datePublished\":\"2023-12-14T14:57:56+00:00\",\"dateModified\":\"2025-03-07T17:28:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/\"},\"wordCount\":91,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg\",\"articleSection\":[\"\u00c1frica Central\",\"Camar\u00f5es\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/\",\"name\":\"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan) - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg\",\"datePublished\":\"2023-12-14T14:57:56+00:00\",\"dateModified\":\"2025-03-07T17:28:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg\",\"width\":809,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/12\\\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan)","description":"Ayer, 15 de diciembre de 2023, el Complexe Scolaire Bilingue Calasanz de Messamendongo acogi\u00f3 la celebraci\u00f3n del \u00e1rbol de Navidad para los alumnos internos y externos. Durante la jornada, los j\u00f3venes celebraron a su manera el nacimiento del Ni\u00f1o Jes\u00fas. El programa incluy\u00f3 canciones, bailes, cuentacuentos, sketches, un concurso para el que m\u00e1s comiera y&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Ayer, 15 de diciembre de 2023, el Complexe Scolaire Bilingue Calasanz de Messamendongo acogi\u00f3 la celebraci\u00f3n del \u00e1rbol de Navidad para los alumnos internos y externos. Durante la jornada, los j\u00f3venes celebraron a su manera el nacimiento del Ni\u00f1o Jes\u00fas. El programa incluy\u00f3 canciones, bailes, cuentacuentos, sketches, un concurso para el que m\u00e1s comiera y&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan)","og_description":"Ayer, 15 de diciembre de 2023, el Complexe Scolaire Bilingue Calasanz de Messamendongo acogi\u00f3 la celebraci\u00f3n del \u00e1rbol de Navidad para los alumnos internos y externos. Durante la jornada, los j\u00f3venes celebraron a su manera el nacimiento del Ni\u00f1o Jes\u00fas. El programa incluy\u00f3 canciones, bailes, cuentacuentos, sketches, un concurso para el que m\u00e1s comiera y&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/","og_site_name":"Itaka-Escolapios","article_published_time":"2023-12-14T14:57:56+00:00","article_modified_time":"2025-03-07T17:28:31+00:00","og_image":[{"width":809,"height":1080,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg","type":"image\/jpeg"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cameroun01"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan)","datePublished":"2023-12-14T14:57:56+00:00","dateModified":"2025-03-07T17:28:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/"},"wordCount":91,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg","articleSection":["\u00c1frica Central","Camar\u00f5es"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/","name":"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan) - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg","datePublished":"2023-12-14T14:57:56+00:00","dateModified":"2025-03-07T17:28:31+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-14-at-15.30.28-1-1.jpeg","width":809,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/12\/english-christmas-tree-at-cabac-messamendongo-yaounde-cameroon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00c1rbol de Navidad en CABAC Messamendongo (Yaund\u00e9-Camer\u00fan)"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/325205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=325205"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/325205\/revisions"}],"predecessor-version":[{"id":326408,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/325205\/revisions\/326408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/325418"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=325205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=325205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=325205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}