{"id":325220,"date":"2024-01-26T09:36:22","date_gmt":"2024-01-26T08:36:22","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=43774"},"modified":"2025-03-07T18:28:29","modified_gmt":"2025-03-07T17:28:29","slug":"english-launch-of-bilingualism-week-at-coscabic","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/","title":{"rendered":"Inicio de la semana del biling\u00fcismo en COSCABIC."},"content":{"rendered":"<p>El biling\u00fcismo oficial es para Camer\u00fan una verdadera autopista hacia la tecnolog\u00eda, una garant\u00eda de armon\u00eda, comprensi\u00f3n intercultural e integraci\u00f3n. La 19\u00aa edici\u00f3n de la Semana Nacional del Biling\u00fcismo, bajo el lema &#8220;El biling\u00fcismo, vector de digitalizaci\u00f3n de la ense\u00f1anza y de promoci\u00f3n de vectores c\u00edvicos y morales para un Camer\u00fan pac\u00edfico y emergente&#8221;, fue lanzada este viernes 26 de enero de 2024 en el COSCABIC de Bafia. Los profesores tuvieron en cuenta las dificultades de los ni\u00f1os para comprender el tema. Por ello, se esmeraron en explicar las palabras dif\u00edciles y, a continuaci\u00f3n, el tema en su totalidad y en los dos idiomas.<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El biling\u00fcismo oficial es para Camer\u00fan una verdadera autopista hacia la tecnolog\u00eda, una garant\u00eda de armon\u00eda, comprensi\u00f3n intercultural e integraci\u00f3n. La 19\u00aa edici\u00f3n de la Semana Nacional del Biling\u00fcismo, bajo [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":325528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,10],"tags":[],"class_list":["post-325220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-camerun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inicio de la semana del biling\u00fcismo en COSCABIC.<\/title>\n<meta name=\"description\" content=\"El biling\u00fcismo oficial es para Camer\u00fan una verdadera autopista hacia la tecnolog\u00eda, una garant\u00eda de armon\u00eda, comprensi\u00f3n intercultural e integraci\u00f3n. La 19\u00aa edici\u00f3n de la Semana Nacional del Biling\u00fcismo, bajo el lema &quot;El biling\u00fcismo, vector de digitalizaci\u00f3n de la ense\u00f1anza y de promoci\u00f3n de vectores c\u00edvicos y morales para un Camer\u00fan pac\u00edfico y emergente&quot;, fue&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/El%20biling\u00fcismo%20oficial%20es%20para%20Camer\u00fan%20una%20verdadera%20autopista%20hacia%20la%20tecnolog\u00eda,%20una%20garant\u00eda%20de%20armon\u00eda,%20comprensi\u00f3n%20intercultural%20e%20integraci\u00f3n.%20La%2019\u00aa%20edici\u00f3n%20de%20la%20Semana%20Nacional%20del%20Biling\u00fcismo,%20bajo%20el%20lema%20El%20biling\u00fcismo,%20vector%20de%20digitalizaci\u00f3n%20de%20la%20ense\u00f1anza%20y%20de%20promoci\u00f3n%20de%20vectores%20c\u00edvicos%20y%20morales%20para%20un%20Camer\u00fan%20pac\u00edfico%20y%20emergente,%20fue&hellip;\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inicio de la semana del biling\u00fcismo en COSCABIC.\" \/>\n<meta property=\"og:description\" content=\"El biling\u00fcismo oficial es para Camer\u00fan una verdadera autopista hacia la tecnolog\u00eda, una garant\u00eda de armon\u00eda, comprensi\u00f3n intercultural e integraci\u00f3n. La 19\u00aa edici\u00f3n de la Semana Nacional del Biling\u00fcismo, bajo el lema &quot;El biling\u00fcismo, vector de digitalizaci\u00f3n de la ense\u00f1anza y de promoci\u00f3n de vectores c\u00edvicos y morales para un Camer\u00fan pac\u00edfico y emergente&quot;, fue&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T08:36:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"Inicio de la semana del biling\u00fcismo en COSCABIC.\",\"datePublished\":\"2024-01-26T08:36:22+00:00\",\"dateModified\":\"2025-03-07T17:28:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/\"},\"wordCount\":129,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg\",\"articleSection\":[\"\u00c1frica Central\",\"Camar\u00f5es\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/\",\"name\":\"Inicio de la semana del biling\u00fcismo en COSCABIC. - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg\",\"datePublished\":\"2024-01-26T08:36:22+00:00\",\"dateModified\":\"2025-03-07T17:28:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg\",\"width\":1080,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/01\\\/english-launch-of-bilingualism-week-at-coscabic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio de la semana del biling\u00fcismo en COSCABIC.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inicio de la semana del biling\u00fcismo en COSCABIC.","description":"El biling\u00fcismo oficial es para Camer\u00fan una verdadera autopista hacia la tecnolog\u00eda, una garant\u00eda de armon\u00eda, comprensi\u00f3n intercultural e integraci\u00f3n. La 19\u00aa edici\u00f3n de la Semana Nacional del Biling\u00fcismo, bajo el lema \"El biling\u00fcismo, vector de digitalizaci\u00f3n de la ense\u00f1anza y de promoci\u00f3n de vectores c\u00edvicos y morales para un Camer\u00fan pac\u00edfico y emergente\", fue&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"El biling\u00fcismo oficial es para Camer\u00fan una verdadera autopista hacia la tecnolog\u00eda, una garant\u00eda de armon\u00eda, comprensi\u00f3n intercultural e integraci\u00f3n. La 19\u00aa edici\u00f3n de la Semana Nacional del Biling\u00fcismo, bajo el lema \"El biling\u00fcismo, vector de digitalizaci\u00f3n de la ense\u00f1anza y de promoci\u00f3n de vectores c\u00edvicos y morales para un Camer\u00fan pac\u00edfico y emergente\", fue&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"Inicio de la semana del biling\u00fcismo en COSCABIC.","og_description":"El biling\u00fcismo oficial es para Camer\u00fan una verdadera autopista hacia la tecnolog\u00eda, una garant\u00eda de armon\u00eda, comprensi\u00f3n intercultural e integraci\u00f3n. La 19\u00aa edici\u00f3n de la Semana Nacional del Biling\u00fcismo, bajo el lema \"El biling\u00fcismo, vector de digitalizaci\u00f3n de la ense\u00f1anza y de promoci\u00f3n de vectores c\u00edvicos y morales para un Camer\u00fan pac\u00edfico y emergente\", fue&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/","og_site_name":"Itaka-Escolapios","article_published_time":"2024-01-26T08:36:22+00:00","article_modified_time":"2025-03-07T17:28:29+00:00","og_image":[{"width":1080,"height":486,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg","type":"image\/jpeg"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cameroun01","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"Inicio de la semana del biling\u00fcismo en COSCABIC.","datePublished":"2024-01-26T08:36:22+00:00","dateModified":"2025-03-07T17:28:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/"},"wordCount":129,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg","articleSection":["\u00c1frica Central","Camar\u00f5es"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/","name":"Inicio de la semana del biling\u00fcismo en COSCABIC. - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg","datePublished":"2024-01-26T08:36:22+00:00","dateModified":"2025-03-07T17:28:29+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-08.00.13-1.jpeg","width":1080,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/01\/english-launch-of-bilingualism-week-at-coscabic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Inicio de la semana del biling\u00fcismo en COSCABIC."}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/325220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=325220"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/325220\/revisions"}],"predecessor-version":[{"id":326381,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/325220\/revisions\/326381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/325528"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=325220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=325220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=325220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}