{"id":325237,"date":"2024-02-20T09:13:54","date_gmt":"2024-02-20T08:13:54","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=44029"},"modified":"2025-03-07T18:28:26","modified_gmt":"2025-03-07T17:28:26","slug":"francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/","title":{"rendered":"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA"},"content":{"rendered":"<p>Del 26 de enero al 4 de febrero de 2024, un equipo de Cooperativa Penascal, junto con la red Itaka-Escolapios visitaron Kinshasa. La visita se inscrib\u00eda en el marco de la preparaci\u00f3n de las opciones t\u00e9cnicas para el complejo escolar Saint Joseph Calasanz de Kinshasa.<\/p>\n<p>El equipo coordinador de este complejo escolar se benefici\u00f3 de cuatro d\u00edas de talleres sobre el proyecto de aprendizaje integral.<\/p>\n<p>Adem\u00e1s, visitar centros como la escuela de aplicaci\u00f3n de la UPN, el Coll\u00e8ge Technique Don Bosco (en Kinshasa), y el Coll\u00e8ge Technique J\u00e9suites (en Lubumbashi), abri\u00f3 un horizonte de inspiraci\u00f3n, visi\u00f3n y posibilidades de colaboraci\u00f3n con empresas para nuestros futuros t\u00e9cnicos. Esta visita nos da motivos para creer que el fruto y la opci\u00f3n t\u00e9cnica de nuestro Complejo Escolar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 26 de enero al 4 de febrero de 2024, un equipo de Cooperativa Penascal, junto con la red Itaka-Escolapios visitaron Kinshasa. La visita se inscrib\u00eda en el marco de [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":325611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[],"class_list":["post-325237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA<\/title>\n<meta name=\"description\" content=\"Del 26 de enero al 4 de febrero de 2024, un equipo de Cooperativa Penascal, junto con la red Itaka-Escolapios visitaron Kinshasa. La visita se inscrib\u00eda en el marco de la preparaci\u00f3n de las opciones t\u00e9cnicas para el complejo escolar Saint Joseph Calasanz de Kinshasa. El equipo coordinador de este complejo escolar se benefici\u00f3 de&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Del%2026%20de%20enero%20al%204%20de%20febrero%20de%202024,%20un%20equipo%20de%20Cooperativa%20Penascal,%20junto%20con%20la%20red%20Itaka-Escolapios%20visitaron%20Kinshasa.%20La%20visita%20se%20inscrib\u00eda%20en%20el%20marco%20de%20la%20preparaci\u00f3n%20de%20las%20opciones%20t\u00e9cnicas%20para%20el%20complejo%20escolar%20Saint%20Joseph%20Calasanz%20de%20Kinshasa.%20El%20equipo%20coordinador%20de%20este%20complejo%20escolar%20se%20benefici\u00f3%20de&hellip;\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA\" \/>\n<meta property=\"og:description\" content=\"Del 26 de enero al 4 de febrero de 2024, un equipo de Cooperativa Penascal, junto con la red Itaka-Escolapios visitaron Kinshasa. La visita se inscrib\u00eda en el marco de la preparaci\u00f3n de las opciones t\u00e9cnicas para el complejo escolar Saint Joseph Calasanz de Kinshasa. El equipo coordinador de este complejo escolar se benefici\u00f3 de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-20T08:13:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T17:28:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/02\/IMG-20240203-WA0035-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"guinea02\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"guinea02\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/\"},\"author\":{\"name\":\"guinea02\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/cebf12599ff6dda22baef2d4ae27aa6a\"},\"headline\":\"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA\",\"datePublished\":\"2024-02-20T08:13:54+00:00\",\"dateModified\":\"2025-03-07T17:28:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/\"},\"wordCount\":146,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG-20240203-WA0035-1.jpg\",\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/\",\"name\":\"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG-20240203-WA0035-1.jpg\",\"datePublished\":\"2024-02-20T08:13:54+00:00\",\"dateModified\":\"2025-03-07T17:28:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG-20240203-WA0035-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG-20240203-WA0035-1.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2024\\\/02\\\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/cebf12599ff6dda22baef2d4ae27aa6a\",\"name\":\"guinea02\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/guinea02\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA","description":"Del 26 de enero al 4 de febrero de 2024, un equipo de Cooperativa Penascal, junto con la red Itaka-Escolapios visitaron Kinshasa. La visita se inscrib\u00eda en el marco de la preparaci\u00f3n de las opciones t\u00e9cnicas para el complejo escolar Saint Joseph Calasanz de Kinshasa. El equipo coordinador de este complejo escolar se benefici\u00f3 de&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Del 26 de enero al 4 de febrero de 2024, un equipo de Cooperativa Penascal, junto con la red Itaka-Escolapios visitaron Kinshasa. La visita se inscrib\u00eda en el marco de la preparaci\u00f3n de las opciones t\u00e9cnicas para el complejo escolar Saint Joseph Calasanz de Kinshasa. El equipo coordinador de este complejo escolar se benefici\u00f3 de&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA","og_description":"Del 26 de enero al 4 de febrero de 2024, un equipo de Cooperativa Penascal, junto con la red Itaka-Escolapios visitaron Kinshasa. La visita se inscrib\u00eda en el marco de la preparaci\u00f3n de las opciones t\u00e9cnicas para el complejo escolar Saint Joseph Calasanz de Kinshasa. El equipo coordinador de este complejo escolar se benefici\u00f3 de&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/","og_site_name":"Itaka-Escolapios","article_published_time":"2024-02-20T08:13:54+00:00","article_modified_time":"2025-03-07T17:28:26+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/02\/IMG-20240203-WA0035-1.jpg","type":"image\/jpeg"}],"author":"guinea02","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"guinea02","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/"},"author":{"name":"guinea02","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/cebf12599ff6dda22baef2d4ae27aa6a"},"headline":"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA","datePublished":"2024-02-20T08:13:54+00:00","dateModified":"2025-03-07T17:28:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/"},"wordCount":146,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/02\/IMG-20240203-WA0035-1.jpg","articleSection":["R.D. Congo"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/","name":"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/02\/IMG-20240203-WA0035-1.jpg","datePublished":"2024-02-20T08:13:54+00:00","dateModified":"2025-03-07T17:28:26+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/02\/IMG-20240203-WA0035-1.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/02\/IMG-20240203-WA0035-1.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2024\/02\/francais-penascal-et-itaka-kinshasa-la-collaboration-se-concretise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"PE\u00d1ASCAL E ITAKA-ESCOLAPIOS KINSHASA: LA COLABORACI\u00d3N TOMA FORMA"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/cebf12599ff6dda22baef2d4ae27aa6a","name":"guinea02","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/guinea02\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/325237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=325237"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/325237\/revisions"}],"predecessor-version":[{"id":326350,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/325237\/revisions\/326350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/325611"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=325237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=325237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=325237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}