{"id":34927,"date":"2021-10-29T08:46:29","date_gmt":"2021-10-29T07:46:29","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=34927"},"modified":"2023-11-28T12:35:56","modified_gmt":"2023-11-28T11:35:56","slug":"francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/","title":{"rendered":"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO)"},"content":{"rendered":"<p>El mi\u00e9rcoles 27 de octubre de 2021, el P. Pedro AGUADO, Superior General de las Escuelas P\u00edas, inaugur\u00f3 oficialmente la Escuela Infantil San Jos\u00e9 Calasanz en Kikonka. La ceremonia tuvo lugar en presencia de los ni\u00f1os y ni\u00f1as, las autoridades religiosas y administrativas, as\u00ed como de la poblaci\u00f3n local.<\/p>\n<p>La alegr\u00eda fue inmensa al ver a los peque\u00f1os y a sus familias orgullosos de las magn\u00edficas instalaciones que har\u00e1n posible su derecho a la educaci\u00f3n a partir de ahora. En la intervenci\u00f3n por parte del alumnado, se invit\u00f3 a escuchar a\u00fan m\u00e1s la llamada a no perder el tren de la educaci\u00f3n, as\u00ed como tambi\u00e9n agradecieron el apoyo a los Escolapios y a la red Itaka-Escolapios.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-34927 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/img_2870\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/IMG_2870-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/whatsapp-image-2021-10-28-at-17-53-53\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.53-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/whatsapp-image-2021-10-28-at-17-53-52\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.52-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/whatsapp-image-2021-10-28-at-17-53-52-1\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.52-1-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/whatsapp-image-2021-10-28-at-17-53-50\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.50-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/whatsapp-image-2021-10-28-at-17-32-28\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.32.28-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/whatsapp-image-2021-10-28-at-17-32-25\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.32.25-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/whatsapp-image-2021-10-28-at-17-32-24\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.32.24-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/whatsapp-image-2021-10-28-at-17-31-16\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.31.16-90x90.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/img_2873-2\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/IMG_2873-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>El mi\u00e9rcoles 27 de octubre de 2021, el P. Pedro AGUADO, Superior General de las Escuelas P\u00edas, inaugur\u00f3 oficialmente la Escuela Infantil San Jos\u00e9 Calasanz en Kikonka. La ceremonia tuvo [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":34935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[],"class_list":["post-34927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO)<\/title>\n<meta name=\"description\" content=\"El mi\u00e9rcoles 27 de octubre de 2021, el P. Pedro AGUADO, Superior General de las Escuelas P\u00edas, inaugur\u00f3 oficialmente la Escuela Infantil San Jos\u00e9 Calasanz en Kikonka. La ceremonia tuvo lugar en presencia de los ni\u00f1os y ni\u00f1as, las autoridades religiosas y administrativas, as\u00ed como de la poblaci\u00f3n local. La alegr\u00eda fue inmensa al ver&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/El%20mi\u00e9rcoles%2027%20de%20octubre%20de%202021,%20el%20P.%20Pedro%20AGUADO,%20Superior%20General%20de%20las%20Escuelas%20P\u00edas,%20inaugur\u00f3%20oficialmente%20la%20Escuela%20Infantil%20San%20Jos\u00e9%20Calasanz%20en%20Kikonka.%20La%20ceremonia%20tuvo%20lugar%20en%20presencia%20de%20los%20ni\u00f1os%20y%20ni\u00f1as,%20las%20autoridades%20religiosas%20y%20administrativas,%20as\u00ed%20como%20de%20la%20poblaci\u00f3n%20local.%20La%20alegr\u00eda%20fue%20inmensa%20al%20ver&hellip;\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO)\" \/>\n<meta property=\"og:description\" content=\"El mi\u00e9rcoles 27 de octubre de 2021, el P. Pedro AGUADO, Superior General de las Escuelas P\u00edas, inaugur\u00f3 oficialmente la Escuela Infantil San Jos\u00e9 Calasanz en Kikonka. La ceremonia tuvo lugar en presencia de los ni\u00f1os y ni\u00f1as, las autoridades religiosas y administrativas, as\u00ed como de la poblaci\u00f3n local. La alegr\u00eda fue inmensa al ver&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-29T07:46:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO)\",\"datePublished\":\"2021-10-29T07:46:29+00:00\",\"dateModified\":\"2023-11-28T11:35:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/\"},\"wordCount\":145,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg\",\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/\",\"name\":\"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO) - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg\",\"datePublished\":\"2021-10-29T07:46:29+00:00\",\"dateModified\":\"2023-11-28T11:35:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2021\\\/10\\\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO)","description":"El mi\u00e9rcoles 27 de octubre de 2021, el P. Pedro AGUADO, Superior General de las Escuelas P\u00edas, inaugur\u00f3 oficialmente la Escuela Infantil San Jos\u00e9 Calasanz en Kikonka. La ceremonia tuvo lugar en presencia de los ni\u00f1os y ni\u00f1as, las autoridades religiosas y administrativas, as\u00ed como de la poblaci\u00f3n local. La alegr\u00eda fue inmensa al ver&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"El mi\u00e9rcoles 27 de octubre de 2021, el P. Pedro AGUADO, Superior General de las Escuelas P\u00edas, inaugur\u00f3 oficialmente la Escuela Infantil San Jos\u00e9 Calasanz en Kikonka. La ceremonia tuvo lugar en presencia de los ni\u00f1os y ni\u00f1as, las autoridades religiosas y administrativas, as\u00ed como de la poblaci\u00f3n local. La alegr\u00eda fue inmensa al ver&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO)","og_description":"El mi\u00e9rcoles 27 de octubre de 2021, el P. Pedro AGUADO, Superior General de las Escuelas P\u00edas, inaugur\u00f3 oficialmente la Escuela Infantil San Jos\u00e9 Calasanz en Kikonka. La ceremonia tuvo lugar en presencia de los ni\u00f1os y ni\u00f1as, las autoridades religiosas y administrativas, as\u00ed como de la poblaci\u00f3n local. La alegr\u00eda fue inmensa al ver&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/","og_site_name":"Itaka-Escolapios","article_published_time":"2021-10-29T07:46:29+00:00","article_modified_time":"2023-11-28T11:35:56+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg","type":"image\/jpeg"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itakaescolapios","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO)","datePublished":"2021-10-29T07:46:29+00:00","dateModified":"2023-11-28T11:35:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/"},"wordCount":145,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg","articleSection":["R.D. Congo"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/","name":"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO) - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg","datePublished":"2021-10-29T07:46:29+00:00","dateModified":"2023-11-28T11:35:56+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-17.53.50.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2021\/10\/francais-inauguration-de-lecole-maternelle-saint-joseph-calasanz-de-kikonka-r-d-congo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"INAUGURACI\u00d3N DE LA ESCUELA INFANTIL SAINT JOSEPH CALASANZ DE KIKONKA (R.D. CONGO)"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/34927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=34927"}],"version-history":[{"count":8,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/34927\/revisions"}],"predecessor-version":[{"id":44182,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/34927\/revisions\/44182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/34935"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=34927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=34927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=34927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}