{"id":35763,"date":"2022-01-25T16:02:12","date_gmt":"2022-01-25T15:02:12","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=35763"},"modified":"2023-11-28T12:35:53","modified_gmt":"2023-11-28T11:35:53","slug":"campagne-de-solidarite-2022-en-r-d-congo","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/","title":{"rendered":"Campagne de solidarit\u00e9 2022 -R. D. Congo"},"content":{"rendered":"<p>Le 24 janvier 2022, s&#8217;est fait le lancement de la campagne de solidarit\u00e9 2022, en R\u00e9publique D\u00e9mocratique du Congo. Les \u00e9l\u00e8ves et enseignants de l&#8217;\u00c9cole publique Saint Sacrement de Kinshasa ont donc eu le privil\u00e8ge de d\u00e9marrer les activit\u00e9s marquant ladite campagne pour le compte de cette ann\u00e9e. La matin\u00e9e a \u00e9t\u00e9 ponctu\u00e9e par un expos\u00e9 sur le th\u00e8me, les objectifs de la campagne, les moyens de contribution, des chants d&#8217;animation et des petits cadeaux offerts aux tout-petits; le tout, sous l&#8217;encadrement de l&#8217;\u00e9quipe de coordination du bureau d&#8217;Itaka en R. D. Congo, l&#8217;appui des volontaires et la collaboration des enseignants. <img decoding=\"async\" class=\"aligncenter size-medium wp-image-35764\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp-2-300x142.jpeg\" alt=\"\" width=\"300\" height=\"142\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp-2-300x142.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp-2-768x364.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp-2-250x118.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp-2.jpeg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"aligncenter size-medium wp-image-35765\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp3-277x300.jpeg\" alt=\"\" width=\"277\" height=\"300\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp3-277x300.jpeg 277w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp3-250x271.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp3.jpeg 607w\" sizes=\"(max-width: 277px) 100vw, 277px\" \/><img decoding=\"async\" class=\"aligncenter size-medium wp-image-35766\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp4-300x135.jpeg\" alt=\"\" width=\"300\" height=\"135\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp4-300x135.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp4-1024x461.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp4-768x345.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp4-250x112.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp4.jpeg 1036w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"aligncenter size-medium wp-image-35767\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp5-300x192.jpeg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp5-300x192.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp5-768x491.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp5-250x160.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/camp5.jpeg 950w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"aligncenter size-medium wp-image-35768\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/campagne-1-286x300.jpeg\" alt=\"\" width=\"286\" height=\"300\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/campagne-1-286x300.jpeg 286w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/campagne-1-250x263.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/campagne-1.jpeg 731w\" sizes=\"(max-width: 286px) 100vw, 286px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 24 janvier 2022, s&#8217;est fait le lancement de la campagne de solidarit\u00e9 2022, en R\u00e9publique D\u00e9mocratique du Congo. Les \u00e9l\u00e8ves et enseignants de l&#8217;\u00c9cole publique Saint Sacrement de Kinshasa [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":35769,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[256],"class_list":["post-35763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo","tag-campana-de-solidaridad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campagne de solidarit\u00e9 2022 -R. D. Congo<\/title>\n<meta name=\"description\" content=\"Le 24 janvier 2022, s&#039;est fait le lancement de la campagne de solidarit\u00e9 2022, en R\u00e9publique D\u00e9mocratique du Congo. Les \u00e9l\u00e8ves et enseignants de l&#039;\u00c9cole publique Saint Sacrement de Kinshasa ont donc eu le privil\u00e8ge de d\u00e9marrer les activit\u00e9s marquant ladite campagne pour le compte de cette ann\u00e9e. La matin\u00e9e a \u00e9t\u00e9 ponctu\u00e9e par un&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Le%2024%20janvier%202022,%20s'est%20fait%20le%20lancement%20de%20la%20campagne%20de%20solidarit\u00e9%202022,%20en%20R\u00e9publique%20D\u00e9mocratique%20du%20Congo.%20Les%20\u00e9l\u00e8ves%20et%20enseignants%20de%20l'\u00c9cole%20publique%20Saint%20Sacrement%20de%20Kinshasa%20ont%20donc%20eu%20le%20privil\u00e8ge%20de%20d\u00e9marrer%20les%20activit\u00e9s%20marquant%20ladite%20campagne%20pour%20le%20compte%20de%20cette%20ann\u00e9e.%20La%20matin\u00e9e%20a%20\u00e9t\u00e9%20ponctu\u00e9e%20par%20un&hellip;\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campagne de solidarit\u00e9 2022 -R. D. Congo\" \/>\n<meta property=\"og:description\" content=\"Le 24 janvier 2022, s&#039;est fait le lancement de la campagne de solidarit\u00e9 2022, en R\u00e9publique D\u00e9mocratique du Congo. Les \u00e9l\u00e8ves et enseignants de l&#039;\u00c9cole publique Saint Sacrement de Kinshasa ont donc eu le privil\u00e8ge de d\u00e9marrer les activit\u00e9s marquant ladite campagne pour le compte de cette ann\u00e9e. La matin\u00e9e a \u00e9t\u00e9 ponctu\u00e9e par un&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-25T15:02:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"Campagne de solidarit\u00e9 2022 -R. D. Congo\",\"datePublished\":\"2022-01-25T15:02:12+00:00\",\"dateModified\":\"2023-11-28T11:35:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg\",\"keywords\":[\"campa\u00f1a de solidaridad\"],\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/\",\"name\":\"Campagne de solidarit\u00e9 2022 -R. D. Congo - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg\",\"datePublished\":\"2022-01-25T15:02:12+00:00\",\"dateModified\":\"2023-11-28T11:35:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg\",\"width\":1280,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/01\\\/campagne-de-solidarite-2022-en-r-d-congo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne de solidarit\u00e9 2022 -R. D. Congo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campagne de solidarit\u00e9 2022 -R. D. Congo","description":"Le 24 janvier 2022, s'est fait le lancement de la campagne de solidarit\u00e9 2022, en R\u00e9publique D\u00e9mocratique du Congo. Les \u00e9l\u00e8ves et enseignants de l'\u00c9cole publique Saint Sacrement de Kinshasa ont donc eu le privil\u00e8ge de d\u00e9marrer les activit\u00e9s marquant ladite campagne pour le compte de cette ann\u00e9e. La matin\u00e9e a \u00e9t\u00e9 ponctu\u00e9e par un&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Le 24 janvier 2022, s'est fait le lancement de la campagne de solidarit\u00e9 2022, en R\u00e9publique D\u00e9mocratique du Congo. Les \u00e9l\u00e8ves et enseignants de l'\u00c9cole publique Saint Sacrement de Kinshasa ont donc eu le privil\u00e8ge de d\u00e9marrer les activit\u00e9s marquant ladite campagne pour le compte de cette ann\u00e9e. La matin\u00e9e a \u00e9t\u00e9 ponctu\u00e9e par un&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"Campagne de solidarit\u00e9 2022 -R. D. Congo","og_description":"Le 24 janvier 2022, s'est fait le lancement de la campagne de solidarit\u00e9 2022, en R\u00e9publique D\u00e9mocratique du Congo. Les \u00e9l\u00e8ves et enseignants de l'\u00c9cole publique Saint Sacrement de Kinshasa ont donc eu le privil\u00e8ge de d\u00e9marrer les activit\u00e9s marquant ladite campagne pour le compte de cette ann\u00e9e. La matin\u00e9e a \u00e9t\u00e9 ponctu\u00e9e par un&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/","og_site_name":"Itaka-Escolapios","article_published_time":"2022-01-25T15:02:12+00:00","article_modified_time":"2023-11-28T11:35:53+00:00","og_image":[{"width":1280,"height":640,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg","type":"image\/jpeg"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itakaescolapios","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"Campagne de solidarit\u00e9 2022 -R. D. Congo","datePublished":"2022-01-25T15:02:12+00:00","dateModified":"2023-11-28T11:35:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/"},"wordCount":121,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg","keywords":["campa\u00f1a de solidaridad"],"articleSection":["R.D. Congo"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/","name":"Campagne de solidarit\u00e9 2022 -R. D. Congo - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg","datePublished":"2022-01-25T15:02:12+00:00","dateModified":"2023-11-28T11:35:53+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-22-at-18.54.37-1.jpeg","width":1280,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/01\/campagne-de-solidarite-2022-en-r-d-congo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Campagne de solidarit\u00e9 2022 -R. D. Congo"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/35763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=35763"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/35763\/revisions"}],"predecessor-version":[{"id":44095,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/35763\/revisions\/44095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/35769"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=35763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=35763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=35763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}