{"id":36474,"date":"2022-04-11T16:43:37","date_gmt":"2022-04-11T15:43:37","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=36474"},"modified":"2023-11-28T12:35:48","modified_gmt":"2023-11-28T11:35:48","slug":"francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/","title":{"rendered":""},"content":{"rendered":"<p>[:en]Saturday, 9th April 2022 took place in the Catholic schools of Futru Bamenda the fourth and the last phase of the food distribution campaign in relation to the Humanitarian Aid project in Bamenda sponsored by the Basque Cooperation and Development Agency. Each of the 1212 beneficiaries received 03 liters of vegetable oil, 02 kg of groundnut, 01 packet of corn seed, 01 kg of fufu corn, 05 kg of ndop rice and 01 pack of hygienic pads. The beneficiaries were very happy and expressed their gratitude towards the Piarist Fathers\u2019 Congregation and all their partners.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-36475 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-scaled.jpg 2000w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-768x576.jpg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-1536x1152.jpg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-2048x1536.jpg 2048w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-250x188.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-510x382.jpg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-1080x810.jpg 1080w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-36476 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-scaled.jpg 2000w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-768x576.jpg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-1536x1152.jpg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-2048x1536.jpg 2048w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-250x188.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-510x382.jpg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-1080x810.jpg 1080w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-36477 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-scaled.jpg 2000w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-768x576.jpg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-1536x1152.jpg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-2048x1536.jpg 2048w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-250x188.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-510x382.jpg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-1080x810.jpg 1080w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-36479 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-scaled.jpg 2000w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-768x576.jpg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-1536x1152.jpg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-2048x1536.jpg 2048w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-250x188.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-510x382.jpg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-1080x810.jpg 1080w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>[:fr]<\/p>\n<div id=\"tw-target-text-container\" class=\"tw-ta-container F0azHf tw-nfl\">\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Traduction\"><span class=\"Y2IQFc\" lang=\"fr\">Le samedi 9 avril 2022 a eu lieu dans les \u00e9coles catholiques de Futru Bamenda la quatri\u00e8me et derni\u00e8re phase de la campagne de distribution alimentaire dans le cadre du projet d&#8217;aide humanitaire \u00e0 Bamenda parrain\u00e9 par l&#8217;Agence basque de coop\u00e9ration et de d\u00e9veloppement. Chacun des 1212 b\u00e9n\u00e9ficiaires a re\u00e7u 03 litres d&#8217;huile v\u00e9g\u00e9tale, 02 kg d&#8217;arachide, 01 sachet de semence de ma\u00efs, 01 kg de ma\u00efs foufou, 05 kg de riz ndop et 01 paquet de serviettes hygi\u00e9niques. Les b\u00e9n\u00e9ficiaires \u00e9taient tr\u00e8s heureux et ont exprim\u00e9 leur gratitude envers la Congr\u00e9gation des P\u00e8res Piaristes et tous leurs partenaires.<\/span><\/p>\n<\/div>\n<p><img decoding=\"async\" class=\"size-full wp-image-36475 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-scaled.jpg 2000w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-768x576.jpg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-1536x1152.jpg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-2048x1536.jpg 2048w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-250x188.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-510x382.jpg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_100359-1080x810.jpg 1080w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-36476 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-scaled.jpg 2000w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-768x576.jpg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-1536x1152.jpg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-2048x1536.jpg 2048w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-250x188.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-510x382.jpg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092327-1080x810.jpg 1080w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-36477 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-scaled.jpg 2000w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-768x576.jpg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-1536x1152.jpg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-2048x1536.jpg 2048w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-250x188.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-510x382.jpg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_085920-1080x810.jpg 1080w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-36479 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-scaled.jpg 2000w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-300x225.jpg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-1024x768.jpg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-768x576.jpg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-1536x1152.jpg 1536w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-2048x1536.jpg 2048w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-250x188.jpg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-510x382.jpg 510w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_090439-1080x810.jpg 1080w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>[:]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[:en]Saturday, 9th April 2022 took place in the Catholic schools of Futru Bamenda the fourth and the last phase of the food distribution campaign in relation to the Humanitarian Aid [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":36480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,10],"tags":[],"class_list":["post-36474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-camerun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Itaka-Escolapios<\/title>\n<meta name=\"description\" content=\"[:en]Saturday, 9th April 2022 took place in the Catholic schools of Futru Bamenda the fourth and the last phase of the food distribution campaign in relation to the Humanitarian Aid project in Bamenda sponsored by the Basque Cooperation and Development Agency. Each of the 1212 beneficiaries received 03 liters of vegetable oil, 02 kg of&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"[:en]Saturday, 9th April 2022 took place in the Catholic schools of Futru Bamenda the fourth and the last phase of the food distribution campaign in relation to the Humanitarian Aid project in Bamenda sponsored by the Basque Cooperation and Development Agency. Each of the 1212 beneficiaries received 03 liters of vegetable oil, 02 kg of&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-11T15:43:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092355-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"Sem t\u00edtulo\",\"datePublished\":\"2022-04-11T15:43:37+00:00\",\"dateModified\":\"2023-11-28T11:35:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/\"},\"wordCount\":199,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/20220409_092355-scaled.jpg\",\"articleSection\":[\"\u00c1frica Central\",\"Camar\u00f5es\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/\",\"name\":\"- Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/20220409_092355-scaled.jpg\",\"datePublished\":\"2022-04-11T15:43:37+00:00\",\"dateModified\":\"2023-11-28T11:35:48+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/04\\\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/20220409_092355-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/20220409_092355-scaled.jpg\",\"width\":2000,\"height\":1500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Itaka-Escolapios","description":"[:en]Saturday, 9th April 2022 took place in the Catholic schools of Futru Bamenda the fourth and the last phase of the food distribution campaign in relation to the Humanitarian Aid project in Bamenda sponsored by the Basque Cooperation and Development Agency. Each of the 1212 beneficiaries received 03 liters of vegetable oil, 02 kg of&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"[:en]Saturday, 9th April 2022 took place in the Catholic schools of Futru Bamenda the fourth and the last phase of the food distribution campaign in relation to the Humanitarian Aid project in Bamenda sponsored by the Basque Cooperation and Development Agency. Each of the 1212 beneficiaries received 03 liters of vegetable oil, 02 kg of&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"- Itaka-Escolapios","og_description":"[:en]Saturday, 9th April 2022 took place in the Catholic schools of Futru Bamenda the fourth and the last phase of the food distribution campaign in relation to the Humanitarian Aid project in Bamenda sponsored by the Basque Cooperation and Development Agency. Each of the 1212 beneficiaries received 03 liters of vegetable oil, 02 kg of&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/","og_site_name":"Itaka-Escolapios","article_published_time":"2022-04-11T15:43:37+00:00","article_modified_time":"2023-11-28T11:35:48+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092355-scaled.jpg","type":"image\/jpeg"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cameroun01","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"Sem t\u00edtulo","datePublished":"2022-04-11T15:43:37+00:00","dateModified":"2023-11-28T11:35:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/"},"wordCount":199,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092355-scaled.jpg","articleSection":["\u00c1frica Central","Camar\u00f5es"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/","name":"- Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092355-scaled.jpg","datePublished":"2022-04-11T15:43:37+00:00","dateModified":"2023-11-28T11:35:48+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/04\/francais-troisieme-campagne-de-distribution-en-faveurs-des-eleves-des-ecoles-de-bamenda\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092355-scaled.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/04\/20220409_092355-scaled.jpg","width":2000,"height":1500},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/36474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=36474"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/36474\/revisions"}],"predecessor-version":[{"id":43983,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/36474\/revisions\/43983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/36480"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=36474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=36474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=36474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}