{"id":37984,"date":"2022-11-25T15:01:11","date_gmt":"2022-11-25T14:01:11","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=37984"},"modified":"2023-11-28T12:35:39","modified_gmt":"2023-11-28T11:35:39","slug":"francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/","title":{"rendered":""},"content":{"rendered":"<p>[:fr]La semaine calasanctienne continue de plus belle dans tous les \u00e9tablissements piaristes de la province d\u2019Afrique centrale. Du Gabon en Guin\u00e9e Equatoriale en passant par le Cameroun, nous sommes tous en f\u00eate. Les \u00e9tablissements se sont mobilis\u00e9s pour c\u00e9l\u00e9brer de mani\u00e8re particuli\u00e8re la semaine de Saint Joseph Calasanz. Comme activit\u00e9s au programme on note en plus des messes\u00a0: la sensibilisation sur les violences faites aux femmes et le d\u00e9fil\u00e9 de mode en tenue traditionnelle et de ville ( Complexe Scolaire Bilingue Int\u00e9gral Saint Joseph Calasanz de Bafia Cameroun), la pr\u00e9sentation des Activit\u00e9s des clubs et animation g\u00e9n\u00e9rale (Complexe Scolaire Bilingue Saint Joseph Calasanz de Malib\u00e9 Gabon), la pr\u00e9sentation des activit\u00e9s sportives ( Coll\u00e8ge Polyvalent Bilingue Saint Joseph Calasanz de Bandjoun Cameroun), les matchs de football et de basketball (Institut Catholique CALASANZ de Libreville) ainsi que les Matchs de volley, de basket ( Ecole Saint Joseph Calasanz d\u2019Akurenam Guin\u00e9e Equatoriale). La c\u00e9l\u00e9bration continue de plus belle\u2026 C\u00e9l\u00e9brons ensemble Saint Joseph Calasanz<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-37985 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-2.18.50-PM.jpeg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-2.18.50-PM.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-2.18.50-PM-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-2.18.50-PM-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-2.18.50-PM-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-2.18.50-PM-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-2.18.50-PM-510x382.jpeg 510w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-37987 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-11.28.37-AM.jpeg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-11.28.37-AM.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-11.28.37-AM-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-11.28.37-AM-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-11.28.37-AM-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-11.28.37-AM-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-25-at-11.28.37-AM-510x382.jpeg 510w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-37989 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.33-PM-1.jpeg\" alt=\"\" width=\"1080\" height=\"608\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.33-PM-1.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.33-PM-1-300x169.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.33-PM-1-1024x576.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.33-PM-1-768x432.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.33-PM-1-250x141.jpeg 250w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-37992 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.25-PM.jpeg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.25-PM.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.25-PM-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.25-PM-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.25-PM-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.25-PM-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-9.31.25-PM-510x382.jpeg 510w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-37993 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.20-PM.jpeg\" alt=\"\" width=\"960\" height=\"1280\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.20-PM.jpeg 960w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.20-PM-225x300.jpeg 225w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.20-PM-768x1024.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.20-PM-250x333.jpeg 250w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-37994 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.16-PM.jpeg\" alt=\"\" width=\"960\" height=\"1280\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.16-PM.jpeg 960w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.16-PM-225x300.jpeg 225w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.16-PM-768x1024.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-24-at-6.29.16-PM-250x333.jpeg 250w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-37995 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-7.04.50-PM.jpeg\" alt=\"\" width=\"752\" height=\"1000\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-7.04.50-PM.jpeg 752w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-7.04.50-PM-226x300.jpeg 226w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-7.04.50-PM-250x332.jpeg 250w\" sizes=\"(max-width: 752px) 100vw, 752px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-37998 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-5.50.34-PM.jpeg\" alt=\"\" width=\"1040\" height=\"780\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-5.50.34-PM.jpeg 1040w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-5.50.34-PM-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-5.50.34-PM-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-5.50.34-PM-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-5.50.34-PM-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-5.50.34-PM-510x382.jpeg 510w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-37999 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.44-PM.jpeg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.44-PM.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.44-PM-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.44-PM-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.44-PM-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.44-PM-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.44-PM-510x382.jpeg 510w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-38000 aligncenter\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.43-PM.jpeg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.43-PM.jpeg 1080w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.43-PM-300x225.jpeg 300w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.43-PM-1024x768.jpeg 1024w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.43-PM-768x576.jpeg 768w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.43-PM-250x188.jpeg 250w, https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-3.13.43-PM-510x382.jpeg 510w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>[:]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[:fr]La semaine calasanctienne continue de plus belle dans tous les \u00e9tablissements piaristes de la province d\u2019Afrique centrale. Du Gabon en Guin\u00e9e Equatoriale en passant par le Cameroun, nous sommes tous [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":37997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,10,285,533],"tags":[],"class_list":["post-37984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-camerun","category-gabon","category-guinea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Itaka-Escolapios<\/title>\n<meta name=\"description\" content=\"[:fr]La semaine calasanctienne continue de plus belle dans tous les \u00e9tablissements piaristes de la province d\u2019Afrique centrale. Du Gabon en Guin\u00e9e Equatoriale en passant par le Cameroun, nous sommes tous en f\u00eate. Les \u00e9tablissements se sont mobilis\u00e9s pour c\u00e9l\u00e9brer de mani\u00e8re particuli\u00e8re la semaine de Saint Joseph Calasanz. Comme activit\u00e9s au programme on note en&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Itaka-Escolapios\" \/>\n<meta property=\"og:description\" content=\"[:fr]La semaine calasanctienne continue de plus belle dans tous les \u00e9tablissements piaristes de la province d\u2019Afrique centrale. Du Gabon en Guin\u00e9e Equatoriale en passant par le Cameroun, nous sommes tous en f\u00eate. Les \u00e9tablissements se sont mobilis\u00e9s pour c\u00e9l\u00e9brer de mani\u00e8re particuli\u00e8re la semaine de Saint Joseph Calasanz. Comme activit\u00e9s au programme on note en&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-25T14:01:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"752\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cameroun01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cameroun01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/\"},\"author\":{\"name\":\"cameroun01\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\"},\"headline\":\"Sem t\u00edtulo\",\"datePublished\":\"2022-11-25T14:01:11+00:00\",\"dateModified\":\"2023-11-28T11:35:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/\"},\"wordCount\":182,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg\",\"articleSection\":[\"\u00c1frica Central\",\"Camar\u00f5es\",\"Gab\u00f3n\",\"Guinea\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/\",\"name\":\"- Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg\",\"datePublished\":\"2022-11-25T14:01:11+00:00\",\"dateModified\":\"2023-11-28T11:35:39+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2022\\\/11\\\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg\",\"width\":1000,\"height\":752},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/d2844383e29bfdfef69039672ce14eb1\",\"name\":\"cameroun01\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/cameroun01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Itaka-Escolapios","description":"[:fr]La semaine calasanctienne continue de plus belle dans tous les \u00e9tablissements piaristes de la province d\u2019Afrique centrale. Du Gabon en Guin\u00e9e Equatoriale en passant par le Cameroun, nous sommes tous en f\u00eate. Les \u00e9tablissements se sont mobilis\u00e9s pour c\u00e9l\u00e9brer de mani\u00e8re particuli\u00e8re la semaine de Saint Joseph Calasanz. Comme activit\u00e9s au programme on note en&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"[:fr]La semaine calasanctienne continue de plus belle dans tous les \u00e9tablissements piaristes de la province d\u2019Afrique centrale. Du Gabon en Guin\u00e9e Equatoriale en passant par le Cameroun, nous sommes tous en f\u00eate. Les \u00e9tablissements se sont mobilis\u00e9s pour c\u00e9l\u00e9brer de mani\u00e8re particuli\u00e8re la semaine de Saint Joseph Calasanz. Comme activit\u00e9s au programme on note en&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"- Itaka-Escolapios","og_description":"[:fr]La semaine calasanctienne continue de plus belle dans tous les \u00e9tablissements piaristes de la province d\u2019Afrique centrale. Du Gabon en Guin\u00e9e Equatoriale en passant par le Cameroun, nous sommes tous en f\u00eate. Les \u00e9tablissements se sont mobilis\u00e9s pour c\u00e9l\u00e9brer de mani\u00e8re particuli\u00e8re la semaine de Saint Joseph Calasanz. Comme activit\u00e9s au programme on note en&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/","og_site_name":"Itaka-Escolapios","article_published_time":"2022-11-25T14:01:11+00:00","article_modified_time":"2023-11-28T11:35:39+00:00","og_image":[{"width":1000,"height":752,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg","type":"image\/jpeg"}],"author":"cameroun01","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cameroun01","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/"},"author":{"name":"cameroun01","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1"},"headline":"Sem t\u00edtulo","datePublished":"2022-11-25T14:01:11+00:00","dateModified":"2023-11-28T11:35:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/"},"wordCount":182,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg","articleSection":["\u00c1frica Central","Camar\u00f5es","Gab\u00f3n","Guinea"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/","name":"- Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg","datePublished":"2022-11-25T14:01:11+00:00","dateModified":"2023-11-28T11:35:39+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2022\/11\/francais-celebration-de-la-semaine-calasanzienne-en-afrique-centrale\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-6.58.28-PM.jpeg","width":1000,"height":752},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/d2844383e29bfdfef69039672ce14eb1","name":"cameroun01","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/cameroun01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/37984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=37984"}],"version-history":[{"count":2,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/37984\/revisions"}],"predecessor-version":[{"id":43759,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/37984\/revisions\/43759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/37997"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=37984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=37984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=37984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}