{"id":42640,"date":"2023-07-10T16:20:20","date_gmt":"2023-07-10T15:20:20","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=42640"},"modified":"2023-11-28T12:35:31","modified_gmt":"2023-11-28T11:35:31","slug":"42640","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/","title":{"rendered":"Visita a Kikonka del proyecto \"So\u00f1ando Congo\""},"content":{"rendered":"<p>Contin\u00faa\u00a0 esta semana el encuentro en Kinshasa en el marco del proyecto de puesta en marcha de la nueva escuela. Durante el fin de semana Jon Ander, Amaya y Pedro, desplazados desde la Red Itaka Escolapios y el Colegio Calasancio de Bilbao han aprovechado para acercarse a Kikonka,\u00a0 han podido conocer la aglomeraci\u00f3n, que fue el primer destino de los escolapios en Rep\u00fablica Democr\u00e1tica de Congo\u00a0 y ver, entre otras cosas, todo lo que se ha podido impulsar gracias al apoyo de la campa\u00f1a de solidaridad del 2018-19, &#8220;al ritmo del Congo&#8221;\u00a0 en la que se trabaj\u00f3 en setenta y ocho centros escolapios de diez pa\u00edses (Espa\u00f1a, Bolivia, Brasil, Venezuela, Rep\u00fablica Dominicana, Camer\u00fan, Gab\u00f3n, Senegal, Filipinas e Indonesia) para conocer la realidad escolapia en RD Congo y se recaudaron m\u00e1s de en las aulas el valor de la educaci\u00f3n como motor de cambio, conociendo la realidad escolapia la Rep\u00fablica Democr\u00e1tica del Congo.223.000 \u20ac. Este apoyo de la Red Itaka Escolapios ha permitido\u00a0 para mejorar la educaci\u00f3n de ni\u00f1os y ni\u00f1as mediante la rehabilitaci\u00f3n y equipamiento de la escuela de primaria, la mejora del saneamiento (construcci\u00f3n de nuevas letrinas), la perforaci\u00f3n de dos pozos de agua y la mejora de la calidad de vida del grupo mujeres de la aglomeraci\u00f3n mediante el apoyo a su formaci\u00f3n.<\/p>\n<p>Ha sido una oportunidad para fortalecer la conexi\u00f3n entre lugares muy distintos de la Red Itaka Escolapios, mejorar la comprensi\u00f3n mutua e identificar nuevos y futuros pasos.<\/p>\n<p>El trabajo continuar\u00e1 durante toda esta semana en Kinshasa entre el futuro equipo directivo del futuro colegio de la capital, el equipo desplazado desde el colegio escolapio de Bilbao y el equipo de proyectos de la Red.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-42640 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/kikonka-2023-julio-3\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-3-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/kikonka-2023-julio-2\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-2-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/kikonka-2023-julio-1\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-1-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/kikonka-2\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/kikonka-2-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/kikonka-2023-julio-6\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-6-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/kikonka-2023-julio-5\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-5-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/kikonka-2023-julio-4\/'><img decoding=\"async\" width=\"90\" height=\"90\" src=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-4-90x90.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contin\u00faa\u00a0 esta semana el encuentro en Kinshasa en el marco del proyecto de puesta en marcha de la nueva escuela. Durante el fin de semana Jon Ander, Amaya y Pedro, [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":42645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53,30,1,337],"tags":[],"class_list":["post-42640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa-central","category-itaka-escolapios","category-none","category-r-d-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visita a Kikonka del proyecto &quot;So\u00f1ando Congo&quot;<\/title>\n<meta name=\"description\" content=\"Contin\u00faa\u00a0 esta semana el encuentro en Kinshasa en el marco del proyecto de puesta en marcha de la nueva escuela. Durante el fin de semana Jon Ander, Amaya y Pedro, desplazados desde la Red Itaka Escolapios y el Colegio Calasancio de Bilbao han aprovechado para acercarse a Kikonka,\u00a0 han podido conocer la aglomeraci\u00f3n, que fue&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/Contin\u00faa\u00a0%20esta%20semana%20el%20encuentro%20en%20Kinshasa%20en%20el%20marco%20del%20proyecto%20de%20puesta%20en%20marcha%20de%20la%20nueva%20escuela.%20Durante%20el%20fin%20de%20semana%20Jon%20Ander,%20Amaya%20y%20Pedro,%20desplazados%20desde%20la%20Red%20Itaka%20Escolapios%20y%20el%20Colegio%20Calasancio%20de%20Bilbao%20han%20aprovechado%20para%20acercarse%20a%20Kikonka,\u00a0%20han%20podido%20conocer%20la%20aglomeraci\u00f3n,%20que%20fue&hellip;\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visita a Kikonka del proyecto &quot;So\u00f1ando Congo&quot;\" \/>\n<meta property=\"og:description\" content=\"Contin\u00faa\u00a0 esta semana el encuentro en Kinshasa en el marco del proyecto de puesta en marcha de la nueva escuela. Durante el fin de semana Jon Ander, Amaya y Pedro, desplazados desde la Red Itaka Escolapios y el Colegio Calasancio de Bilbao han aprovechado para acercarse a Kikonka,\u00a0 han podido conocer la aglomeraci\u00f3n, que fue&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-10T15:20:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"Visita a Kikonka del proyecto \\\"So\u00f1ando Congo\\\"\",\"datePublished\":\"2023-07-10T15:20:20+00:00\",\"dateModified\":\"2023-11-28T11:35:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/\"},\"wordCount\":315,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Kikonka-2023-julio-4.jpg\",\"articleSection\":[\"\u00c1frica Central\",\"Itaka Escolapios\",\"Ninguna\",\"R.D. Congo\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/\",\"name\":\"Visita a Kikonka del proyecto \\\"So\u00f1ando Congo\\\" - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Kikonka-2023-julio-4.jpg\",\"datePublished\":\"2023-07-10T15:20:20+00:00\",\"dateModified\":\"2023-11-28T11:35:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Kikonka-2023-julio-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Kikonka-2023-julio-4.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/07\\\/42640\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visita a Kikonka del proyecto \\\"So\u00f1ando Congo\\\"\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visita a Kikonka del proyecto \"So\u00f1ando Congo\"","description":"Contin\u00faa\u00a0 esta semana el encuentro en Kinshasa en el marco del proyecto de puesta en marcha de la nueva escuela. Durante el fin de semana Jon Ander, Amaya y Pedro, desplazados desde la Red Itaka Escolapios y el Colegio Calasancio de Bilbao han aprovechado para acercarse a Kikonka,\u00a0 han podido conocer la aglomeraci\u00f3n, que fue&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"Contin\u00faa\u00a0 esta semana el encuentro en Kinshasa en el marco del proyecto de puesta en marcha de la nueva escuela. Durante el fin de semana Jon Ander, Amaya y Pedro, desplazados desde la Red Itaka Escolapios y el Colegio Calasancio de Bilbao han aprovechado para acercarse a Kikonka,\u00a0 han podido conocer la aglomeraci\u00f3n, que fue&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"Visita a Kikonka del proyecto \"So\u00f1ando Congo\"","og_description":"Contin\u00faa\u00a0 esta semana el encuentro en Kinshasa en el marco del proyecto de puesta en marcha de la nueva escuela. Durante el fin de semana Jon Ander, Amaya y Pedro, desplazados desde la Red Itaka Escolapios y el Colegio Calasancio de Bilbao han aprovechado para acercarse a Kikonka,\u00a0 han podido conocer la aglomeraci\u00f3n, que fue&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/","og_site_name":"Itaka-Escolapios","article_published_time":"2023-07-10T15:20:20+00:00","article_modified_time":"2023-11-28T11:35:31+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-4.jpg","type":"image\/jpeg"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itakaescolapios","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"Visita a Kikonka del proyecto \"So\u00f1ando Congo\"","datePublished":"2023-07-10T15:20:20+00:00","dateModified":"2023-11-28T11:35:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/"},"wordCount":315,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-4.jpg","articleSection":["\u00c1frica Central","Itaka Escolapios","Ninguna","R.D. Congo"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/","name":"Visita a Kikonka del proyecto \"So\u00f1ando Congo\" - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-4.jpg","datePublished":"2023-07-10T15:20:20+00:00","dateModified":"2023-11-28T11:35:31+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-4.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/07\/Kikonka-2023-julio-4.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/07\/42640\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"Visita a Kikonka del proyecto \"So\u00f1ando Congo\""}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/42640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=42640"}],"version-history":[{"count":9,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/42640\/revisions"}],"predecessor-version":[{"id":43558,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/42640\/revisions\/43558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/42645"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=42640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=42640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=42640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}