{"id":43103,"date":"2023-10-24T17:21:50","date_gmt":"2023-10-24T16:21:50","guid":{"rendered":"https:\/\/www.itakaescolapios.org\/?p=43103"},"modified":"2023-11-28T12:35:28","modified_gmt":"2023-11-28T11:35:28","slug":"francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination","status":"publish","type":"post","link":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/","title":{"rendered":"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N"},"content":{"rendered":"<p>En l\u00ednea con la planificaci\u00f3n del proyecto &#8220;So\u00f1ando el Congo&#8221;, la oficina de Itaka Escolapios-RDC ya ha creado un equipo de coordinaci\u00f3n para el (futuro) complejo escolar Saint Joseph de Calasanz en Kinshasa. El equipo est\u00e1 formado por laicos de edades y experiencias diversas. Tras elaborar el calendario anual de tareas a realizar, el equipo comenz\u00f3 su formaci\u00f3n en Calasanz en septiembre de 2023 y continuar\u00e1 durante todo el a\u00f1o. Tambi\u00e9n recibir\u00e1n formaci\u00f3n inform\u00e1tica. Estos dos cursos de formaci\u00f3n, y todos los previstos, est\u00e1n dise\u00f1ados para proporcionar las habilidades y conocimientos necesarios para una coordinaci\u00f3n eficaz y eficiente de una &#8220;escuela para la vida&#8221; del tipo que queremos en Kinshasa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En l\u00ednea con la planificaci\u00f3n del proyecto &#8220;So\u00f1ando el Congo&#8221;, la oficina de Itaka Escolapios-RDC ya ha creado un equipo de coordinaci\u00f3n para el (futuro) complejo escolar Saint Joseph de [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":43104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[337],"tags":[46,565],"class_list":["post-43103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-r-d-congo","tag-educacion","tag-itaka-congo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N<\/title>\n<meta name=\"description\" content=\"En l\u00ednea con la planificaci\u00f3n del proyecto &quot;So\u00f1ando el Congo&quot;, la oficina de Itaka Escolapios-RDC ya ha creado un equipo de coordinaci\u00f3n para el (futuro) complejo escolar Saint Joseph de Calasanz en Kinshasa. El equipo est\u00e1 formado por laicos de edades y experiencias diversas. Tras elaborar el calendario anual de tareas a realizar, el equipo&hellip;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/En%20l\u00ednea%20con%20la%20planificaci\u00f3n%20del%20proyecto%20So\u00f1ando%20el%20Congo,%20la%20oficina%20de%20Itaka%20Escolapios-RDC%20ya%20ha%20creado%20un%20equipo%20de%20coordinaci\u00f3n%20para%20el%20(futuro)%20complejo%20escolar%20Saint%20Joseph%20de%20Calasanz%20en%20Kinshasa.%20El%20equipo%20est\u00e1%20formado%20por%20laicos%20de%20edades%20y%20experiencias%20diversas.%20Tras%20elaborar%20el%20calendario%20anual%20de%20tareas%20a%20realizar,%20el%20equipo&hellip;\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N\" \/>\n<meta property=\"og:description\" content=\"En l\u00ednea con la planificaci\u00f3n del proyecto &quot;So\u00f1ando el Congo&quot;, la oficina de Itaka Escolapios-RDC ya ha creado un equipo de coordinaci\u00f3n para el (futuro) complejo escolar Saint Joseph de Calasanz en Kinshasa. El equipo est\u00e1 formado por laicos de edades y experiencias diversas. Tras elaborar el calendario anual de tareas a realizar, el equipo&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/\" \/>\n<meta property=\"og:site_name\" content=\"Itaka-Escolapios\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-24T16:21:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T11:35:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/10\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"809\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"itakaescolapios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"itakaescolapios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/\"},\"author\":{\"name\":\"itakaescolapios\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\"},\"headline\":\"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N\",\"datePublished\":\"2023-10-24T16:21:50+00:00\",\"dateModified\":\"2023-11-28T11:35:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/\"},\"wordCount\":134,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg\",\"keywords\":[\"educaci\u00f3n\",\"Itaka Congo\"],\"articleSection\":[\"R.D. Congo\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/\",\"name\":\"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N - Itaka-Escolapios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg\",\"datePublished\":\"2023-10-24T16:21:50+00:00\",\"dateModified\":\"2023-11-28T11:35:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg\",\"width\":1080,\"height\":809},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/2023\\\/10\\\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Itaka-Escolapios\",\"item\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"name\":\"Itaka-Escolapios\",\"description\":\"Red de Itaka-Escolapios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Itaka-Escolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"contentUrl\":\"https:\\\/\\\/www.itakaescolapios.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-itakaescolapios-peque.png\",\"width\":500,\"height\":199,\"caption\":\"Fundaci\u00f3 Itaka-Escolapios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itakaescolapios.org\\\/es\\\/#\\\/schema\\\/person\\\/768ce0f19db5c2c2b6361e77e15db2db\",\"name\":\"itakaescolapios\",\"url\":\"https:\\\/\\\/www.itakaescolapios.org\\\/pt\\\/author\\\/itakaescolapios\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N","description":"En l\u00ednea con la planificaci\u00f3n del proyecto \"So\u00f1ando el Congo\", la oficina de Itaka Escolapios-RDC ya ha creado un equipo de coordinaci\u00f3n para el (futuro) complejo escolar Saint Joseph de Calasanz en Kinshasa. El equipo est\u00e1 formado por laicos de edades y experiencias diversas. Tras elaborar el calendario anual de tareas a realizar, el equipo&hellip;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"En l\u00ednea con la planificaci\u00f3n del proyecto \"So\u00f1ando el Congo\", la oficina de Itaka Escolapios-RDC ya ha creado un equipo de coordinaci\u00f3n para el (futuro) complejo escolar Saint Joseph de Calasanz en Kinshasa. El equipo est\u00e1 formado por laicos de edades y experiencias diversas. Tras elaborar el calendario anual de tareas a realizar, el equipo&hellip;","og_locale":"pt_BR","og_type":"article","og_title":"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N","og_description":"En l\u00ednea con la planificaci\u00f3n del proyecto \"So\u00f1ando el Congo\", la oficina de Itaka Escolapios-RDC ya ha creado un equipo de coordinaci\u00f3n para el (futuro) complejo escolar Saint Joseph de Calasanz en Kinshasa. El equipo est\u00e1 formado por laicos de edades y experiencias diversas. Tras elaborar el calendario anual de tareas a realizar, el equipo&hellip;","og_url":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/","og_site_name":"Itaka-Escolapios","article_published_time":"2023-10-24T16:21:50+00:00","article_modified_time":"2023-11-28T11:35:28+00:00","og_image":[{"width":1080,"height":809,"url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/10\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg","type":"image\/jpeg"}],"author":"itakaescolapios","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"itakaescolapios","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/#article","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/"},"author":{"name":"itakaescolapios","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db"},"headline":"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N","datePublished":"2023-10-24T16:21:50+00:00","dateModified":"2023-11-28T11:35:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/"},"wordCount":134,"publisher":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#organization"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/10\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg","keywords":["educaci\u00f3n","Itaka Congo"],"articleSection":["R.D. Congo"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/","url":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/","name":"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N - Itaka-Escolapios","isPartOf":{"@id":"https:\/\/www.itakaescolapios.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/#primaryimage"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/#primaryimage"},"thumbnailUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/10\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg","datePublished":"2023-10-24T16:21:50+00:00","dateModified":"2023-11-28T11:35:28+00:00","breadcrumb":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/#primaryimage","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/10\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2023\/10\/Imagen-de-WhatsApp-2023-10-24-a-las-17.09.39_01f4636b.jpg","width":1080,"height":809},{"@type":"BreadcrumbList","@id":"https:\/\/www.itakaescolapios.org\/pt\/2023\/10\/francais-complexe-scolaire-de-kinshasa-formations-de-lequipe-de-coordination\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Itaka-Escolapios","item":"https:\/\/www.itakaescolapios.org\/es\/"},{"@type":"ListItem","position":2,"name":"COMPLEJO ESCOLAR DE KINSHASA: FORMACI\u00d3N DEL EQUIPO DE COORDINACI\u00d3N"}]},{"@type":"WebSite","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#website","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","name":"Itaka-Escolapios","description":"Red de Itaka-Escolapios","publisher":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itakaescolapios.org\/pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#organization","name":"Fundaci\u00f3 Itaka-Escolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","contentUrl":"https:\/\/www.itakaescolapios.org\/wp-content\/uploads\/2024\/04\/Logo-itakaescolapios-peque.png","width":500,"height":199,"caption":"Fundaci\u00f3 Itaka-Escolapios"},"image":{"@id":"https:\/\/www.itakaescolapios.org\/pt\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itakaescolapios.org\/es\/#\/schema\/person\/768ce0f19db5c2c2b6361e77e15db2db","name":"itakaescolapios","url":"https:\/\/www.itakaescolapios.org\/pt\/author\/itakaescolapios\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/43103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/comments?post=43103"}],"version-history":[{"count":4,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/43103\/revisions"}],"predecessor-version":[{"id":43487,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/posts\/43103\/revisions\/43487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media\/43104"}],"wp:attachment":[{"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/media?parent=43103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/categories?post=43103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itakaescolapios.org\/pt\/wp-json\/wp\/v2\/tags?post=43103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}